{"id":99163,"date":"2023-12-06T12:53:40","date_gmt":"2023-12-06T15:53:40","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=99163"},"modified":"2023-12-06T03:07:34","modified_gmt":"2023-12-06T06:07:34","slug":"mira-en-vivo-los-recorridos-de-las-ballenas-que-visitan-la-provincia-de-chubut","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2023\/12\/06\/mira-en-vivo-los-recorridos-de-las-ballenas-que-visitan-la-provincia-de-chubut\/","title":{"rendered":"Mir\u00e1 en vivo los recorridos de las ballenas que visitan la provincia de Chubut"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h6><strong>Es gracias al Proyecto \u201cSiguiendo Ballenas\u201d, el cual busca comprender los ciclos de vida de estas especies migratorias, fundamentando estrategias para su preservaci\u00f3n.<\/strong><\/h6>\n<p>El Proyecto \u201cSiguiendo Ballenas\u201d, del Conicet Cenpat, entra en su octava temporada, implementando transmisores satelitales de \u00faltima generaci\u00f3n en 16 ballenas francas australes.<\/p>\n<p>Este esfuerzo conjunto de organizaciones gubernamentales, la sociedad civil y acad\u00e9micos busca comprender los ciclos de vida de estas especies migratorias, fundamentando estrategias para su preservaci\u00f3n.<\/p>\n<p>En octubre, las ballenas fueron equipadas con transmisores satelitales en el Golfo Nuevo, Pen\u00ednsula Vald\u00e9s, Chubut. Estos dispositivos, que se desprenden sin afectar la salud de los mam\u00edferos, permitir\u00e1n obtener datos cruciales sobre su comportamiento y movimientos en el oc\u00e9ano, informaci\u00f3n esencial para conservar esta especie emblem\u00e1tica.<\/p>\n<p>La octava edici\u00f3n incorpora transmisores de nueva generaci\u00f3n, anticipando su potencial reemplazo en los pr\u00f3ximos a\u00f1os. Estos avances no solo benefician a las ballenas de Pen\u00ednsula Vald\u00e9s, sino que contribuyen al desarrollo global de mejores transmisores para estos majestuosos cet\u00e1ceos.<\/p>\n<p>En esta temporada, las ballenas fueron bautizadas con nombres de dioses y diosas griegas, destacando la individualidad de 15 hembras adultas con cr\u00edas, como Atenea, Pers\u00e9fone, Iris y Calliope, y un juvenil solitario llamado Zeus.<\/p>\n<p>El monitoreo diario, accesible en\u00a0<a href=\"http:\/\/www.siguiendoballenas.org\/\" target=\"_blank\" rel=\"noopener\">w<\/a><a href=\"http:\/\/www.siguiendoballenas.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">ww.siguiendoballenas.org<\/a>, proporcionar\u00e1 informaci\u00f3n valiosa sobre sus movimientos y h\u00e1bitats.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Es gracias al Proyecto \u201cSiguiendo Ballenas\u201d, el cual busca comprender los ciclos de vida de estas especies migratorias, fundamentando<\/p>\n","protected":false},"author":1,"featured_media":99139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-99163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2023\/12\/20231206-ballenas.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/99163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=99163"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/99163\/revisions"}],"predecessor-version":[{"id":99165,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/99163\/revisions\/99165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/99139"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=99163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=99163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=99163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}