{"id":93267,"date":"2023-07-04T02:13:32","date_gmt":"2023-07-04T05:13:32","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=93267"},"modified":"2023-07-04T02:13:32","modified_gmt":"2023-07-04T05:13:32","slug":"la-onu-aseguro-que-el-derecho-a-la-alimentacion-esta-amenazado-por-el-cambio-climatico","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2023\/07\/04\/la-onu-aseguro-que-el-derecho-a-la-alimentacion-esta-amenazado-por-el-cambio-climatico\/","title":{"rendered":"La ONU asegur\u00f3 que el derecho a la alimentaci\u00f3n est\u00e1 amenazado por el cambio clim\u00e1tico"},"content":{"rendered":"<h6><\/h6>\n<h6 class=\"simple-meta\"><strong>La Organizaci\u00f3n de las Naciones Unidas (ONU) asegur\u00f3 hoy que el derecho a la alimentaci\u00f3n est\u00e1 amenazado por el cambio clim\u00e1tico, por lo que inst\u00f3 a los Estados parte a tomar medidas urgentes para combatirlo y a los tribunales de todo el mundo a exigir responsabilidades.<\/strong><\/h6>\n<div class=\"simple-meta\">Volker T\u00fcrk, alto comisionado del organismo internacional, hizo el anuncio durante una sesi\u00f3n del Consejo de Derechos Humanos dedicada al Impacto adverso del cambio clim\u00e1tico sobre la plena realizaci\u00f3n del derecho a la alimentaci\u00f3n y agreg\u00f3 que esta tendencia pone en riesgo de padecer hambre hasta a 80 millones de personas m\u00e1s a mediados de este siglo; una cifra que se sumar\u00eda a los 828 millones de personas que pasaron hambre en 2021.<\/div>\n<div class=\"content-container\">\n<p>El funcionario se\u00f1al\u00f3 que los dirigentes expresaron en numerosas ocasiones su intenci\u00f3n de tomar medidas para frenar el cambio clim\u00e1tico y prometen actuar, pero que luego \u201cse atascan en el corto plazo\u201d.<\/p>\n<p>Seg\u00fan estimaciones de las Naciones Unidas, si no se toman provisiones urgentes, el aumento medio de la temperatura a finales de este siglo ser\u00eda de 3 grados Celsius, lo que har\u00eda que los ecosistemas, el aire, los alimentos, el agua y la vida humana, fuesen irreconocibles.<\/p>\n<p><strong>El funcionario se\u00f1al\u00f3 que los dirigentes expresaron en numerosas ocasiones su intenci\u00f3n de tomar medidas para frenar el cambio clim\u00e1tico y prometen actuar, pero que luego \u201cse atascan en el corto plazo\u201d.<\/strong><\/p>\n<div class=\"banner-box\">\n<div>\nEn este sentido, la ONU expres\u00f3, a trav\u00e9s de un comunicado, que los fen\u00f3menos meteorol\u00f3gicos extremos, y los desastres tanto repentinos como graduales causados por el cambio clim\u00e1tico, pueden arrasar cosechas, reba\u00f1os, pesquer\u00edas y ecosistemas enteros.<\/div>\n<\/div>\n<p>\u201cVastos territorios desaparecer\u00edan bajo la subida de los oc\u00e9anos, o se volver\u00edan pr\u00e1cticamente inhabitables, debido al calor y a la falta de agua. El pasado mes de agosto, la temperatura en Basora, en el sur de Iraq, subi\u00f3 hasta los 52,6 grados. Viajar\u00e9 a Iraq a finales de este a\u00f1o, en parte para poner de relieve los riesgos de este futuro dist\u00f3pico\u201d, enfatiz\u00f3 T\u00fcrk.<\/p>\n<p>A nivel mundial, aumentaron en un 134% los desastres \u201crelacionados con inundaciones provocadas por el clima entre 2000-2023\u201d, apunt\u00f3 la publicaci\u00f3n de la ONU y remarc\u00f3 que hay \u201cuna frecuencia de repetici\u00f3n de estos fen\u00f3menos cada vez mayor\u201d que hace imposible que las comunidades puedan reconstruirse y mantenerse a s\u00ed mismas.<\/p>\n<p>\u201cEl vaiv\u00e9n previsible y regular de las estaciones se desv\u00eda salvajemente de su curso. Ciclones de proporciones sin precedentes azotan mareas tormentosas letales. Una ola de calor recorre el oc\u00e9ano, amenazando la vida marina, la pesca y los corales. Y los mares y lagos interiores, que han alimentado a generaciones de agricultores y pescadores, se est\u00e1n convirtiendo en cuencos de polvo\u201d, agreg\u00f3 T\u00fcrk.<\/p>\n<p>Por su parte, la organizaci\u00f3n Expertos sobre el Cambio Clim\u00e1tico asegur\u00f3 que los fen\u00f3menos meteorol\u00f3gicos extremos relacionados con el cambio clim\u00e1tico ya da\u00f1aron la productividad de todos los sectores agr\u00edcolas y pesqueros, con consecuencias negativas para la seguridad alimentaria y los medios de vida de las personas.<\/p>\n<div class=\"banner-box\">\n<div>\u201cA medida que se acelere el calentamiento global, estas repercusiones ser\u00e1n cada vez m\u00e1s amplias e intensas. Ning\u00fan pa\u00eds saldr\u00e1 indemne. Los m\u00e1s afectados ser\u00e1n los habitantes de pa\u00edses donde ya existe inseguridad alimentaria y donde los sistemas de protecci\u00f3n no son lo suficientemente s\u00f3lidos como para responder eficazmente a las perturbaciones clim\u00e1ticas\u201d, apunt\u00f3 T\u00fcrk.<\/div>\n<\/div>\n<p>Asimismo, el funcionario consider\u00f3 que se puede hacer frente a los retos actuales utilizando \u201clas herramientas tecnol\u00f3gicas m\u00e1s potentes de la historia\u201d, poniendo fin a la industria de los combustibles f\u00f3siles y cambiando a las energ\u00edas verdes.<\/p>\n<p>En consecuencia, inst\u00f3 a los tribunales de todo el mundo a exigir responsabilidades a las empresas y a los gobiernos y a transformar las instituciones internacionales de desarrollo y financiaci\u00f3n en motores de la acci\u00f3n clim\u00e1tica, de modo que los pa\u00edses y las personas m\u00e1s afectados tengan acceso a los recursos necesarios para hacerle frente.<\/p>\n<p>\u201cSi se adoptan medidas para defender la buena gobernanza de modo que cuando la financiaci\u00f3n est\u00e9 disponible, aporte apoyo y remedio a las personas m\u00e1s afectadas, entonces podr\u00e1 tener lugar una transici\u00f3n justa hacia una econom\u00eda verde, a escala nacional y mundial\u201d, expres\u00f3.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Organizaci\u00f3n de las Naciones Unidas (ONU) asegur\u00f3 hoy que el derecho a la alimentaci\u00f3n est\u00e1 amenazado por el cambio<\/p>\n","protected":false},"author":1,"featured_media":93268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"La ONU asegur\u00f3 que el derecho a la alimentaci\u00f3n est\u00e1 amenazado por el cambio clim\u00e1tico","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,138],"tags":[],"class_list":["post-93267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-internacional"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2023\/07\/20230704-cambio-climaticosequia.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/93267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=93267"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/93267\/revisions"}],"predecessor-version":[{"id":93270,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/93267\/revisions\/93270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/93268"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=93267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=93267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=93267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}