{"id":87803,"date":"2023-01-29T21:08:02","date_gmt":"2023-01-30T00:08:02","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=87803"},"modified":"2023-01-29T21:08:02","modified_gmt":"2023-01-30T00:08:02","slug":"hambre-emocional-cuando-escapar-al-estres-atenta-contra-la-salud","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2023\/01\/29\/hambre-emocional-cuando-escapar-al-estres-atenta-contra-la-salud\/","title":{"rendered":"Hambre emocional: cuando escapar al estr\u00e9s atenta contra la salud"},"content":{"rendered":"<div class=\"wrapper-header\">\n<div class=\"container-xl\">\n<div class=\"row\">\n<div class=\"col-12\">\n<div class=\"head-content mb-4\">\n<p>&nbsp;<\/p>\n<h6 class=\"speak\"><strong>Los especialistas diferencian el \u00abhambre real\u00bb del \u00abhambre emocional\u00bb, y advirtieron que los \u00abatracones\u00bb pueden derivar por una \u00abalteraci\u00f3n del estado de \u00e1nimo, depresi\u00f3n, estr\u00e9s postraum\u00e1tico o situaciones no resueltas\u00bb.<\/strong><\/h6>\n<p class=\"speak\">Comer en forma continua peque\u00f1as cantidades de dulces, hidratos de carbono y grasa, y levantarse a medianoche para hurgar en la heladera son algunos de los actos que los especialistas constituyen el<strong>\u00a0\u00abhambre emocional\u00bb, un concepto que caracteriza la conducta de las personas recurren a la comida como v\u00eda de escape ante una situaci\u00f3n de estr\u00e9s emocional.<\/strong><\/p>\n<p><strong>La idea hace referencia a \u00abcuando comemos por las emociones\u00bb, seg\u00fan lo defini\u00f3 la m\u00e9dica cl\u00ednica y especialista en nutrici\u00f3n del Hospital Italiano de Buenos Aires, Anal\u00eda Yamaguchi<\/strong>, para quien existe un<strong>\u00a0\u00abhambre real\u00bb y uno \u00abemocional\u00bb.<\/strong><\/p>\n<p>\u00abEl primero -agreg\u00f3- es un proceso fisiol\u00f3gico que aparece lentamente y, luego de comer, desaparece. El segundo, en cambio, aparece de manera brusca y, en general, es selectivo hacia alimentos ricos en az\u00facar, hidratos de carbono y grasas. Es un proceso mental y emocional\u00bb.<\/p>\n<p>Por su parte,\u00a0<strong>Laura Oliva, especialista en nutrici\u00f3n cl\u00ednica y experta en enfermedades metab\u00f3licas, coment\u00f3 a T\u00e9lam<\/strong>\u00a0que \u00abfue a partir de la publicaci\u00f3n en 2021 de un estudio sobre la &#8216;Fenotipificaci\u00f3n de la obesidad&#8217; realizado por el gastroenter\u00f3logo ecuatoriano Andr\u00e9s Acosta, de la Cl\u00ednica Mayo, que el concepto &#8216;hambre emocional&#8217; adquiri\u00f3 una entidad objetivable\u00bb.<\/p>\n<p>\u00abSi antes se alud\u00eda al apetito y se lo relacionaba con ciertos disparadores o &#8216;gatillos&#8217;, como la alegr\u00eda o la tristeza, es a partir de esta clasificaci\u00f3n de las obesidades que empez\u00f3 a hablarse de los comportamientos alimentarios.\u00a0<strong>Estos son: el comportamiento hiperf\u00e1gico, cuando no podemos dejar de comer; el comportamiento hed\u00f3nico, relacionado con el placer; y el hambre emocional, asociado al estr\u00e9s y a las emociones\u00bb<\/strong>, argument\u00f3 Oliva.<\/p>\n<p><strong>A juicio de Ignacio Porras, licenciado en Nutrici\u00f3n y presidente de la Fundaci\u00f3n Sanar<\/strong>, \u00ablo que llamamos &#8216;hambre emocional&#8217; es el s\u00edntoma de aquellas personas que canalizan el estr\u00e9s a trav\u00e9s de la comida\u00bb.<\/p>\n<p>Porras<strong>\u00a0observ\u00f3 que \u00ablas personas no solamente comemos cuando tenemos hambre; a veces lo hacemos sin tener apetito o, en ocasiones, nos privamos de comer a pesar de tenerlo. Esto lleva a la generaci\u00f3n de trastornos en la conducta alimentaria\u00bb.<\/strong><\/p>\n<p>\u00abNos relacionamos en forma permanente con la comida al estar inmersos en un sistema alimentario que promueve distintos consumos que van confeccionando en cada persona un patr\u00f3n alimentario propio, ya sea por las experiencias previas, por el acceso a los alimentos o no, por la identificaci\u00f3n cultural, y por cuestiones del entorno y el ambiente que pueden disparar situaciones de ansiedad en algunas personas\u00bb, reflexion\u00f3 Porras.<\/p>\n<p><strong>Liliana Albarenga consult\u00f3 a su nutricionista cuando advirti\u00f3 que se volv\u00eda recurrente, en simult\u00e1neo con problemas laborales que le causaban estr\u00e9s<\/strong>, el levantarse durante la madrugada para comer, dijo,\u00a0<strong>\u00ablo que encontrara en la heladera\u00bb; un h\u00e1bito que afecta a cada vez m\u00e1s personas y que los especialistas denominan \u00abhambre emocional\u00bb y que puede derivar en trastornos nutricionales de no ser atendidos a tiempo.<\/p>\n<p><\/strong>Algo de lo que mencionaba Porras buscaba Albarenga (47 a\u00f1os), quien\u00a0<strong>debi\u00f3 consultar a su nutricionista tras advertir que las tensiones laborales hac\u00edan recurrente que se levantara durante la madrugada para comer \u00ablo que encontrara en la heladera\u00bb.<\/strong><\/p>\n<p>\u00abDebido a las presiones de mi trabajo -relat\u00f3 a esta agencia-, el estr\u00e9s activ\u00f3 en m\u00ed una compulsi\u00f3n a comer durante la noche, que nunca antes hab\u00eda tenido. Me tom\u00f3 mucho tiempo blanquearlo y asimilarlo porque mi conducta alimentaria durante el d\u00eda sigue siendo normal, incluso hago ejercicio, pero durante la noche tengo atracones y como mucho, sobre todo dulces\u00bb.<\/p>\n<p>En efecto,<strong>\u00a0seg\u00fan la m\u00e9dica psiquiatra y terapeuta Juana Poulisis<\/strong>, \u00abcuando buscamos calmar nuestra ansiedad a trav\u00e9s de ciertas comidas, \u00e9stas funcionan como un regulador, que amortigua y anestesia las sensaciones de angustia y vac\u00edo, pero a corto plazo.\u00bb<\/p>\n<p><strong>\u00abEn realidad, nadie se come una ensalada en una situaci\u00f3n de estr\u00e9s\u00bb,<\/strong>\u00a0insisti\u00f3 Porras.<\/p>\n<p>Luna Segovia, de 19 a\u00f1os y<strong>\u00a0quien hab\u00eda sufrido un cuadro de anorexia cuando ten\u00eda 15, durante la pandemia comenz\u00f3 a comer de manera compulsiva y aument\u00f3 mucho de peso.<\/p>\n<p>\u00abEn terapia trabaj\u00e9 sobre qu\u00e9 pudo haber disparado mis ganas repentinas de comer\u00bb, se\u00f1al\u00f3 a T\u00e9lam. Y agreg\u00f3: \u00abCreo que se sumaron varias cosas, estaba por terminar la secundaria, y con mi familia nos est\u00e1bamos mudando a otro pa\u00eds, por lo que tuve que prepararme para rendir ex\u00e1menes en el exterior. Creo que todo eso, sumado a la situaci\u00f3n sanitaria y a que estaba aislada de mis amigos hizo que me angustiara\u00bb.<\/strong><\/p>\n<p>Poulisis advirti\u00f3 que \u00absi la conducta de comer en forma compulsiva, emocional, con atracones y picoteos se reitera y mantiene en el tiempo, generar\u00e1 m\u00e1s angustia, m\u00e1s culpa, dificultades con el peso, depresi\u00f3n y aislamiento\u00bb.<\/p>\n<p>En general,\u00a0<strong>el hambre emocional no aparece de la nada o porque s\u00ed. Algunos especialistas sostienen que existe una predisposici\u00f3n biol\u00f3gica relacionada con la estructura del cerebro en determinadas personas.\u00a0<\/strong>Otros, en cambio, postulan la intervenci\u00f3n de m\u00faltiples factores como el entorno social, el ambiente, las identificaciones culturales, los premios y castigos.<\/p>\n<p>\u00abEn muchos casos surge como consecuencia de haber transitado alguna de las &#8216;dietas restrictivas&#8217; que imponen como moda &#8216;saltear comidas&#8217;, o un &#8216;ayuno intermitente&#8217;; comer menos cantidad o consumir productos &#8216;diet\u00e9ticos&#8217;. En respuesta a estas prohibiciones, se da el atrac\u00f3n como efecto contrario, generando un comportamiento desmedido\u00bb, analiz\u00f3 Poulisis.<\/p>\n<p>Para la especialista,<strong>\u00a0\u00abel atrac\u00f3n, que es el t\u00e9rmino psicol\u00f3gico con el que nombramos a este tipo de diagn\u00f3stico, tambi\u00e9n puede aparecer en personas que tienen de base trastornos psiqui\u00e1tricos, alteraci\u00f3n del estado de \u00e1nimo, depresi\u00f3n, estr\u00e9s postraum\u00e1tico o situaciones no resueltas, como un abuso, por ejemplo\u00bb.<\/strong><\/p>\n<p>\u00abCuando en consultorio, las y los nutricionistas, analizamos la conducta alimentaria de nuestros pacientes, exploramos los &#8216;gatillos&#8217; que desataron esos comportamientos desordenados y, muchas veces, los derivamos a psicoterapia, entendiendo que solo desde el afrontamiento de alguna situaci\u00f3n emocional en particular, ser\u00e1 posible ayudar a regular tal comportamiento alimentario\u00bb, sostuvo Oliva.t\u00e9lam<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Los especialistas diferencian el \u00abhambre real\u00bb del \u00abhambre emocional\u00bb, y advirtieron que los \u00abatracones\u00bb pueden derivar por una \u00abalteraci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":87804,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"Hambre emocional: cuando escapar al estr\u00e9s atenta contra la salud","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15,70],"tags":[],"class_list":["post-87803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias","category-salud"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2023\/01\/20230130-Hambre.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/87803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=87803"}],"version-history":[{"count":3,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/87803\/revisions"}],"predecessor-version":[{"id":87808,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/87803\/revisions\/87808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/87804"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=87803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=87803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=87803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}