{"id":87673,"date":"2023-01-26T10:21:45","date_gmt":"2023-01-26T13:21:45","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=87673"},"modified":"2023-01-25T18:27:34","modified_gmt":"2023-01-25T21:27:34","slug":"anses-calendario-completo-de-pagos-a-jubilados-y-pensionados-de-febrero-2023","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2023\/01\/26\/anses-calendario-completo-de-pagos-a-jubilados-y-pensionados-de-febrero-2023\/","title":{"rendered":"ANSES: calendario completo de pagos a jubilados y pensionados de febrero 2023"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h6>La Administraci\u00f3n Nacional de la Seguridad Social (ANSES) modific\u00f3 el\u00a0<strong>calendario de pagos de febrero 2023 para los jubilados, pensionados<\/strong>\u00a0y titulares de la Asignaci\u00f3n Universal por Hijo (AUH) por los feriados de carnaval.<\/h6>\n<p>A trav\u00e9s de la Resoluci\u00f3n 273, el Gobierno anunci\u00f3 que<strong>\u00a0las fechas se unificar\u00e1n a partir del mi\u00e9rcoles 15 de febrero<\/strong>\u00a0y alterar\u00e1 los d\u00edas de acreditaci\u00f3n de los montos de hasta $ 25.000 para el segundo grupo, correspondiente a la Prestaci\u00f3n Alimentar (ex Tarjeta Alimentar).<\/p>\n<p>\u00abApru\u00e9bense los calendarios de pago de las Prestaciones del Sistema Integrado Previsional Argentino (SIPA), para las emisiones correspondientes a los meses de diciembre de 2022, que incluye la segunda cuota del haber anual complementario, enero y febrero de 2023\u00bb, figura en el art\u00edculo 1\u00b0 de la normativa publicada el 25 de noviembre.<\/p>\n<h4><strong>Calendario de cobro de Pensionados de Anses<\/strong><\/h4>\n<p>Los titulares de las Pensiones no Contributivas (PnC), en sus cuatro categor\u00edas, cobrar\u00e1n desde el mi\u00e9rcoles 1 de febrero, seg\u00fan la terminaci\u00f3n del DNI.<\/p>\n<p>DNI terminados en 0 y 1: mi\u00e9rcoles 1 de febrero<br \/>\nDNI terminados en 2 y 3: jueves 2 de febrero<br \/>\nDNI terminados en 4 y 5: viernes 3 de febrero<br \/>\nDNI terminados en 6 y 7: lunes 6 de febrero<br \/>\nDNI terminados en 8 y 9: martes 7 de febrero<\/p>\n<h4><strong>Jubilados de Anses: pago de febrero<\/strong><\/h4>\n<p>Los jubilados ANSES cobrar\u00e1n sus haberes desde el mi\u00e9rcoles 8 junto al bono de refuerzo de $10.000. Adem\u00e1s, si el titular es afiliado al PAMI, recibir\u00e1n un extra de $ 2500.<\/p>\n<p>DNI terminados en 0: mi\u00e9rcoles 8 de febrero<br \/>\nDNI terminados en 1: jueves 9 de febrero<br \/>\nDNI terminados en 2: viernes 10 de febrero<br \/>\nDNI terminados en 3: lunes 13 de febrero<br \/>\nDNI terminados en 4: martes 14 de febrero<br \/>\nDNI terminados en 5: mi\u00e9rcoles 15 de febrero<br \/>\nDNI terminados en 6: mi\u00e9rcoles 15 de febrero<br \/>\nDNI terminados en 7: jueves 16 de febrero<br \/>\nDNI terminados en 8: jueves 16 de febrero<br \/>\nDNI terminados en 9: viernes 17 de febrero<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La Administraci\u00f3n Nacional de la Seguridad Social (ANSES) modific\u00f3 el\u00a0calendario de pagos de febrero 2023 para los jubilados, pensionados\u00a0y<\/p>\n","protected":false},"author":1,"featured_media":87674,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"ANSES: calendario completo de pagos a jubilados y pensionados de febrero 2023","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,41],"tags":[],"class_list":["post-87673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2023\/01\/20230126-ANses.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/87673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=87673"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/87673\/revisions"}],"predecessor-version":[{"id":87676,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/87673\/revisions\/87676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/87674"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=87673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=87673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=87673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}