{"id":84717,"date":"2022-11-07T11:10:50","date_gmt":"2022-11-07T14:10:50","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=84717"},"modified":"2022-11-07T00:46:07","modified_gmt":"2022-11-07T03:46:07","slug":"cuidarse-de-excesos-y-atender-a-los-signos-de-alarma-los-consejos-de-cardiologos-antes-del-mundial","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2022\/11\/07\/cuidarse-de-excesos-y-atender-a-los-signos-de-alarma-los-consejos-de-cardiologos-antes-del-mundial\/","title":{"rendered":"Cuidarse de excesos y atender a los signos de alarma, los consejos de cardi\u00f3logos antes del Mundial"},"content":{"rendered":"<h6><\/h6>\n<h6>Los efectos f\u00edsicos y psicol\u00f3gicos derivados de la pasi\u00f3n por el f\u00fatbol, como el aumento de la presi\u00f3n arterial y la frecuencia card\u00edaca, y el \u00abalto estr\u00e9s y nerviosismo\u00bb que viven los hinchas durante los partidos contribuyen a la aparici\u00f3n de \u00abcomplicaciones cardiovasculares\u00bb.<\/h6>\n<p>Los efectos f\u00edsicos y psicol\u00f3gicos derivados de la pasi\u00f3n por el f\u00fatbol como el aumento de la presi\u00f3n arterial y la frecuencia card\u00edaca, y el \u00abalto estr\u00e9s y nerviosismo\u00bb que viven los hinchas durante los partidos contribuyen a la aparici\u00f3n de \u00abcomplicaciones cardiovasculares\u00bb, por<strong>\u00a0lo que especialistas recomendaron \u00abcuidarse de los excesos\u00bb y \u00abprestar atenci\u00f3n a signos de alarma\u00bb<\/strong>, a dos semanas del Mundial de Qatar.<\/p>\n<p>Gustavo Alcal\u00e1, miembro de la Federaci\u00f3n Argentina de Cardiolog\u00eda (FAC), asegur\u00f3 a T\u00e9lam que las expectativas que suscita la Copa Mundial de la FIFA para los muy futboleros y los que no lo son tanto no los libran de las consecuencias que pueden tener esas cargas emocionales en la salud.<\/p>\n<p><strong>\u00abIncremento de la presi\u00f3n arterial y de la frecuencia card\u00edaca, la liberaci\u00f3n de adrenalina por ansiedad y hostilidad, m\u00e1s la alteraci\u00f3n en ocasiones de las horas de descanso y sue\u00f1o\u00bb<\/strong>, enumer\u00f3 el especialista sobre los s\u00edntomas m\u00e1s habituales en \u00e9pocas de mundiales, que pueden contribuir en conjunto a complicaciones cardiovasculares como arritmias, infartos de miocardio y accidentes cerebrovasculares.<\/p>\n<p><strong>El f\u00fatbol y la salud cardiovascular<\/strong><\/p>\n<p>Al ser uno de los\u00a0<strong>deportes m\u00e1s populares del mundo<\/strong>, el f\u00fatbol gener\u00f3 m\u00e1s\u00a0<strong>investigaciones sobre su relaci\u00f3n con la salud<\/strong>\u00a0cardiovascular de jugadores y espectadores.<\/p>\n<p>\u00abUna de ellas se realiz\u00f3 durante la<strong>\u00a0eliminaci\u00f3n de Inglaterra a manos de Argentina en Francia 1998<\/strong>, luego del tiempo suplementario y los penales (el arquero argentino Carlos Roa ataj\u00f3 dos)\u00bb, explic\u00f3 Alcal\u00e1.<\/p>\n<p><strong>Ese d\u00eda y en las 48 horas posteriores\u00a0<\/strong>\u00ablos\u00a0<strong>infartos de miocardio se incrementaron en Inglaterra un 25%<\/strong>\u00a0en comparaci\u00f3n con el mismo per\u00edodo de a\u00f1os sin Copa Mundial de f\u00fatbol, describi\u00f3.<\/p>\n<p>El cardi\u00f3logo sostuvo que investigadores de las universidades de Bristol y Birmingham (Reino Unido) analizaron cuidadosamente los datos en 2002 (Mundial en Corea del Sur y Jap\u00f3n), pero el resultado fue que \u00abno ocurri\u00f3 lo mismo en los otros partidos que disput\u00f3 la selecci\u00f3n inglesa en esa competencia\u00bb.<\/p>\n<p>\u00abLa ciencia tambi\u00e9n es piadosa y no se evalu\u00f3 la influencia en Brasil cuando jug\u00f3 como local y perdi\u00f3 1 a 7 ante Alemania en semifinales de 2014\u00bb, brome\u00f3 Alcal\u00e1 en di\u00e1logo con T\u00e9lam.<\/p>\n<p>Sin embargo, s\u00ed\u00a0<strong>se public\u00f3 el incremento de infartos en ese pa\u00eds durante los Mundiales de 1998, 2002, 2006 y 2010,<\/strong>\u00a0lo que arroj\u00f3 \u00abun 9% m\u00e1s durante los torneos y 16% m\u00e1s los d\u00edas en que jug\u00f3 su Selecci\u00f3n\u00bb.<\/p>\n<p><strong>Un hallazgo en Espa\u00f1a<\/strong>\u00a0fue mostrar que los\u00a0<strong>d\u00edas de partido durante la liga local<\/strong>\u00a0\u00ab<strong>el cumplimiento con la medicaci\u00f3n antidiab\u00e9tica, f\u00e1rmacos para presi\u00f3n arterial y colesterol bajaba significativamente<\/strong>, seg\u00fan una investigaci\u00f3n publicada este a\u00f1o\u00bb, indic\u00f3 el especialista.<\/p>\n<h4><strong>S\u00edntomas de alarma y recomendaciones<\/strong><\/h4>\n<p>En los casos donde la emoci\u00f3n futbolera puede desatar alguna complicaci\u00f3n de salud se recomienda prestar atenci\u00f3n a los\u00a0<strong>principales signos de alarma\u00a0<\/strong>que requieren consulta inmediata, como\u00a0<strong>dolor en el pecho, mand\u00edbula o brazos; falta inusual de aire y dificultad para hablar o entender lo que otros est\u00e1n diciendo.<\/strong><\/p>\n<p>A esta lista se suma la\u00a0<strong>par\u00e1lisis o entumecimiento de un brazo o pierna<\/strong>, junto con el<strong>\u00a0dolor s\u00fabito e intenso de cabeza y los problemas de equilibrio y coordinaci\u00f3n,\u00a0<\/strong>a\u00f1adi\u00f3 Alcal\u00e1.<\/p>\n<p>Como la distinci\u00f3n no es sencilla, el cardi\u00f3logo remarc\u00f3 la importancia de \u00abdejar el televisor de lado o solicitar ayuda dentro del estadio\u00bb ante la duda si se presentan s\u00edntomas sugestivos de un evento cardiovascular, ya que el tiempo de demora hasta el tratamiento \u00abmodifica sustancialmente el pron\u00f3stico\u00bb.<\/p>\n<p>Entre las\u00a0<strong>principales recomendaciones previas a los partidos<\/strong>, apunt\u00f3 \u00ab<strong>limitar el consumo de alcohol, grasas animales y cigarrillos, o no fumar\u00bb<\/strong>, y\u00a0<strong>verificar si los valores de presi\u00f3n arterial, az\u00facar y colesterol<\/strong>\u00a0en sangre \u00abest\u00e1n bajo control\u00bb.<\/p>\n<p>\u00abSi no te hace bien el f\u00fatbol, no lo mires, y si te pone nervioso el relator que est\u00e1 transmitiendo el partido, escuchalo mudo\u00bb, dijo a T\u00e9lam el\u00a0<strong>cardi\u00f3logo y expresidente de la Fundaci\u00f3n Cardiol\u00f3gica Argentina, Jorge Tartaglione<\/strong>, que adem\u00e1s recomend\u00f3 a quienes toman medicaci\u00f3n no dejar de hacerlo y ser \u00abm\u00e1s preciso\u00bb que nunca.<\/p>\n<p>\u00ab<strong>Lo ideal es que los pacientes card\u00edacos tengan m\u00e1s cuidado con los excesos que el resto de los mortales\u00bb<\/strong>, a\u00f1adi\u00f3.<\/p>\n<h4><strong>La previa al partido<\/strong><\/h4>\n<p>Otro punto a tener en cuenta son las<strong>\u00a0previas de los partidos.<\/strong>\u00a0\u00abEn estos casos, es recomendable no comerse un super asado y tampoco quedarse sin dormir para ver el juego de la 7 de la ma\u00f1ana\u00bb, destac\u00f3.<\/p>\n<p>En relaci\u00f3n a los<strong>\u00a0efectos mentales de la fiebre futbolera<\/strong>, el\u00a0<strong>psic\u00f3logo Diego Quindimil<\/strong>\u00a0explic\u00f3 a T\u00e9lam que uno de los motivos por los que hay tantas expectativas es que \u00aba muchos que nos gusta el f\u00fatbol vemos en los jugadores a nuestro ideal del yo\u00bb, lo que significa que \u00abson estas personas que est\u00e1n cumpliendo el sue\u00f1o que a nosotros nos hubiese gustado cumplir, vestir la camiseta argentina\u00bb.<\/p>\n<p><strong>La pasi\u00f3n \u00abtiene la misma ra\u00edz que la palabra padecimiento\u00bb,<\/strong>\u00a0lo que significa que \u00abes un arma de doble filo\u00bb, dijo Quindimil, para quien ese sentimiento puesto en exceso en un partido de f\u00fatbol \u00abpuede provocar una situaci\u00f3n de alto estr\u00e9s, gran ansiedad, nerviosismo, inclusive de angustia marcada si el resultado no es como esper\u00e1bamos\u00bb.<\/p>\n<p>\u00abEsto genera un estado de tensi\u00f3n que, en el caso de que el partido sea victorioso, se puede volver incluso en un desborde de alegr\u00eda; pero lo mismo sucede si el resultado es negativo, puede haber una gran tristeza y una gran frustraci\u00f3n, lo que impacta en el humor social del d\u00eda a d\u00eda y tambi\u00e9n en la salud mental\u00bb, detall\u00f3.<\/p>\n<p>Para abordar estas situaciones, Quindimil retom\u00f3 una frase del exfutbolista y entrenador italiano Arrigo Sacchi, quien dijo que \u00ab<strong>el f\u00fatbol es la cosa m\u00e1s importante de las menos importantes\u00bb.<\/strong><\/p>\n<p>\u00abYo creo que el f\u00fatbol es hermoso, que el Mundial es una fiesta, que somos muy apasionados por el f\u00fatbol y todo lo que lo rodea, pero hay que darle la importancia que se merece porque la vida tiene otras alegr\u00edas y otros sufrimientos\u00bb, concluy\u00f3.t\u00e9lam<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los efectos f\u00edsicos y psicol\u00f3gicos derivados de la pasi\u00f3n por el f\u00fatbol, como el aumento de la presi\u00f3n arterial y<\/p>\n","protected":false},"author":1,"featured_media":84718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"Cuidarse de excesos y atender a los signos de alarma, los consejos de cardi\u00f3logos antes del Mundial","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-84717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/11\/20221107-Tano-Pasman.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/84717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=84717"}],"version-history":[{"count":3,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/84717\/revisions"}],"predecessor-version":[{"id":84721,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/84717\/revisions\/84721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/84718"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=84717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=84717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=84717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}