{"id":79952,"date":"2022-07-29T11:34:50","date_gmt":"2022-07-29T14:34:50","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=79952"},"modified":"2022-07-28T23:14:12","modified_gmt":"2022-07-29T02:14:12","slug":"mas-de-3-000-vehiculos-electricos-fueron-patentados-en-el-primer-semestre-en-el-pais","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2022\/07\/29\/mas-de-3-000-vehiculos-electricos-fueron-patentados-en-el-primer-semestre-en-el-pais\/","title":{"rendered":"M\u00e1s de 3.000 veh\u00edculos el\u00e9ctricos fueron patentados en el primer semestre en el pa\u00eds"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5 class=\"block__headline\">Esta cifra es 274 unidades m\u00e1s alta que el registro del mismo per\u00edodo del a\u00f1o pasado.<\/h5>\n<p class=\"block__headline\">Un total de 3.453 veh\u00edculos con motorizaci\u00f3n no tradicional, es decir completamente el\u00e9ctricos o h\u00edbridos, se patentaron en el primer semestre del a\u00f1o en la Argentina, lo que represent\u00f3 un incremento del 28% respecto del mismo per\u00edodo de 2021, de acuerdo con un informe del Sistema de Informaci\u00f3n Online del Mercado Automotor de Argentina (Siomaa).<\/p>\n<div class=\"entry\">\n<p>Las ventas en el mercado local durante el primer semestre del a\u00f1o las contin\u00faa liderando Toyota, con algo m\u00e1s del 84% de participaci\u00f3n del total, destac\u00f3 el reporte del Siomaa que depende de la Asociaci\u00f3n de Concesionarias de Automotores (Acara).<\/p>\n<p>Toyota lidera este mercado de electromovilidad con sus dos modelos Corolla, la versi\u00f3n sed\u00e1n y la SUV Cross, que son los modelos m\u00e1s vendidos, con un crecimiento del \u00faltimo del 39% respecto del segundo trimestre de 2021.<\/p>\n<p>La lista de marcas m\u00e1s vendidas en el segmento contin\u00faa con Ford con su modelo Kuga y la incursi\u00f3n de la nueva F-150, con 283 unidades totales; y en tercer lugar DS con 64 patentamientos de su DS 7 Crossback.<\/p>\n<p>Luego le sigue la novedad del semestre que es la nacional Coradir, con los primeros patentamientos de su modelo Tito (%3 unidades), Lexus (50), Peugeot (24), Mercedes Benz (17), Nissan (15), Volvo (11), Audi (11), Renault (10), Land Rover (7), Honda (2) y Sero (2).<\/p>\n<p>De esta manera se movi\u00f3 el mercado de electromovilidad en el primer semestre en la Argentina, con un total de 3.453 veh\u00edculos con motorizaci\u00f3n no tradicional patentados, de los cuales 82 fueron el\u00e9ctricos puros y 3.371 h\u00edbridos, tal como se puede acceder en el portal www.siomaa.com.<\/p>\n<p>Esta cifra es 274 unidades m\u00e1s alta que el registro del mismo per\u00edodo del a\u00f1o pasado (+28,7%), lo que demuestra que la performance del sector contin\u00faa ligada a la regulaci\u00f3n del Ministerio de Desarrollo Productivo y a sus disposiciones para establecer cupos para la importaci\u00f3n de este tipo de veh\u00edculos con preferencias arancelarias.<\/p>\n<p>La puesta en vigencia de cada decreto permiti\u00f3 la importaci\u00f3n de los cupos asignados y los patentamientos de esas unidades avanzaron al mismo ritmo.<\/p>\n<p>De hecho, el decreto 159\/2022 distribuy\u00f3 los cupos para la importaci\u00f3n del trimestre marzo \u2013 junio 2022 y dio curso a solicitudes por 939 unidades de las 1.284 disponibles.<\/p>\n<p>Las unidades que se autorizar\u00e1n para el trimestre junio \u2013 septiembre a\u00fan no se distribuyeron aunque el per\u00edodo para presentar solicitudes de importaci\u00f3n venci\u00f3 el 16 de mayo.<\/p>\n<p>El informe del Siomaa tambi\u00e9n destac\u00f3 que en este primer semestre del a\u00f1o, siete marcas patentaron modelos nuevos en el mercado argentino.<\/p>\n<p>La nacional Coradir comenz\u00f3 a vender su Tito S2-100 y la primera unidad de su S5-100 (5 puertas), Peugeot patent\u00f3 la versi\u00f3n hibrida de su 3008, Audi el A4, Mercedes Benz los C300 y E450, Volvo sus versiones hibridas de XC60, XC40 y XC90, mientras que Lexus LS, DS 4 y Honda Accord tuvieron tambi\u00e9n su debut en el mercado local.<\/p>\n<p>Finalmente, el parque de circulantes puramente el\u00e9ctricos corresponden a 13 modelos que circulan por las calles argentinas y que tienen una historia relativamente corta, ya que los primeros comenzaron a patentarse reci\u00e9n en 2018 y desde entonces avanzan lentamente hasta las actuales 247 unidades en circulaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Esta cifra es 274 unidades m\u00e1s alta que el registro del mismo per\u00edodo del a\u00f1o pasado. Un total de<\/p>\n","protected":false},"author":1,"featured_media":79918,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"M\u00e1s de 3.000 veh\u00edculos el\u00e9ctricos fueron patentados en el primer semestre en el pa\u00eds","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15,2589],"tags":[],"class_list":["post-79952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias","category-medio-ambiente-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/07\/20220729-Auto-electrico.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/79952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=79952"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/79952\/revisions"}],"predecessor-version":[{"id":79954,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/79952\/revisions\/79954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/79918"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=79952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=79952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=79952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}