{"id":78354,"date":"2022-06-29T08:09:52","date_gmt":"2022-06-29T11:09:52","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=78354"},"modified":"2022-06-28T18:14:01","modified_gmt":"2022-06-28T21:14:01","slug":"cinco-consejos-para-evitar-la-ludopatia","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2022\/06\/29\/cinco-consejos-para-evitar-la-ludopatia\/","title":{"rendered":"Cinco consejos para evitar la Ludopat\u00eda"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5 class=\"block__headline\">La ludopat\u00eda o adicci\u00f3n al juego es el problema psicol\u00f3gico m\u00e1s peligroso que conlleva a unas secuelas terribles.<\/h5>\n<p class=\"block__headline\">La ludopat\u00eda o adicci\u00f3n al juego es el problema psicol\u00f3gico m\u00e1s peligroso que conlleva a unas secuelas terribles, para el adicto al juego y para todo su entorno m\u00e1s cercano, est\u00e1 ser\u00e1 la conducta compulsiva sin control que obligar\u00e1 a jugar y apostar en las <strong>casas de apuestas<\/strong>\u00a0de una manera compulsiva.<\/p>\n<div class=\"entry\">\n<p>No se puede conseguir placer alguno con esta actividad, los lud\u00f3patas no van a disfrutar al apostar, s\u00f3lo lo necesitan para poder calmar su propio dolor o insatisfacci\u00f3n personal, siempre se va a considerar que alguien tenga problemas de ludopat\u00eda cuando estos pierden much\u00edsimo dinero o hasta llegar a la ruina.<\/p>\n<p>Este no ser\u00e1 el \u00fanico problema, el problema principal ser\u00e1 que el jugador, que est\u00e1 implicado en exclusiva en los juegos, va a descuidar o abandonara totalmente otras realidades c\u00f3mo las personales, por ejemplo, familiares, sociales o laborales, esto quiere decir que el juego cambiar\u00e1 totalmente y radicalmente su vida.<\/p>\n<h4>\u00bfC\u00f3mo evitar la ludopat\u00eda?<\/h4>\n<p><strong>La familia juega un rol importante<\/strong><\/p>\n<p>El papel que cumple la familia o su entorno m\u00e1s pr\u00f3ximo es de suma importancia para que la evoluci\u00f3n de la enfermedad sea cual sea el grado de deterioro que ha llegado esa persona lud\u00f3pata c\u00f3mo consecuencia de los juegos, si esa persona tiene la suerte de tener consigo a su lado una pareja, un amigo o familiares que se decidan y est\u00e9n dispuestos totalmente a no dejarlo solo a pesar de todo.<\/p>\n<p>Ser\u00e1 la clave primordial para que esa persona supere ese gran problema, con la ayuda y una buena motivaci\u00f3n, el enfermo o adicto al juego puede llegar a sobresalir con tiempo de esa adicci\u00f3n.<\/p>\n<p>Cuando su entorno se llega a enfrentar a un lud\u00f3pata, este tipo de personas podr\u00e1 ser que no vaya a reconocer que \u00e9l tiene esa enfermedad o que solo no quieren ponerse en tratamiento.<\/p>\n<p>Lo primero que hay que hacer es no negar nunca que existe un problema, no tener verg\u00fcenza o temores a las sentencias de los dem\u00e1s, y algo de mucha importancia es no dejar que esa adicci\u00f3n se llegue a progresar.<\/p>\n<p><strong>Pensar con l\u00f3gica<\/strong><\/p>\n<p>Debes pensar cu\u00e1l ser\u00e1 el motivo por el que juegas, que es lo que realmente te va a ofrecer el juego que no te pueda brindar otras cosas en tu vida, para conseguirlo por otros medios, ser\u00e1 muy posible que juegues puesto que te sientes muy solo, porque ser\u00e1 la representaci\u00f3n de obtener algo real en tu vida, o es puramente para relajarte.<\/p>\n<p>Para poder salir de esa enfermedad ser\u00e1 muy importante que hagas otras actividades que te van a permitir conocer a otras personas, que te van a motivar y mejorar tu autoestima, puede ser cine, un taller de lectura, un buen curso de fotograf\u00eda, distintos deportes, entre otras actividades m\u00e1s.<\/p>\n<p><strong>Mantener buena comunicaci\u00f3n con las personas de tu entorno<\/strong><\/p>\n<p>Deber\u00e1s comunicar tus preocupaciones a personas que le tengas mucha confianza, para que ellos puedan intentar ayudarte, en el caso de los adolescentes, el apoyo de la familia y un excelente ambiente le va a ayudar mucho, la comunicaci\u00f3n para que puedas decir tus problemas van a resultar ser la clave.<\/p>\n<p><strong>Mant\u00e9n una rutina saludable<\/strong><\/p>\n<p>Si piensas que hay una rutina en tu vida que te hace jugar, tarta en lo posible cambiarla, por ejemplo, no almuerces en ese establecimiento en donde existen las tragaperras a la que te va a costar resistirte.<\/p>\n<p>En vez de hacer eso, ve al gimnasio o da un largo paseo en vez de conectarte a una p\u00e1gina de apuestas, deber\u00e1s aprender t\u00e9cnicas nuevas para controlar el estr\u00e9s, esto tambi\u00e9n te va a ayudar a evitar las reca\u00eddas.<\/p>\n<p><strong>No pierdas el control<\/strong><\/p>\n<p>Es muy necesario a nivel social, que ejerzan un control de la elevada exhibici\u00f3n a los juegos de azar, ya que varias veces se va a transmitir que solo tienen \u00e9xito los que ganan.<\/p>\n<p>Poder superar est\u00e1 adicci\u00f3n al\u00a0<strong>juego<\/strong>\u00a0es una tarea dif\u00edcil y complicada, por lo que es probable, que el adicto vive momentos de estr\u00e9s y angustia en el que \u00e9l va a necesitar de ti para que lo apoyes, es de suma importancia que le puedas brindar todo tu apoyo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La ludopat\u00eda o adicci\u00f3n al juego es el problema psicol\u00f3gico m\u00e1s peligroso que conlleva a unas secuelas terribles. La<\/p>\n","protected":false},"author":1,"featured_media":78336,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"Cinco consejos para evitar la Ludopat\u00eda","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[],"class_list":["post-78354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/06\/20220629-LUDOPATIA.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/78354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=78354"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/78354\/revisions"}],"predecessor-version":[{"id":78356,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/78354\/revisions\/78356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/78336"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=78354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=78354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=78354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}