{"id":76219,"date":"2024-05-17T00:08:37","date_gmt":"2024-05-17T03:08:37","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=76219"},"modified":"2024-05-16T22:09:20","modified_gmt":"2024-05-17T01:09:20","slug":"dia-mundial-de-internet-por-que-se-celebra-este-17-de-mayo","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2024\/05\/17\/dia-mundial-de-internet-por-que-se-celebra-este-17-de-mayo\/","title":{"rendered":"D\u00eda Mundial de Internet: por qu\u00e9 se celebra este 17 de mayo"},"content":{"rendered":"<p>El objetivo de esta efem\u00e9ride es dar a conocer las posibilidades que ofrecen las nuevas tecnolog\u00edas y promover su accesibilidad a la red.<\/p>\n<p>En la actualidad se observa el incremento de la conectividad a la red y la consolidaci\u00f3n de la econom\u00eda digital, entre otros aspectos. Sin embargo, se destacan brechas o diferencias significativas en el acceso y velocidad de las redes, generando condiciones de desventaja y desigualdad en el uso de la red en varios pa\u00edses del mundo.<\/p>\n<h4 id=\"resTit_2\"><strong>Origen del D\u00eda Mundial de Internet<\/strong><\/h4>\n<p>El\u00a0<strong>D\u00eda Mundial de Internet<\/strong>\u00a0se celebr\u00f3 por primera vez el 25 de octubre de 2005, con un notable \u00e9xito de participaci\u00f3n.<\/p>\n<p>Poco tiempo despu\u00e9s, la Cumbre de la Sociedad de la Informaci\u00f3n celebrada en T\u00fanez en noviembre de 2005, decidi\u00f3 proponer a la\u00a0<strong>Organizaci\u00f3n de las Naciones Unidas (ONU)<\/strong>\u00a0la designaci\u00f3n del 17 de mayo como el\u00a0<strong>D\u00eda Mundial de las Telecomunicaciones y de la Sociedad de la Informaci\u00f3n<\/strong>, trasladando el D\u00eda Mundial de Internet a dicha fecha.<\/p>\n<p>Actualmente ambas fechas se celebran el 17 de mayo, ya que la ONU decret\u00f3 el 17 de mayo como\u00a0<strong>D\u00eda Mundial de las Telecomunicaciones y de la Sociedad de la Informaci\u00f3n<\/strong>.<\/p>\n<h4 id=\"resTit_3\"><strong>\u00bfC\u00f3mo ha cambiado Internet nuestra vida?<\/strong><\/h4>\n<p>El uso de internet ha cambiado la forma de relacionarnos con el mundo, traspasando las barreras de la comunicaci\u00f3n y las fronteras geogr\u00e1ficas. Diversos sectores (comercio, gobierno, educaci\u00f3n, salud, entre otros) han sido impactados por las redes de informaci\u00f3n, generando avances que benefician a la humanidad.<\/p>\n<p>Quien iba a pensar en los a\u00f1os 70 y 80 se podr\u00eda utilizar la tecnolog\u00eda como herramienta de apoyo en nuestra vida cotidiana, como buscar una receta de cocina al instante y con un solo clic, reservar un vuelo o hacer compras online. Estas facilidades son solo una de las ventajas de la universalizaci\u00f3n de Internet.<\/p>\n<p>Aspectos esenciales como la educaci\u00f3n o la sanidad han registrado notables avances gracias a las nuevas tecnolog\u00edas y el acceso a Internet: estudios y avances en el control y erradicaci\u00f3n de enfermedades y aplicaci\u00f3n de tratamientos y procedimientos m\u00e9dicos, telemedicina, fomento de la alfabetizaci\u00f3n digital y audiovisual, desarrollo del autoaprendizaje.<\/p>\n<p>En el \u00e1mbito laboral se destaca el mejoramiento en las condiciones de trabajo, simplificando los procesos de producci\u00f3n as\u00ed como el desempe\u00f1o de tareas y funciones, favoreciendo la comunicaci\u00f3n y el intercambio de informaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo de esta efem\u00e9ride es dar a conocer las posibilidades que ofrecen las nuevas tecnolog\u00edas y promover su accesibilidad<\/p>\n","protected":false},"author":1,"featured_media":76220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El 17 de mayo\u00a0se celebra el\u00a0D\u00eda Mundial de Internet\u00a0en gran parte del mundo, promovido por la\u00a0Asociaci\u00f3n de Usuarios de Internet e Internet Society","footnotes":"","jetpack_publicize_message":"D\u00eda Mundial de Internet: por qu\u00e9 se celebra este 17 de mayo","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,2594],"tags":[],"class_list":["post-76219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-efemerides"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/05\/20220516-internet.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/76219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=76219"}],"version-history":[{"count":5,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/76219\/revisions"}],"predecessor-version":[{"id":104992,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/76219\/revisions\/104992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/76220"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=76219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=76219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=76219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}