{"id":74940,"date":"2022-04-24T22:12:44","date_gmt":"2022-04-25T01:12:44","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=74940"},"modified":"2022-04-24T22:12:44","modified_gmt":"2022-04-25T01:12:44","slug":"el-rover-perseverance-de-la-nasa-filmo-un-eclipse-solar-en-marte","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2022\/04\/24\/el-rover-perseverance-de-la-nasa-filmo-un-eclipse-solar-en-marte\/","title":{"rendered":"El rover Perseverance de la NASA film\u00f3 un eclipse solar en Marte"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5 class=\"news-headline__article-summary\">En el video se puede ver a Fobos, una de las lunas marcianas, cruzando por delante del Sol. Es el mejor registro de este fen\u00f3meno jam\u00e1s tomado desde ese planeta.<\/h5>\n<p><strong>El rover Perseverance grab\u00f3 desde la superficie de Marte un eclipse solar que se produjo cuando la luna Fobos cruz\u00f3 por delante del Sol<\/strong>. Es el video de este fen\u00f3meno m\u00e1s ampliado y con m\u00e1s velocidad de fotogramas en la historia de la NASA.<br \/>\n<strong><br \/>\n\u00abPuedes ver detalles en la forma de la sombra de Fobos, como crestas y protuberancias en el paisaje de la luna. Tambi\u00e9n puedes ver las manchas solares. Y es genial que puedas ver este eclipse exactamente como lo vio el rover desde Marte\u00bb<\/strong>, dijo Mark Lemmon, astr\u00f3nomo planetario de la NASA.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/aKK7vS2CHC8\" width=\"824\" height=\"463\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<article class=\"article-body article-body--first-paragraph\">El veh\u00edculo de exploraci\u00f3n capt\u00f3 las im\u00e1genes el pasado 2 de abril, en el d\u00eda marciano n\u00famero 397 de su misi\u00f3n. Perseverance cuenta con una c\u00e1mara Mastcam-Z con actualizaci\u00f3n en el zoom.\u00a0<strong>Esto le permiti\u00f3 registrar mejores im\u00e1genes que sus antecesores Spirit y Opportunity<\/strong>, los primeros rover en tomar fotos de un eclipse solar en Marte en el a\u00f1o 2004.El eclipse dur\u00f3 poco m\u00e1s de 40 segundos, mucho menos que un eclipse solar visto desde la Tierra. Esto se debe a que\u00a0<strong>Fobos es aproximadamente 157 veces m\u00e1s peque\u00f1a que nuestra Luna<\/strong>. La otra luna de Marte, Deimos, es a\u00fan m\u00e1s chica.<\/p>\n<p>Seg\u00fan inform\u00f3 la NASA,\u00a0<strong>estas im\u00e1genes pueden ayudar a los cient\u00edficos a comprender mejor la \u00f3rbita de Fobos y c\u00f3mo su gravedad atrae la superficie marciana<\/strong>, dando forma a la corteza y el manto del planeta rojo. La luna se est\u00e1 acercando a Marte y est\u00e1 destinada a estrellarse contra el planeta en decenas de millones de a\u00f1os.<\/p>\n<\/article>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; En el video se puede ver a Fobos, una de las lunas marcianas, cruzando por delante del Sol. Es<\/p>\n","protected":false},"author":1,"featured_media":74941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"El rover Perseverance de la NASA film\u00f3 un eclipse solar en Marte","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-74940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/04\/20220425-Marte-Fobos-Eclipse.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/74940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=74940"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/74940\/revisions"}],"predecessor-version":[{"id":74943,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/74940\/revisions\/74943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/74941"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=74940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=74940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=74940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}