{"id":74482,"date":"2022-04-17T21:58:23","date_gmt":"2022-04-18T00:58:23","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=74482"},"modified":"2022-04-17T19:06:31","modified_gmt":"2022-04-17T22:06:31","slug":"doble-femicidio-en-jujuy-mato-a-dos-hermanas-e-hirio-a-la-madre-de-ambas","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2022\/04\/17\/doble-femicidio-en-jujuy-mato-a-dos-hermanas-e-hirio-a-la-madre-de-ambas\/","title":{"rendered":"Doble femicidio en Jujuy: mat\u00f3 a dos hermanas e hiri\u00f3 a la madre de ambas"},"content":{"rendered":"<h5><\/h5>\n<h5 class=\"detalle\">Javier Broy, de 37 a\u00f1os, ex pareja de una de las mujeres asesinadas, es el principal sospechoso. Se encuentra pr\u00f3fugo.<\/h5>\n<p><strong>Una joven madre de 23 a\u00f1os y su hermana de 27 fueron asesinadas y la madre de ambas result\u00f3 herida tras ser atacadas a tiros y golpes en la localidad juje\u00f1a de Yuto y por el hecho buscan a la expareja de la menor de las v\u00edctimas<\/strong>, quien cuenta con antecedentes por violencia de g\u00e9nero y ya estuvo detenido, informaron hoy fuentes policiales y judiciales.<\/p>\n<p>A su vez, la justicia imput\u00f3 a dos polic\u00edas de incumplimiento de los deberes de funcionario ya que<strong>\u00a0una de las v\u00edctimas hab\u00eda sido agredida por el principal sospechoso horas antes de que la mataran y deb\u00eda tener custodia<\/strong>.<\/p>\n<p>El hecho ocurri\u00f3 anteayer a la noche, en dicha<strong>\u00a0localidad del departamento de Ledesma<\/strong>, en el este de la provincia de Jujuy.<\/p>\n<p>Seg\u00fan las fuentes,\u00a0<strong>las v\u00edctimas fueron identificadas como Pamela Gorosito (23), su hermana Ramona (27) y la madre de ambas.<\/strong><\/p>\n<p>En base a las tareas investigativas,<strong>\u00a0los pesquisas policiales identificaron como principal sospechoso a Javier Broy (37)<\/strong>, expareja de una de las hermanas, quien esta tarde era buscado en distintas zonas urbanas y rurales de Yuto.<\/p>\n<p>Un vocero policial explic\u00f3 a T\u00e9lam que<strong>\u00a0este sospechoso hab\u00eda sido denunciado en diciembre pasado por su expareja por violencia de g\u00e9nero<\/strong>, tambi\u00e9n cuenta con \u00abantecedentes delictivos y se encontrar\u00eda armado\u00bb.<\/p>\n<p>Todo comenz\u00f3 la noche del viernes, alrededor de las 23, en un domicilio ubicado en el barrio Sur de Yuto, unos 160 kil\u00f3metros noreste de San Salvador de Jujuy, donde\u00a0<strong>Pamela, madre de dos ni\u00f1os, fue sorprendida presuntamente por su expareja, quien le efectu\u00f3 un disparo.<\/strong><\/p>\n<p>De acuerdo a los pesquisas, ese mismo d\u00eda, el hombre hab\u00eda ido hasta la casa de la v\u00edctima, la golpe\u00f3 y amenaz\u00f3 con matarla, lo que ella luego denunci\u00f3 en la comisar\u00eda local.<\/p>\n<p>De hecho,\u00a0<strong>Broy hab\u00eda estado detenido luego de que en diciembre \u00faltimo Pamela lo acus\u00f3 de \u00abviolaci\u00f3n de domicilio en un contexto de violencia de g\u00e9nero\u00bb.<\/strong><\/p>\n<p>Mientras que el personal policial, luego de constatar que Pamela estaba muerta de un balazo, recibi\u00f3 un llamado telef\u00f3nico de un vecino que alert\u00f3 que en el pasaje que divide los barrios Sur y San Miguel hab\u00eda dos personas tendidas en el suelo.<\/p>\n<p>Al concurrir a ese lugar los efectivos descubrieron que\u00a0<strong>esas dos v\u00edctimas eran la hermana y la madre de Pamela, quienes fueron atacadas aparentemente por el mismo agresor cuando intentaron auxiliar a la joven.<\/strong><\/p>\n<p>Seg\u00fan los peritos, Ramona yac\u00eda muerta de un balazo a varios metros de la casa de su hermana, mientras que la madre de ambas result\u00f3 herida a golpes en la cabeza, por lo que fue trasladada de urgencia al hospital Oscar Or\u00edas, de Libertador General San Mart\u00edn, donde qued\u00f3 internada.<\/p>\n<p><strong>\u00abSon varios los cuerpos designados de la Polic\u00eda que est\u00e1n afectados a la tarea de b\u00fasqueda, sin que hasta el momento se conozca el paradero del doble homicida\u00bb<\/strong>, dijo hoy a T\u00e9lam una fuente policial y agreg\u00f3 que las tareas se profundizaron en una zona de montes en Yuto y en los alrededores, pues los investigadores no descartan que all\u00ed pueda haber encontrado refugio.<\/p>\n<p>En los operativos intervienen efectivos de la Brigada de Investigaciones, el Cuerpo de Caballer\u00eda y Divisi\u00f3n Canes de la Unidad Regional 4, con asiento en Libertador General San Mart\u00edn.<\/p>\n<p>A su vez, la causa penal qued\u00f3 a cargo del fiscal en Violencia de G\u00e9nero 6, de la circunscripci\u00f3n Libertador General San Mart\u00edn, Julio Fernando Lobos, quien junto al ayudante fiscal Mart\u00edn Ra\u00fal Orihuela, se hicieron presente en Yuto para ordenar todas las tareas investigativas de rigor.<\/p>\n<p>Adem\u00e1s,<strong>\u00a0iniciaron actuaciones por \u00abfemicidio, homicidio simple y lesiones en concurso real\u00bb, a\u00f1adi\u00f3 el Ministerio P\u00fablico de la Acusaci\u00f3n (MPA).<\/strong><\/p>\n<p>Por su parte, el MPA indic\u00f3 que se inici\u00f3 una investigaci\u00f3n e imput\u00f3 a dos polic\u00edas por el delito de \u00abIncumplimiento de los deberes de funcionario p\u00fablico\u00bb.<\/p>\n<p>Es que los oficiales hab\u00edan recibido al orden por parte del fiscal Moreno para que concurrieran a la casa de la familia Gorosito luego de la denuncia por golpes contra el sospechoso buscado.<\/p>\n<p>Seg\u00fan consta en la pesquisa, los polic\u00edas se presentaron en la vivienda, pero al llegar no hab\u00eda nadie, y una persona les manifest\u00f3 que la v\u00edctima se hab\u00eda ido a la casa de su madre, ubicada en otro barrio.<\/p>\n<p><strong>El fiscal estableci\u00f3 que polic\u00edas no fueron a verificar tal situaci\u00f3n, por lo que no dispusieron la consigna.<\/strong><\/p>\n<p>En tanto, varias personas se manifestaron en las redes sociales pidiendo justicia por las hermanas asesinadas y condenando la negligencia por parte de los dos efectivos policiales.<\/p>\n<p><strong>\u00ab\u00a1Justicia para las hermanas Gorosito!, escribieron desde la p\u00e1gina de Facebook Feminismo Popular y Disidente Jujuy.<\/strong><\/p>\n<p>\u00abDescansa en paz hermosa, diste todo por ella y eso es digno de admiraci\u00f3n. Tus chicos te van a extra\u00f1ar much\u00edsimo. Siempre (emoji de coraz\u00f3n). Tuve la suerte de conocerte. Un fuerte abrazo al cielo (emoji de llanto)\u00bb, escribi\u00f3 otra usuaria con una foto de Pamela.<\/p>\n<p><em><strong>Si sos v\u00edctima de violencia de g\u00e9nero o conoc\u00e9s a alguien que necesite ayuda, comunicate a la l\u00ednea nacional y gratuita 144, que funciona todos los d\u00edas del a\u00f1o, las 24 horas.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Javier Broy, de 37 a\u00f1os, ex pareja de una de las mujeres asesinadas, es el principal sospechoso. Se encuentra pr\u00f3fugo.<\/p>\n","protected":false},"author":1,"featured_media":74484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"Doble femicidio en Jujuy: mat\u00f3 a dos hermanas e hiri\u00f3 a la madre de ambas","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[8],"tags":[],"class_list":["post-74482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/04\/20220417-Doble-Femicidio-Jujuy-1.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/74482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=74482"}],"version-history":[{"count":4,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/74482\/revisions"}],"predecessor-version":[{"id":74488,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/74482\/revisions\/74488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/74484"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=74482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=74482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=74482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}