{"id":68761,"date":"2022-01-13T13:44:32","date_gmt":"2022-01-13T16:44:32","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=68761"},"modified":"2022-01-13T13:44:32","modified_gmt":"2022-01-13T16:44:32","slug":"recomendaciones-para-un-uso-eficiente-y-responsable","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2022\/01\/13\/recomendaciones-para-un-uso-eficiente-y-responsable\/","title":{"rendered":"Recomendaciones para un uso eficiente y responsable"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>Ante las altas temperaturas, desde el ENRE recomienda algunas buenas pr\u00e1cticas para ser m\u00e1s eficientes en el consumo de la energ\u00eda el\u00e9ctrica.<\/h5>\n<p>Cuidar la energ\u00eda en nuestros hogares es una tarea que est\u00e1 al alcance de todos y todas; tan solo debemos realizar peque\u00f1as modificaciones en nuestros h\u00e1bitos. Te acercamos algunos consejos y datos que te servir\u00e1n de gu\u00eda para lograr un uso m\u00e1s eficiente.<\/p>\n<div class=\"alert alert-info\">\n<h4><strong><br \/>\nEquipos de aire acondicionado<\/strong><\/h4>\n<\/div>\n<ul>\n<li>Fij\u00e1 la temperatura en 24 \u00b0C.<\/li>\n<li>Cuando el equipo est\u00e9 encendido, manten\u00e9 puertas y ventanas cerradas para evitar el ingreso de aire exterior al ambiente climatizado.<\/li>\n<li>Apag\u00e1 el equipo de AA cuando abandones dicho ambiente.<\/li>\n<li>Record\u00e1 que el modo ventilaci\u00f3n ayuda al ahorro de energ\u00eda.<\/li>\n<\/ul>\n<div class=\"alert alert-info\">\n<p class=\"margin-0\">\n<h4><strong>Ventiladores<\/strong><\/h4>\n<p>Presentan tres grandes ventajas:<\/p>\n<\/div>\n<ul>\n<li>En determinados ambientes, los ventiladores (preferentemente de techo) pueden mantener un adecuado confort, e incluso producir una sensaci\u00f3n de descenso de la temperatura de entre 3 y 5\u00b0 C.<\/li>\n<li>Pr\u00e1cticamente no necesitan mantenimiento.<\/li>\n<li>Consumen menos kilovatios por hora que un equipo de aire acondicionado: casi ocho veces menos en el transcurso de un fin de semana.<\/li>\n<\/ul>\n<div class=\"alert alert-info\">\n<p class=\"margin-0\">\n<h4><strong>Heladera<\/strong><\/h4>\n<\/div>\n<ul>\n<li>Abr\u00ed la heladera el menor tiempo posible y asegurate de que quede bien cerrada.<\/li>\n<li>Verific\u00e1 el estado de los burletes de las puertas.<\/li>\n<li>Evit\u00e1 guardar alimentos calientes: la heladera consume m\u00e1s energ\u00eda para enfriarlos.<\/li>\n<li>Descongelala regularmente. El exceso de consumo comienza cuando las paredes interiores acumulan hielo.<\/li>\n<\/ul>\n<div class=\"alert alert-info\">\n<p class=\"margin-0\">\n<h4><strong>Lavarropas<\/strong><\/h4>\n<\/div>\n<ul>\n<li>Us\u00e1 el lavarropas en la capacidad m\u00e1xima aconsejada por el fabricante.<\/li>\n<li>Utiliz\u00e1 los programas m\u00e1s cortos y de lavado con agua fr\u00eda. El agua caliente consume un 80% m\u00e1s de energ\u00eda.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ante las altas temperaturas, desde el ENRE recomienda algunas buenas pr\u00e1cticas para ser m\u00e1s eficientes en el consumo de<\/p>\n","protected":false},"author":1,"featured_media":68762,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[],"class_list":["post-68761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2022\/01\/20220113-Aire-acondicionado.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/68761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=68761"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/68761\/revisions"}],"predecessor-version":[{"id":68764,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/68761\/revisions\/68764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/68762"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=68761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=68761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=68761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}