{"id":67571,"date":"2021-12-23T11:30:39","date_gmt":"2021-12-23T14:30:39","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=67571"},"modified":"2021-12-23T11:30:39","modified_gmt":"2021-12-23T14:30:39","slug":"navidad-2021-recomendaciones-para-realizar-compras-online-seguras","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2021\/12\/23\/navidad-2021-recomendaciones-para-realizar-compras-online-seguras\/","title":{"rendered":"Navidad 2021: Recomendaciones para realizar compras online seguras"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>Defensa de las y los Consumidores elabor\u00f3 una serie de recomendaciones a la hora de comprar los regalos para estas fiestas.<\/h5>\n<p>La Secretar\u00eda de Comercio Interior de la Naci\u00f3n, a trav\u00e9s de la Direcci\u00f3n Nacional de Defensa del Consumidor y Arbitraje en Consumo, elabor\u00f3 una serie de recomendaciones a la hora de comprar los regalos para estas fiestas. El objetivo es que quienes concreten sus compras puedan efectuar las operaciones con seguridad y verificar que las ofertas publicadas sean reales y no est\u00e9n manipuladas o presentadas de manera enga\u00f1osa.<\/p>\n<p>En el marco de los festejos de Navidad y A\u00f1o Nuevo, las y los consumidores cuentan con una serie de derechos que deben aplicarse y cumplirse en todas las relaciones de consumo. Estos son algunos de los consejos a tener en cuenta antes, durante y despu\u00e9s de realizar la compra por internet.<\/p>\n<p><strong>Antes de la compra<\/strong><\/p>\n<ul>\n<li>Verificar que las p\u00e1ginas web donde se quiere comprar sean seguras. Para identificarlas, la direcci\u00f3n del sitio debe comenzar con https:\/\/<\/li>\n<li>En internet hay infinidad de ofertas de bienes y servicios, por eso es muy importante investigar previamente, buscar referencias, comparar precios y la relaci\u00f3n precio\/calidad\/cantidad.<\/li>\n<li>Conocer los datos del vendedor o la empresa le aporta mayor seguridad a la compra y sirven para reclamar en caso de tener alg\u00fan problema.<\/li>\n<\/ul>\n<p><strong>Durante la compra<\/strong><\/p>\n<ul>\n<li>Una vez decidida la compra, es importante leer toda la informaci\u00f3n de la publicaci\u00f3n, inclusive la letra chica.<\/li>\n<li>Durante estas fechas suele haber diferentes tipos de promociones. Si dice \u201cPromoci\u00f3n v\u00e1lida hasta agotar stock\u201d o \u201cCantidades limitadas\u201d, tienen que informar las unidades disponibles. Si ofrecen un descuento, se debe aclarar el precio anterior. En caso del 2&#215;1, aclarar el precio unitario.<\/li>\n<li>Las empresas tienen que informar de forma clara toda la informaci\u00f3n sobre el env\u00edo: qui\u00e9n lo realiza, cu\u00e1l es el costo, cu\u00e1l es el plazo de entrega.<\/li>\n<li>Al momento del pago, no puede haber diferencias de precio entre efectivo, d\u00e9bito y cr\u00e9dito en un pago. Al realizar el pago con tarjeta de cr\u00e9dito, observar las opciones de cuotas disponibles, si tienen o no intereses y cu\u00e1l es el porcentaje de inter\u00e9s.<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-67572\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/12\/20211223-Compras-online-seguras.jpg\" alt=\"\" width=\"768\" height=\"428\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/12\/20211223-Compras-online-seguras.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/12\/20211223-Compras-online-seguras-300x167.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p><strong>Despu\u00e9s de la compra<\/strong><\/p>\n<ul>\n<li>Una vez concretada la compra, el proveedor debe enviar la factura electr\u00f3nica o el comprobante de pago.<\/li>\n<li>El plazo de entrega forma parte de la oferta y debe ser respetado. La empresa debe brindar un n\u00famero de seguimiento sobre el env\u00edo y darte correcta atenci\u00f3n a tus consultas.<\/li>\n<li>Todos los productos tienen una garant\u00eda legal. Si el producto es nuevo, es de 6 meses, y si es usado de 3. El proveedor puede ofrecer un plazo mayor, pero no menor al que establece la ley.<\/li>\n<li>Si se realiza la compra por internet, el comprador tiene un plazo de 10 d\u00edas desde que recibe el producto para arrepentirse de la compra. La empresa debe tener el bot\u00f3n de arrepentimiento de forma visible en su p\u00e1gina web.<\/li>\n<\/ul>\n<p><strong>Reclamos<\/strong><\/p>\n<ul>\n<li>Ante alg\u00fan inconveniente con la compra se puede reclamar.<\/li>\n<li>El proveedor directo y la plataforma electr\u00f3nica de venta deben recibir los reclamos, dar un trato respetuoso sin discriminaciones ni malas formas, y ofrecer soluciones.<\/li>\n<li>Si el consumidor no se est\u00e1 conforme con la respuesta de la empresa, puede ingresar su reclamo a trav\u00e9s de la Direcci\u00f3n Nacional de Defensa de las y los consumidores en la web<br \/>\nhttps:\/\/www.argentina.gob.ar\/produccion\/defensadelconsumidor\/formulario<\/li>\n<\/ul>\n<h4>Ahora 12<\/h4>\n<p>Contin\u00faa vigente el programa Ahora 12 de la Secretar\u00eda de Comercio Interior, para colaborar con el bolsillo de los hogares del pa\u00eds y fomentar el consumo en estas fiestas.<\/p>\n<p>El programa permite acceder a planes de financiamiento con tarjeta de cr\u00e9dito en 3, 6, 12, 18, 24 y 30 cuotas. Entre los rubros disponibles se encuentran Elementos durables de cocina, L\u00ednea blanca, Televisores y monitores, Peque\u00f1os electrodom\u00e9sticos, Computadoras, notebooks y tabletas, Indumentaria, Calzado y marroquiner\u00eda, juguetes, bicicletas, muebles, colchones, Artefactos de iluminaci\u00f3n, turismo, perfumer\u00eda, libros e instrumentos musicales.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Defensa de las y los Consumidores elabor\u00f3 una serie de recomendaciones a la hora de comprar los regalos para<\/p>\n","protected":false},"author":1,"featured_media":67573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,41],"tags":[],"class_list":["post-67571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/12\/20211223-Compras-online-seguras1.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/67571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=67571"}],"version-history":[{"count":3,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/67571\/revisions"}],"predecessor-version":[{"id":67576,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/67571\/revisions\/67576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/67573"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=67571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=67571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=67571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}