{"id":63262,"date":"2021-10-12T17:54:56","date_gmt":"2021-10-12T20:54:56","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=63262"},"modified":"2021-10-12T17:54:56","modified_gmt":"2021-10-12T20:54:56","slug":"kicillof-anuncio-la-vacunacion-libre-para-mayores-de-18-anos-en-toda-la-provincia","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2021\/10\/12\/kicillof-anuncio-la-vacunacion-libre-para-mayores-de-18-anos-en-toda-la-provincia\/","title":{"rendered":"Kicillof anunci\u00f3 la vacunaci\u00f3n libre para mayores de 18 a\u00f1os en toda la Provincia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>Es para segundas dosis y para personas con o sin comorbilidades. El Gobernador dijo que el 90% de los bonaerenses mayores de 18 ya tiene al menos una dosis.<\/h5>\n<p>El mismo d\u00eda en que el Gobierno bonaerense comenz\u00f3 a vacunar contra el coronavirus a ni\u00f1os de 3 a 11 a\u00f1os en los 135 municipios de la provincia, Axel Kicillof anunci\u00f3 tambi\u00e9n la inoculaci\u00f3n libre con segundas dosis para los mayores de 18 a\u00f1os sin enfermedades preexistentes. El proceso se iniciar\u00e1 a partir de este mi\u00e9rcoles, en todo el \u201cterritorio provincial\u201d, incluido a los que tienen m\u00e1s de 12 con alg\u00fan tipo de comorbilidad.<\/p>\n<p><em>\u201cA partir del d\u00eda de ma\u00f1ana tambi\u00e9n hay segunda dosis libre para mayores de 18 en todo el territorio provincial. Obviamente cumplido el plazo de cada una de las vacunas\u201d,<\/em> anunci\u00f3 el gobernador y aclar\u00f3 que<em> \u201cpodemos tener un problema de disponibilidad pero estamos con distribuci\u00f3n y log\u00edstica para llegar a todos los rincones. Seguimos con turnos pero tambi\u00e9n los mayores de 18 y los que tienen m\u00e1s de 12 con enfermedades tambi\u00e9n libre las dosis\u201d.<\/em><\/p>\n<p>El gobernador detall\u00f3 que el 90% de todos los mayores de 18 a\u00f1os de la provincia ya est\u00e1n vacunados, seg\u00fan las estimaciones poblacionales, y que, de ese 90%, el 83% tiene segunda dosis. Tambi\u00e9n aprovech\u00f3 para denunciar que \u201chubo una campa\u00f1a de antivacunaci\u00f3n para todos los gustos\u201d pero, consider\u00f3,<em> \u201cpor suerte tenemos una sociedad que entendi\u00f3 que al vacunarnos todos nos cuidamos todos\u201d.<br \/>\n<\/em><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58360\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/07\/20210727-VACUNACION.jpg\" alt=\"\" width=\"768\" height=\"428\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/07\/20210727-VACUNACION.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/07\/20210727-VACUNACION-300x167.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Kicillof encabez\u00f3 el acto luego de recorrer las instalaciones del vacunatorio de la UTN junto al intendente de Mor\u00f3n, Lucas Ghi, y el ministro de Salud bonaerense, Nicol\u00e1s Kreplak. As\u00ed, los adultos podr\u00e1n acercarse a partir de ahora y sin turno a los m\u00e1s de 400 puntos para recibir la segunda dosis. En todos los casos, deber\u00e1n haber cumplido el per\u00edodo recomendado por las autoridades sanitarias respecto de la primera aplicaci\u00f3n.<\/p>\n<p>Hasta ahora, seg\u00fan el Ministerio de Salud de la Naci\u00f3n, el intervalo entre dosis es de 8 semanas para las vacunas Sputnik y AstraZeneca y 3 en el caso de haber sido inoculado con Sinopharm. Acorde a la informaci\u00f3n brindada por el Ministerio de Salud provincial, el total de vacunas aplicadas hasta ahora es de 21.071.389, de las cuales 11.626.014 corresponden a la primera dosis y 9.445.375 a la segunda.<\/p>\n<p>Asimismo, las autoridades recordaron a la poblaci\u00f3n que los mayores de 18 a\u00f1os podr\u00e1n acceder a la \u201cvacunaci\u00f3n libre\u201d a cualquier posta con DNI que acredite domicilio dentro del territorio bonaerense.<\/p>\n<p>Sobre el inicio de la vacunaci\u00f3n en los ni\u00f1os de 3 a 11 a\u00f1os, Kicillof expres\u00f3 que se<em> \u201ccruzan muchos sentimiento y emociones. En marzo del 2020 llegaban los primeros casos del covid que afect\u00f3 a 5 millones de contagiados que hubo en Argentina. Luego toda la etapa que consisti\u00f3 en la lucha sin instrumentos de avanzada. Nos enteramos que en algunos pa\u00edses del mundo la vacuna era exitosa y nos lanzamos a la b\u00fasqueda de la vacuna. Han pasado tantas cosas pero luego ya en diciembre desembarcaron las vacunas y cambi\u00f3 para siempre la historia de la pandemia\u201d.<\/em><\/p>\n<p><em>\u201cLas vacunas se concentran en muy pocos pa\u00edses y tenemos el privilegio de vacunar a nuestra poblaci\u00f3n. En Argentina lleg\u00f3 en diciembre de diferentes laboratorios\u201d,<\/em> agreg\u00f3 e inform\u00f3 que al menos 21 millones de vacunas fueron aplicadas en la provincia. En ese sentido, se refiri\u00f3 al \u00e9xodo en el pa\u00eds durante el fin de semana largo:<em> \u201cHubo un 60% m\u00e1s de turismo que antes de la pandemia. La causa de que este fin de semana haya sido explosivo es la vacuna\u201d.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Es para segundas dosis y para personas con o sin comorbilidades. El Gobernador dijo que el 90% de los<\/p>\n","protected":false},"author":1,"featured_media":58508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,56],"tags":[],"class_list":["post-63262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-buenos-aires"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/07\/20210730-vacunacion-18.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/63262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=63262"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/63262\/revisions"}],"predecessor-version":[{"id":63264,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/63262\/revisions\/63264"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/58508"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=63262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=63262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=63262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}