{"id":55967,"date":"2021-06-21T16:51:46","date_gmt":"2021-06-21T19:51:46","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=55967"},"modified":"2021-06-21T16:51:46","modified_gmt":"2021-06-21T19:51:46","slug":"la-ivermectina-seria-eficaz-en-el-tratamiento-contra-el-covid-segun-un-estudio","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2021\/06\/21\/la-ivermectina-seria-eficaz-en-el-tratamiento-contra-el-covid-segun-un-estudio\/","title":{"rendered":"La ivermectina ser\u00eda eficaz en el tratamiento contra el Covid, seg\u00fan un estudio"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>Un antiparasitario reduce la concentraci\u00f3n viral y es \u00fatil para el tratamiento de pacientes contagiado, seg\u00fan un estudio realizado en la Argentina.<\/h5>\n<p><strong>La ivermectina (IVM) reduce la concentraci\u00f3n viral y es \u00fatil para el tratamiento de pacientes contagiados con Covid-19,<\/strong>\u00a0seg\u00fan un estudio cient\u00edfico realizado en la Argentina y publicado en una revista del prestigioso grupo editor The Lancet.<\/p>\n<p>La ivermectina es un producto que se conoce m\u00e1s por su uso veterinario y que fue descubierta por el\u00a0<strong>cient\u00edfico japon\u00e9s Satoshi Omura, qui\u00e9n gan\u00f3 el Premio Nobel por su descubrimiento.<\/strong><\/p>\n<p>De origen veterinario, su uso es com\u00fan en seres humanos para e<strong>l tratamiento de algunas afecciones espec\u00edficas como en la llamada \u00abenfermedad de los r\u00edos\u00bb (una parasitosis transmitida por una mosca que produce ceguera), la sarna y la pediculosis,<\/strong>\u00a0y en muchos lugares es de venta libre.<\/p>\n<p>Como antiparasitario, la ivermectina es de venta habitual en las farmacias argentinas,\u00a0<strong>aunque no est\u00e1 aprobado por la ANMAT como tratamiento para el Covid-19.<\/strong><\/p>\n<p><strong>La Agencia Europea de Medicamentos (EMA) desaconsej\u00f3 hace unos meses su utilizaci\u00f3n en la prevenci\u00f3n o el tratamiento del coronavirus por fuera de ensayos cl\u00ednicos controlados.<\/strong><\/p>\n<p>La Organizaci\u00f3n Mundial de la Salud (OMS), a su vez, considera de \u00abmuy baja certeza\u00bb el \u00e9xito de los estudios realizados hasta el momento con el f\u00e1rmaco.<\/p>\n<p>En Am\u00e9rica Latina, hay ciudades y profesionales m\u00e9dicos que los emplean para pacientes con coronavirus, y en\u00a0<strong>Argentina son cinco las provincias que habilitaron su dosificaci\u00f3n en pacientes con la enfermedad: Misiones, Corrientes, La Pampa, Salta y Tucum\u00e1n.<\/strong><\/p>\n<p>El estudio argentino fue realizado con el apoyo de la Agencia Nacional de Promoci\u00f3n de la Investigaci\u00f3n, el Desarrollo Tecnol\u00f3gico y la Innovaci\u00f3n, y tuvo como objetivo evaluar el efecto antiviral de la ivermectina sobre la carga viral de las secreciones respiratorias y su relaci\u00f3n con las concentraciones plasm\u00e1ticas del f\u00e1rmaco.<\/p>\n<p>La investigaci\u00f3n recibi\u00f3 un importante aval al ser publicado en la revista cient\u00edfica \u00abE Clinical Medicine\u00bb, del grupo editor The Lancet.<\/p>\n<p>Se trat\u00f3 de una prueba para evaluar la actividad antiviral de IVM en dosis altas en 45 pacientes internados con Covid-19 en cuatro hospitales de Argentina.<\/p>\n<p>Los pacientes elegibles eran adultos con infecci\u00f3n por SARS- CoV-2 confirmada por RT-PCR dentro de los 5 d\u00edas posteriores al inicio de los s\u00edntomas.<\/p>\n<p>El criterio de valoraci\u00f3n principal fue la diferencia en la carga viral en las secreciones respiratorias entre el inicio y el d\u00eda 5, mediante RT-PCR cuantitativa, adem\u00e1s de medirse las concentraciones de IVM en plasma.<\/p>\n<p><strong>En los primeros cuatro meses de ensayos se comprob\u00f3 que la administraci\u00f3n de ivermectina a dosis de 0,6 miligramos por kilo de peso,<\/strong>\u00a0el triple de lo usado habitualmente, <em>\u00abproduce la eliminaci\u00f3n m\u00e1s r\u00e1pida y profunda del virus cuando se inicia el tratamiento en etapas tempranas de la infecci\u00f3n (hasta 5 d\u00edas desde el inicio de s\u00edntomas)\u00bb.<\/em><\/p>\n<p>En el estudio se logr\u00f3 identificar una actividad antiviral dependiente de la concentraci\u00f3n de la ivermectina oral en dosis altas en un r\u00e9gimen de dosificaci\u00f3n que fue bien tolerado.<\/p>\n<p>No obstante, los investigadores advirtieron que se necesitan grandes ensayos con criterios de valoraci\u00f3n cl\u00ednicos para determinar la utilidad cl\u00ednica de IVM en Covid-19.<\/p>\n<p><em>\u00abNuestro estudio aporta evidencia de la<strong>\u00a0actividad antiviral de la ivermectina contra el SARS-CoV-2 en pacientes con Covid-19 a trav\u00e9s de un ensayo cl\u00ednico aleatorizado, controlado y cegado al evaluador de resultados con an\u00e1lisis innovadores\u00bb<\/strong>,<\/em> indicaron los investigadores en la nota.<\/p>\n<p>Explicaron que <em>\u00abse identific\u00f3 un efecto antiviral dependiente de la concentraci\u00f3n de la ivermectina en COVID-19, con r<strong>educciones significativas en la carga viral del SARS-CoV-2\u00a0<\/strong>en las secreciones respiratorias entre los pacientes que alcanzaron una alta concentraci\u00f3n de ivermectina sist\u00e9mica en comparaci\u00f3n con los controles no tratados\u00bb.<\/em><\/p>\n<p><em>\u00abEstos resultados, que no mostraron toxicidad relacionada con el uso de ivermectina en dosis altas, proporcionan evidencia del efecto antiviral y respaldan el dise\u00f1o de ensayos para investigar las implicaciones cl\u00ednicas de nuestros hallazgos.<strong>\u00a0Tambi\u00e9n se justifica una mayor exploraci\u00f3n de los factores implicados en la biodisponibilidad oral de la ivermectina\u00bb<\/strong>,<\/em> afirmaron. na<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un antiparasitario reduce la concentraci\u00f3n viral y es \u00fatil para el tratamiento de pacientes contagiado, seg\u00fan un estudio realizado<\/p>\n","protected":false},"author":1,"featured_media":55968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15],"tags":[],"class_list":["post-55967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/06\/20210622-ivermectina.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/55967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=55967"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/55967\/revisions"}],"predecessor-version":[{"id":55970,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/55967\/revisions\/55970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/55968"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=55967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=55967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=55967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}