{"id":50569,"date":"2021-04-11T18:34:05","date_gmt":"2021-04-11T21:34:05","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=50569"},"modified":"2021-04-11T18:34:05","modified_gmt":"2021-04-11T21:34:05","slug":"directores-de-hospitales-llaman-a-la-responsabilidad-ciudadana-en-el-peor-momento-de-la-pandemia","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2021\/04\/11\/directores-de-hospitales-llaman-a-la-responsabilidad-ciudadana-en-el-peor-momento-de-la-pandemia\/","title":{"rendered":"Directores de hospitales llaman a la \u00abresponsabilidad ciudadana\u00bb en el \u00abpeor momento\u00bb de la pandemia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>Directores de hospitales bonaerenses llamaron a la \u00abresponsabilidad ciudadana para salvar miles de vidas\u00bb ya que, advirtieron, el pa\u00eds est\u00e1 en el \u00abpeor momento\u00bb de la pandemia.<\/h5>\n<p>En una solicitada publicada hoy en medios gr\u00e1ficos bonaerenses, 139 autoridades sanitarias de la Provincia afirmaron que es<em> \u00abel peor momento de la pandemia\u00bb<\/em> y que <em>\u00abla cantidad de casos que son r\u00e9cords todos los d\u00edas demuestran esta situaci\u00f3n\u00bb.<\/em><\/p>\n<p>En ese marco, los firmantes hicieron<em> \u00abun llamado a la solidaridad y a la responsabilidad ciudadana para salvar miles de vidas\u00bb,<\/em> a la vez que advirtieron que es necesario que <em>\u00abtodos los habitantes de la provincia de Buenos Aires sepan lo que est\u00e1 pasando en cada hospital provincial y municipal\u00bb.<\/em><\/p>\n<p>Adem\u00e1s, indicaron que se trata de <em>\u00abun momento cr\u00edtico\u00bb ya que en los \u00faltimos 15 d\u00edas se ha multiplicado la cantidad de personas que requirieron hisopados, hicieron consultas o necesitaron internaci\u00f3n de \u00abuna manera que ni siquiera vimos en todo el a\u00f1o pasado\u00bb.<\/em><\/p>\n<p>Las autoridades sanitarias afirmaron que a pesar de las mejoras que hubo en el sistema de salud de la provincia, <em>\u00absi los casos siguen subiendo nada va a alcanzar\u00bb.<\/em><\/p>\n<p><em>\u00abVemos lo que pasa en la regi\u00f3n y en el mundo, con sistemas de salud m\u00e1s robustos que est\u00e1n colapsados\u00bb,<\/em> se\u00f1alaron, por lo que remarcaron que <em>\u00abnecesitamos de la solidaridad y la responsabilidad ciudadana para que los contagios no sigan creciendo y la situaci\u00f3n se descontrole\u00bb.<\/em><\/p>\n<p><em>\u00abSabemos que las medidas de los gobiernos nacional, provincial y municipales son fundamentales para tratar de controlar el espacio p\u00fablico y las apoyamos, porque vemos lo que est\u00e1 pasando. Pero no hay medida que funcione sin una ciudadan\u00eda solidaria y responsable que las cumpla, ni controles que las garanticen\u00bb,<\/em> aseveraron.<\/p>\n<p>En este sentido, remarcaron que es esencial tambi\u00e9n que los cuidados y los protocolos <em>\u00abse cumplan en el \u00e1mbito privado\u00bb<\/em> ya que <em>\u00abla mayor\u00eda de los casos que nos llegan a los hospitales son producto de reuniones familiares y encuentros con amigos\u00bb.<\/em><\/p>\n<p>Ante esta situaci\u00f3n, remarcaron que <em>\u00abson semanas claves, que pueden salvar miles de vidas\u00bb, al sostener que \u00abcada d\u00eda que ganemos, la vacunaci\u00f3n va a avanzar para proteger a quienes tienen mayor riesgo. Es un tiempo limitado pero clave, sabiendo que la vacuna nos da una salida tan cercana\u00bb.<\/em><\/p>\n<p><em>\u00abDesde nuestro lugar, seguiremos haciendo un esfuerzo extraordinario, que pone en juego nuestra salud y la de nuestras familias. Sentimos el acompa\u00f1amiento y aquellos aplausos nos reconfortaban\u00bb,<\/em> pero <em>\u00abel \u00fanico reconocimiento que necesitamos hoy es el esfuerzo de toda la ciudadan\u00eda para poder frenar los casos y ayudarnos a controlar la situaci\u00f3n\u00bb,<\/em> indicaron.<\/p>\n<p><em>\u00abSabemos que la pandemia no termin\u00f3 y est\u00e1 en su peor momento. Pero tambi\u00e9n sabemos que podemos hacer que termine\u00bb,<\/em> concluyeron.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Directores de hospitales bonaerenses llamaron a la \u00abresponsabilidad ciudadana para salvar miles de vidas\u00bb ya que, advirtieron, el pa\u00eds<\/p>\n","protected":false},"author":1,"featured_media":50570,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-50569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/04\/20210411-hospital.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/50569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=50569"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/50569\/revisions"}],"predecessor-version":[{"id":50572,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/50569\/revisions\/50572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/50570"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=50569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=50569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=50569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}