{"id":45769,"date":"2021-01-29T22:31:04","date_gmt":"2021-01-30T01:31:04","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=45769"},"modified":"2021-01-29T22:31:04","modified_gmt":"2021-01-30T01:31:04","slug":"clausuran-el-club-el-ciclon-de-burzaco-por-un-torneo-de-futbol-clandestino","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2021\/01\/29\/clausuran-el-club-el-ciclon-de-burzaco-por-un-torneo-de-futbol-clandestino\/","title":{"rendered":"Clausuran el Club \u00abEl Cicl\u00f3n\u00bb de Burzaco por un torneo de f\u00fatbol clandestino"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>El Municipio de Almirante Brown realiz\u00f3 una inspecci\u00f3n en el Club \u00abEl Cicl\u00f3n\u00bb de la localidad de Burzaco y procedi\u00f3 a clausurar las instalaciones luego de que en las \u00faltimas horas se desarrollara all\u00ed un torneo de f\u00fatbol clandestino que no respetaba los protocolos de prevenci\u00f3n del Covid-19 en medio de la pandemia.<\/h5>\n<p>Fuentes de la Direcci\u00f3n de Inspecci\u00f3n General del Municipio browniano informaron que una vez producida la clausura \u00abse gener\u00f3 un expediente que ser\u00e1 girado a la Justicia de Faltas para que determine las sanciones que corresponden en este caso\u00bb.<\/p>\n<p>El evento que motiv\u00f3 la inspecci\u00f3n y la clausura de la Comuna se habr\u00eda desarrollado sin respetar el distanciamiento social dispuesto por las autoridades sanitarias ni el horario l\u00edmite para las actividades nocturnas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; El Municipio de Almirante Brown realiz\u00f3 una inspecci\u00f3n en el Club \u00abEl Cicl\u00f3n\u00bb de la localidad de Burzaco y<\/p>\n","protected":false},"author":1,"featured_media":45770,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,33,43],"tags":[],"class_list":["post-45769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown","category-alte-brown-alte-brown","category-burzaco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2021\/01\/20210129-club-el-ciclon.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/45769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=45769"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/45769\/revisions"}],"predecessor-version":[{"id":45772,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/45769\/revisions\/45772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/45770"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=45769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=45769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=45769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}