{"id":4367,"date":"2016-07-15T17:18:07","date_gmt":"2016-07-15T20:18:07","guid":{"rendered":"http:\/\/laurbedigital.com.ar\/noticias\/?p=4367"},"modified":"2016-07-15T17:18:07","modified_gmt":"2016-07-15T20:18:07","slug":"la-anmat-hace-estudios-en-chocolates-potencialmente-cancerigenos","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2016\/07\/15\/la-anmat-hace-estudios-en-chocolates-potencialmente-cancerigenos\/","title":{"rendered":"La Anmat hace estudios en chocolates \u00abpotencialmente\u00bb cancer\u00edgenos"},"content":{"rendered":"<p>El organismo inform\u00f3 que\u00a0\u00abse est\u00e1n haciendo los estudios y evaluaciones t\u00e9cnicas correspondientes\u00bb\u00a0para conocer si existe riesgo en el pa\u00eds.<\/p>\n<p class=\"selectionShareable\">Los envoltorios de tres famosas marcas de chocolate contienen sustancias \u00abpotencialmente cancer\u00edgenas\u00bb, alert\u00f3 la organizaci\u00f3n de defensa de los derechos del consumidor y la calidad alimentaria \u00abFoodwatch\u00bb, mientras que la autoridad sanitaria argentina Anmat se\u00f1al\u00f3 que \u00abse est\u00e1n haciendo los estudios y evaluaciones t\u00e9cnicas correspondientes\u00bb para conocer si existe riesgo en el pa\u00eds.<\/p>\n<p class=\"selectionShareable\">\nFoodwatch, integrada por Alemania, Francia y Holanda, precis\u00f3 luego de realizar pruebas de laboratorio en 20 productos que se hallaron niveles \u00abpeligrosos\u00bb de hidrocarburos arom\u00e1ticos derivados de aceites minerales (MOAH, en ingl\u00e9s) en los envoltorios de las conocidas \u00abbarritas Kinder\u00bb de la empresa Ferrero, los \u00abFioretto Nougat Minis\u00bb de Lindt y \u00abSun Rice Classic Schoko Happen\u00bb de la marca R\u00fcbezahl.<\/p>\n<p class=\"selectionShareable\">\nSe trata de sustancias que se obtienen a trav\u00e9s de la refinaci\u00f3n del petr\u00f3leo y que en contacto con los alimentos pueden ser \u00abaltamente cancer\u00edgenas\u00bb, detall\u00f3 el organismo de control con sede en Berl\u00edn, que dijo haber informado \u00abde antemano\u00bb a los productores de esas golosinas acerca de los resultados de las pruebas para que retiraran los productos de la venta al p\u00fablico.<\/p>\n<p class=\"selectionShareable\">\nLas \u00abbarritas Kinder\u00bb fueron el dulce con peores resultados, ya que obtuvieron los niveles m\u00e1s altos en la prueba de aceites minerales saturados (MOSH) y en los MOAH, aunque Ferrero Argentina emiti\u00f3 hoy un comunicado en el que asegur\u00f3 que todos sus productos y \u00aben especial Kinder Chocolate\u00bb, son \u00abseguros y fabricados con la m\u00e1xima calidad y atenci\u00f3n a la seguridad, siempre de acuerdo con las m\u00e1s estrictas legislaciones y regulaciones alimentarias\u00bb.<\/p>\n<p class=\"selectionShareable\">\nLa compa\u00f1\u00eda afirm\u00f3 que \u00abla discusi\u00f3n sobre componentes de aceite mineral (MOSH\/MOAH) no es nueva y afecta a diferentes categor\u00edas de alimentos\u00bb y que los rastros de aceite mineral detectados en sus componentes \u00abexisten casi por doquier en el ambiente y pueden ser transferidos a los alimentos de muchas formas\u00bb.<\/p>\n<p class=\"selectionShareable\">\nUna de esas formas es a trav\u00e9s de \u00ablas tintas de impresi\u00f3n, que son introducidas al ciclo de reciclaje de los envoltorios y a trav\u00e9s del transporte conteniendo fibras recicladas migran a las materias primas y a los alimentos\u00bb. \u00abEn Ferrero estamos buscando soluciones t\u00e9cnicas para minimizar al m\u00e1ximo nivel posible estas sustancias y evitar su transferencia a trav\u00e9s de los envoltorios\u00bb, afirmaron y enfatizaron que \u00abel consumo de los productos mencionados es seguro, m\u00e1s a\u00fan al representar apenas una peque\u00f1a porci\u00f3n de la alimentaci\u00f3n total del individuo\u00bb.<\/p>\n<p class=\"selectionShareable\">\nSin embargo, para John Heeg, integrante de Foodwatch, en casos como estos los productores \u00abson culpables de una negligencia grave\u00bb, ya que \u00aben vez de quitar los chocolates del mercado y advertir a los consumidores sobre el riesgo se sostiene que todo se hizo de forma legal\u00bb, coment\u00f3.<\/p>\n<p class=\"selectionShareable\">\nEl organismo denunciante critic\u00f3 tambi\u00e9n a la Federaci\u00f3n Alemana de la Industria de Golosinas (BDSI, por su sigla en alem\u00e1n), asociaci\u00f3n a la que pertenecen Ferrero, Lindt y R\u00fcbezahl, pero esas empresas comunicaron oficialmente que \u00abel consumo de chocolate contaminado con aceites minerales arom\u00e1ticos es inofensivo\u00bb.<\/p>\n<p class=\"selectionShareable\">\nNo obstante, la Agencia Europea de Seguridad Alimentaria (EFSA), advirti\u00f3 que esos hidrocarburos arom\u00e1ticos en los alimentos tienen efectos \u00abaltamente mutag\u00e9nicos\u00bb independientemente de la cantidad que se ingiera, mientras que el Instituto Federal de Evaluaci\u00f3n de Riesgos (BfR) tambi\u00e9n consider\u00f3 que \u00abdebido a su potencial efecto cancer\u00edgeno ning\u00fan alimento ni sus envoltorios deber\u00edan presentar rastros de aceites minerales en ninguna medida\u00bb.<\/p>\n<p class=\"selectionShareable\">\nEl informe de Foodwatch tambi\u00e9n revel\u00f3 que esos productos contienen \u00abnumerosos aceites minerales saturados\u00bb que pueden \u00abacumularse en el cuerpo y producir a largo plazo graves da\u00f1os en los \u00f3rganos humanos especialmente en ni\u00f1os\u00bb, por lo que instaron a que se establezcan \u00abl\u00edmites estrictos para los MOSH en los alimentos y tolerancia cero para los aceites minerales arom\u00e1ticos en cualquier medida\u00bb.<\/p>\n<p class=\"selectionShareable\">\nA pesar de la denuncia, desde la BDSI aseguraron que \u00abno existe ninguna raz\u00f3n para que la poblaci\u00f3n entre en p\u00e1nico ni motivo suficiente como para retirar los productos del mercado\u00bb, y argumentaron que \u00ablos aceites est\u00e1n presentes en el envoltorio y no en el chocolate en s\u00ed mismo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El organismo inform\u00f3 que\u00a0\u00abse est\u00e1n haciendo los estudios y evaluaciones t\u00e9cnicas correspondientes\u00bb\u00a0para conocer si existe riesgo en el pa\u00eds. Los<\/p>\n","protected":false},"author":1,"featured_media":4368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[],"class_list":["post-4367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2016\/07\/20160715-salud.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=4367"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4367\/revisions"}],"predecessor-version":[{"id":4369,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/4367\/revisions\/4369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/4368"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=4367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=4367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=4367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}