{"id":26502,"date":"2020-05-18T17:16:47","date_gmt":"2020-05-18T20:16:47","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=26502"},"modified":"2020-05-18T17:16:47","modified_gmt":"2020-05-18T20:16:47","slug":"marcha-atras-a-las-salidas-y-permisos-en-localidades-de-buenos-aires-rio-negro-y-chubut","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2020\/05\/18\/marcha-atras-a-las-salidas-y-permisos-en-localidades-de-buenos-aires-rio-negro-y-chubut\/","title":{"rendered":"Marcha atr\u00e1s a las salidas y permisos en localidades de Buenos Aires, R\u00edo Negro y Chubut"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>Baradero, Castelli y Chascom\u00fas (en territorio bonaerense), Ingeniero Jacobacci (R\u00edo Negro), Gastre (Chubut) y toda la provincia de Catamarca retrotraen la flexibilizaci\u00f3n ante la aparici\u00f3n de casos en sus distritos o localidades vecinas.<\/h5>\n<p>Localidades bonaerenses como Chascom\u00fas, Baradero y Castelli, as\u00ed como otros municipios de Chubut y R\u00edo Negro resolvieron retrotraer la habilitaci\u00f3n de salidas recreativas y otras actividades tras evaluar los resultados de la flexibilizaci\u00f3n del aislamiento que hab\u00edan autorizado en d\u00edas previos.<\/p>\n<h5>Buenos Aires<\/h5>\n<p>Es el caso de Castelli, que aunque no tiene casos positivos de coronavirus, resolvi\u00f3 este lunes retrotraer la habilitaci\u00f3n de salidas recreativas para restringir la circulaci\u00f3n de personas, seg\u00fan inform\u00f3 el Comit\u00e9 de Crisis de este distrito bonaerense.<\/p>\n<p>\u00abA partir de hoy quedan suspendidas hasta nuevo aviso todas las salidas recreativas, para restringir la circulaci\u00f3n de personas\u00bb, informaron en un comunicado, tras la evaluaci\u00f3n y resultados de la apertura determinada la semana pasada.<\/p>\n<p>Si bien Castelli no registra casos positivos de coronavirus, en las \u00faltimas horas de ayer el intendente Francisco Echarren no se mostr\u00f3 conforme con el comportamiento de la comunidad, y a trav\u00e9s de las redes anticip\u00f3: \u00abVamos a retroceder con la apertura y vamos a cuidad a la ciudad\u00bb.<\/p>\n<p>\u00abHemos observado que muchos vecinos no han respetado las normas y no vamos a poner en riesgo nuestra salud en el mayor pico de circulaci\u00f3n del virus\u00bb, dijo el jefe comunal, quien agreg\u00f3 que \u00abestimamos que los pr\u00f3ximos d\u00edas son muy importantes para prevenir el ingreso del Covid-19\u00bb.<\/p>\n<p>La medida se dio a conocer poco despu\u00e9s de que el municipio vecino de Chascom\u00fas, distante a unos 60 kil\u00f3metros, informara sobre los primeros cinco casos de coronavirus en el distrito.<\/p>\n<p>\u00abEn virtud de la preocupante situaci\u00f3n que se ha presentado con la confirmaci\u00f3n en la noche de este s\u00e1bado de tres casos de coronavirus, elevando a 5 la cantidad de casos positivos y tres que esperan resultados en las pr\u00f3ximas horas, este municipio resolvi\u00f3 retrotraer en cuanto a las medidas de aperturas y suspender las caminatas saludables\u00bb, se inform\u00f3 oficialmente.<\/p>\n<p>\u00abDije hace unos d\u00edas que si era necesario se iba a volver atr\u00e1s y \u00e9ste es el momento\u00bb, asegur\u00f3 el intendente de Chascom\u00fas Javier Gast\u00f3n, tras darse a conocer el parte oficial, y llam\u00f3 a respetar el aislamiento obligatorio.<\/p>\n<p>De igual modo, el intendente de Baradero, Esteban Sanzio, tras darse a conocer el mi\u00e9rcoles en el reporte diario oficial sobre los tres primeros casos de coronavirus, inform\u00f3 que se retrotraen todas las habilitaciones decretadas: \u00abEl equipo de salud ya est\u00e1 en la b\u00fasqueda de los contactos estrechos que tuvieron las personas de Baradero que dieron positivo\u00bb, explic\u00f3 Sanzio.<\/p>\n<h5>R\u00edo Negro<\/h5>\n<p>El Ministerio de Salud provincial confirm\u00f3 el \u00faltimo s\u00e1bado que una mujer del asilo de ancianos San Jos\u00e9 y un joven de 18 a\u00f1os de Ingeniero Jacobacci son portadores del virus por lo que el intendente Carlos Toro resolvi\u00f3 suspender por una semana la actividad minera, la obra p\u00fablica y privada y limitar la actividad comercial, volviendo a la fase 1 con las medidas preventivas.<\/p>\n<p>La restricci\u00f3n implica que \u00abs\u00f3lo se permitir\u00e1 la apertura de locales comerciales que expenden alimentos y las \u00fanicas dos farmacias con las que cuenta la localidad\u00bb, se inform\u00f3, al tiempo que \u00abvuelven los controles en puntos estrat\u00e9gicos y quedan restringidas las actividades recreativas\u00bb.<\/p>\n<h5>Chubut<\/h5>\n<p>El intendente de la localidad de Gastre, Genaro P\u00e9rez, anunci\u00f3: \u00abVolvimos a fojas 0 con la cuarentena tras conocerse dos casos en la localidad de Jacobaccsi que est\u00e1 a 140 kil\u00f3metros (al norte) y ante el rumor de que uno de los afectados pas\u00f3 por nuestro pueblo\u00bb.<\/p>\n<p>Gastre es una localidad con 800 habitantes que est\u00e1 ubicada en el centro norte de la provincia del Chubut y era una de las \u00abliberadas\u00bb de cumplir con el aislamiento social, preventivo y obligatorio entre una veintena de poblaciones que no tienen restricciones de circulaci\u00f3n en el ejido, pero si controles en los accesos.<\/p>\n<p>\u00abNo podemos correr el riesgo y prefiero pecar de precavido\u00bb, dijo P\u00e9rez en di\u00e1logo con T\u00e9lam y agreg\u00f3 que, entre las medidas anunciadas, figura tambi\u00e9n \u00abel bloqueo de la ruta 13 (de ripio) que llega a nuestra localidad desde el norte y la prohibici\u00f3n estricta para que ning\u00fan cami\u00f3n proveedor ingrese desde ah\u00ed hasta que la situaci\u00f3n sanitaria quede superada\u00bb.<\/p>\n<h5>Catamarca<\/h5>\n<p>Por \u00faltimo, otra jurisdicci\u00f3n que podr\u00eda perder los permisos ganados es la provincia de Catamarca. Aunque logr\u00f3 que el coronavirus no ingresara en su territorio y eso gener\u00f3 la posibilidad de volver a practicar deportes al aire libre, desde el Comit\u00e9 Operativo de Emergencia (COE) advirtieron que \u00abhemos observado que por ah\u00ed no se han cumplido de la manera en las que se han estipulado. De todas maneras, el d\u00eda mi\u00e9rcoles lo vamos a evaluar\u00bb, dijo a la prensa el ministro de Seguridad y vocero del COE, Hern\u00e1n Martel, ante la posibilidad de volver hacia atr\u00e1s con la medida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Baradero, Castelli y Chascom\u00fas (en territorio bonaerense), Ingeniero Jacobacci (R\u00edo Negro), Gastre (Chubut) y toda la provincia de Catamarca<\/p>\n","protected":false},"author":1,"featured_media":26503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,56,44,41],"tags":[],"class_list":["post-26502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-buenos-aires","category-chubut","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2020\/05\/20200518-pcia.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/26502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=26502"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/26502\/revisions"}],"predecessor-version":[{"id":26504,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/26502\/revisions\/26504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/26503"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=26502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=26502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=26502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}