{"id":24871,"date":"2020-04-15T20:00:41","date_gmt":"2020-04-15T23:00:41","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=24871"},"modified":"2020-04-18T13:12:05","modified_gmt":"2020-04-18T16:12:05","slug":"situacion-del-coronavirus-almirante-brown","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2020\/04\/15\/situacion-del-coronavirus-almirante-brown\/","title":{"rendered":"Situaci\u00f3n del coronavirus en Almirante Brown"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>La Secretar\u00eda de Salud del Municipio de Almirante Brown inform\u00f3 que al mi\u00e9rcoles 15 de abril de 2020 se registraban 17 casos de Coronavirus notificados por las autoridades sanitarias. Mientras tanto, 196 test realizados en el distrito dieron negativos y 72 casos se encuentran en estudio. El promedio de edad de los pacientes es de 41 a\u00f1os.<\/h5>\n<p>Desde Salud de la Comuna browniana informaron tambi\u00e9n que no hay ning\u00fan paciente con Covid-19 internado en el Hospital provincial Arturo O\u00f1ativia ni tampoco en el hospital provincial Lucio Mel\u00e9ndez.<\/p>\n<p>Del total de pacientes, 5 permanecen con internaci\u00f3n domiciliaria y 11 internados en nosocomios de Almirante Brown y la Ciudad Aut\u00f3noma de Buenos Aires.<\/p>\n<p>Como se viene informando, hasta el momento falleci\u00f3 un paciente por Covid-17 en el distrito y otra paciente se encuentra con Asistencia Mec\u00e1nica Respiratoria. El resto presenta una buena evoluci\u00f3n cl\u00ednica al d\u00eda de la fecha.<\/p>\n<p>El \u00e1rea de epidemiolog\u00eda del Municipio realiza el monitoreo diario de los pacientes Covid-19 positivos con internaci\u00f3n domiciliaria, de los casos sospechosos a la espera de los resultados de laboratorio y de los contactos estrechos de los pacientes confirmados y sospechosos\u00a0con indicaci\u00f3n de cuarentena.<\/p>\n<p>Mientras tanto, el Municipio inform\u00f3 que avanza con diversas acciones para prevenir el Covid-19 como desinfecci\u00f3n de bancos, cajeros, estaciones de trenes e instituciones como centros de jubilados, realiza estrictos controles viales, inspecciona y controla precios, y verifica el cumplimiento del aislamiento social, preventivo y obligatorio.<\/p>\n<p>El Municipio tambi\u00e9n extiende los operativos para cuidar a los adultos mayores en su ingreso a las entidades bancarias y profundiza las acciones de fumigaci\u00f3n para prevenir el Dengue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La Secretar\u00eda de Salud del Municipio de Almirante Brown inform\u00f3 que al mi\u00e9rcoles 15 de abril de 2020 se<\/p>\n","protected":false},"author":1,"featured_media":24872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[33],"tags":[2519,2407],"class_list":["post-24871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown-alte-brown","tag-coronavirus-argentina","tag-covid-19"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2020\/04\/20200415-brown5.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/24871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=24871"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/24871\/revisions"}],"predecessor-version":[{"id":24873,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/24871\/revisions\/24873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/24872"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=24871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=24871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=24871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}