{"id":24415,"date":"2020-04-03T15:50:04","date_gmt":"2020-04-03T18:50:04","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=24415"},"modified":"2020-04-03T15:50:04","modified_gmt":"2020-04-03T18:50:04","slug":"mercado-libre-anuncio-desafio-donaciones-cruz-roja-banco-alimentos","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2020\/04\/03\/mercado-libre-anuncio-desafio-donaciones-cruz-roja-banco-alimentos\/","title":{"rendered":"Mercado Libre anunci\u00f3 un \u00abdesaf\u00edo de donaciones\u00bb para Cruz Roja y Banco de Alimentos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>La empresa Mercado Libre y su asociada Mercado Pago lanzaron hoy la campa\u00f1a #CodoaCodoChallenge mediante la cual la mayor empresa de valoraci\u00f3n burs\u00e1til del pa\u00eds desaf\u00eda a empresas y personas para sumar donaciones a la Cruz Roja y al Banco de Alimentos de la Argentina.<\/h5>\n<p>La compa\u00f1\u00eda inform\u00f3 que la mec\u00e1nica ser\u00e1 a trav\u00e9s de la app de Mercado Pago, en la cual cada persona podr\u00e1 elegir la organizaci\u00f3n y el monto que desea donar, y luego podr\u00e1 compartir la donaci\u00f3n a trav\u00e9s de sus redes sociales e invitar a sus contactos a sumarse bajo el hashtag #CodoACodoChallenge.<\/p>\n<p>Lo recaudado se destinar\u00e1 a Cruz Roja, para dotar a su voluntariado de kits de protecci\u00f3n personal para la evaluaci\u00f3n y asistencia sanitaria durante la emergencia por el coronavrus, y a kits de higiene y alimentos que distribuir\u00e1 la Red de Bancos de Alimentos a personas en situaci\u00f3n social vulnerable.<\/p>\n<p>La iniciativa se desarrolla de manera simult\u00e1nea en Argentina, Brasil, Colombia, M\u00e9xico, Per\u00fa y Uruguay, y las donaciones no tienen ning\u00fan costo y Mercado Pago bonifica todas las comisiones de esta acci\u00f3n.<\/p>\n<p>Para impulsar las donaciones, Mercado Libre ya don\u00f3 el equivalente a 36.750 kits a la Cruz Roja junto a 43.400 kilos de alimentos y m\u00e1s de 10.800 kits de higiene a la Red Banco de Alimentos de Argentina.<\/p>\n<p>A su vez, Mercado Libre est\u00e1 convocando a empresas para que tambi\u00e9n se sumen al desaf\u00edo aportando sus productos, servicios o dinero para hacer m\u00e1s grande el desaf\u00edo.<\/p>\n<p>Las empresas que se quieran sumar deben contactarse con codoacodo@mercadolibre.com para obtener la informaci\u00f3n y adherir.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La empresa Mercado Libre y su asociada Mercado Pago lanzaron hoy la campa\u00f1a #CodoaCodoChallenge mediante la cual la mayor<\/p>\n","protected":false},"author":1,"featured_media":24416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3],"tags":[],"class_list":["post-24415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2020\/04\/20200402-mercadolibre-00002.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/24415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=24415"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/24415\/revisions"}],"predecessor-version":[{"id":24417,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/24415\/revisions\/24417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/24416"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=24415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=24415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=24415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}