{"id":2428,"date":"2016-04-04T00:18:59","date_gmt":"2016-04-04T03:18:59","guid":{"rendered":"http:\/\/laurbedigital.com.ar\/noticias\/?p=2428"},"modified":"2016-04-04T00:18:59","modified_gmt":"2016-04-04T03:18:59","slug":"los-griegos-marchan-a-atenas-contra-el-ajuste","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2016\/04\/04\/los-griegos-marchan-a-atenas-contra-el-ajuste\/","title":{"rendered":"Los griegos marchan a Atenas contra el ajuste"},"content":{"rendered":"<p>Decenas de personas comenzaron hoy en Patras, en el norte del Peloponeso griego, una marcha a pie de ocho d\u00edas organizada por el gobierno de la ciudad que tendr\u00e1 como destino Atenas y como objetivo, pedirle para pedir que el Gobierno griego tome medidas contra el aumento del desempleo del pa\u00eds.<\/p>\n<p><span id=\"ContentPlaceHolder1_lbl_Cuerpo\">A primera hora de la ma\u00f1ana, el alcalde de Patras, Kostas Peletidis, del comunista KKE, dio el puntapi\u00e9 inicial a la marcha de 220 kil\u00f3metros, que parar\u00e1 en los pr\u00f3ximos d\u00edas en las ciudades de Egio, Akrata, Xyl\u00f3kastro, Corinto, Agii Theodori, M\u00e9gara, Elefsina y Jaidari hasta finalmente llegar a la capital griega el 10 de abril, fecha en la que est\u00e1 convocado una gran manifestaci\u00f3n en la plaza Syntagma, frente al Parlamento.<\/p>\n<p>A lo largo de esta semana y finalmente en la simb\u00f3lica plaza de Atenas, sede de infinitas protestas en la historia reciente de Grecia, los manifestantes pedir\u00e1n m\u00e1s medidas de protecci\u00f3n de los desempleados y sus familias, as\u00ed como que el gobierno de Alexis Tsipras promueva proyectos, por ejemplo de infraestructuras, para paliar \u00ablas necesidades del pueblo\u00bb, inform\u00f3 la agencia de noticias EFE.<\/p>\n<p>En cada una de estas localidades donde se detendr\u00e1 la comitiva est\u00e1n programados actos de concienciaci\u00f3n como reuniones, conciertos, protestas y eventos culturales.<\/p>\n<p>Peletidis dijo a los medios locales que esta marcha es \u00abun mensaje de esperanza a los ciudadanos que se han convertido en espectadores de unos pol\u00edticos que les consideran ovejas dispuestas a sacrificarse sin decir una palabra\u00bb,<\/p>\n<p>\u00abEs hora de escuchar la voz de los desempleados, la voz de los trabajadores, de los pensionistas y de los j\u00f3venes\u00bb, concluy\u00f3 Peletidis.<\/p>\n<p>El 25 de enero de 2015, despu\u00e9s de cinco a\u00f1os de ajuste implacable, Grecia eligi\u00f3 por mayor\u00eda un gobierno encabezado por la coalici\u00f3n de izquierdas Syriza y su propuesta antiajuste contra el monitoreo externo de la econom\u00eda.<\/p>\n<p>Syriza inici\u00f3 inmediatamente unas negociaciones con sus acreedores, representados por la \u00abTroika\u00bb formada por el FMI, el Banco Central Europeo (BCE) y la Comisi\u00f3n Europea (CE), pero la presi\u00f3n de la Uni\u00f3n Europea fue demasiado fuerte y Tsipras termin\u00f3 aceptando un nuevo acuerdo de ajuste y medidas de austeridad.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decenas de personas comenzaron hoy en Patras, en el norte del Peloponeso griego, una marcha a pie de ocho d\u00edas<\/p>\n","protected":false},"author":1,"featured_media":2429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-2428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2016\/04\/20160403-mundo.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/2428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=2428"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/2428\/revisions"}],"predecessor-version":[{"id":2430,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/2428\/revisions\/2430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/2429"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=2428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=2428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=2428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}