{"id":2396,"date":"2016-04-01T21:16:46","date_gmt":"2016-04-02T00:16:46","guid":{"rendered":"http:\/\/laurbedigital.com.ar\/noticias\/?p=2396"},"modified":"2016-04-01T21:16:46","modified_gmt":"2016-04-02T00:16:46","slug":"disney-prepara-cinta-sobre-rosa-roja-la-hermana-de-blancanieves","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2016\/04\/01\/disney-prepara-cinta-sobre-rosa-roja-la-hermana-de-blancanieves\/","title":{"rendered":"Disney prepara cinta sobre Rosa Roja, la hermana de Blancanieves"},"content":{"rendered":"<p>Disney prepara una pel\u00edcula centrada en el personaje de Rosa Roja, la hermana de Blancanieves, basada en una idea del guionista Evan Daugherty, responsable de los dos \u00faltimos largometrajes inspirados en el cuento cl\u00e1sico recopilado por los hermanos Grimm.<\/p>\n<p>Rosa Roja es un personaje que aparece en uno de los cuentos versionados por los Grimm, aunque no en el m\u00e1s conocido, que es \u00abBlancanieves y los siete enanitos\u00bb, seg\u00fan precisa en su web The Hollywood Reporter.<\/p>\n<p>Disney ha seleccionado ya el proyecto, idea de Daugherty, que ya trabaja en una nueva versi\u00f3n del primer gui\u00f3n realizado por Justin Merz.<\/p>\n<p>Daugherty quiere acercar la pel\u00edcula a la historia m\u00e1s conocida de Blancanieves, haciendo que Rosa Roja juegue un papel clave en averiguar c\u00f3mo devolver a la vida a su hermana despu\u00e9s de que \u00e9sta muerda la manzana envenenada.<\/p>\n<p>Ser\u00e1 la tercera ocasi\u00f3n en que Daugherty se acerque al personaje de Blancanieves tras realizar el gui\u00f3n de \u00abSnow White and the Huntsman\u00bb (\u00abBlancanieves y la leyenda del cazador\u00bb, 2012) y colaborar en el de \u00abThe Huntsman: Winter&#8217;s War\u00bb (\u00abLas cr\u00f3nicas de Blancanieves: El cazador y la reina del hielo\u00bb, 2016), que se estrena la pr\u00f3xima semana.<br \/>\nCon este proyecto, Disney contin\u00faa en su l\u00ednea de hacer nuevas versiones de sus grandes cl\u00e1sicos o pel\u00edculas derivadas de ellas.<\/p>\n<p>Antes de embarcarse en las historias de Blancanieves, en 2010 estren\u00f3 \u00abAlice in Wonderlan\u00bb (\u00abAlicia en el pa\u00eds de las maravillas\u00bb, 2010), una modernizaci\u00f3n del cl\u00e1sico, que ya tiene a punto de estrenar una secuela, \u00abAlice Through the Looking Glass\u00bb (\u00abAlicia a trav\u00e9s del espejo\u00bb, 2016).<\/p>\n<p>\u00abOz the Great and Powerful\u00bb (\u00abOz, un mundo de fantas\u00eda\u00bb) fue la nueva versi\u00f3n de la historia de \u00abThe Wizard of Oz\u00bb (\u00abEl mago de Oz\u00bb, 1936), estrenada en 2013.<\/p>\n<p>En dos semanas llegar\u00e1 a las pantallas \u00abThe Jungle Book\u00bb (\u00abEl libro de la selva\u00bb) , inspirada en uno de sus grandes cl\u00e1sicos animados, y tiene en preparaci\u00f3n \u00abGenies\u00bb, una precuela de \u00abAladdin\u00bb (1992).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disney prepara una pel\u00edcula centrada en el personaje de Rosa Roja, la hermana de Blancanieves, basada en una idea del<\/p>\n","protected":false},"author":1,"featured_media":2397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[30,5],"tags":[],"class_list":["post-2396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine","category-cultura"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2016\/04\/20160401-cine.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/2396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=2396"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/2396\/revisions"}],"predecessor-version":[{"id":2398,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/2396\/revisions\/2398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/2397"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=2396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=2396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=2396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}