{"id":23932,"date":"2020-03-20T15:40:35","date_gmt":"2020-03-20T18:40:35","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=23932"},"modified":"2020-03-20T15:40:35","modified_gmt":"2020-03-20T18:40:35","slug":"la-hermana-la-joven-asesinada-monte-grande-reconoce-detenido-autor-del-disparo","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2020\/03\/20\/la-hermana-la-joven-asesinada-monte-grande-reconoce-detenido-autor-del-disparo\/","title":{"rendered":"La hermana de la joven asesinada en Monte Grande reconoce a un detenido como autor del disparo"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h5>La hermana de Zoe Nerea Cortez, la joven de 18 a\u00f1os que fue asesinada de un tiro en la localidad bonaerense de Monte Grande, reconoci\u00f3 hoy a uno de los detenidos como el autor material del crimen, informaron fuentes judiciales.<\/h5>\n<p>La rueda de reconocimiento fue realizada esta ma\u00f1ana en la fiscal\u00eda descentralizada de Esteben Echeverr\u00eda que dirige el fiscal de la causa, Andr\u00e9s Devoto, a trav\u00e9s de la exhibici\u00f3n de fotograf\u00edas, ya que por el aislamiento general obligatorio decretado por el coronavirus, est\u00e1 suspendido el traslado de detenidos.<\/p>\n<p>Por las mismas restricciones, la hermana de la v\u00edctima, de 16 a\u00f1os y testigo clave del hecho, concurri\u00f3 a diligencia con un certificado emitido por la fiscal\u00eda.<\/p>\n<p>Seg\u00fan las fuentes consultadas, la adolescente de 16 a\u00f1os reconoci\u00f3 entre las fotos al detenido Cristian Maximiliano Cipolloni (18), alias \u201cEl Cabeza\u201d, como el delincuente que efectu\u00f3 el disparo que asesin\u00f3 a su hermana desde un auto en movimiento.<\/p>\n<p>\u201cLa chica pudo verle la cara porque el tirador ven\u00eda en el asiento trasero del auto, del lado izquierdo, con la ventanilla baja\u201d, explic\u00f3 a T\u00e9lam uno de los investigadores.<\/p>\n<p>Por el caso, hay otros dos detenidos, Agust\u00edn Gelman (19), alias \u201cEl Chuleta\u201d, y Nahuel Ezequiel Lescano (21), alias \u201cEl Tucumano\u201d, un joven que estaba parado al lado del auto usado en el crimen, un Renault Symbol, patente LSW310, cuando a pocos minutos del homicidio, el veh\u00edculo fue hallado abandonado en las calles Los Tulipanes y Alfonso Amat de Monte Grande.<\/p>\n<p>La causa adem\u00e1s tiene pr\u00f3fugo a otro joven identificado como Walter Para, alias \u201cEl Aguja\u201d.<\/p>\n<p>La clave para esclarecer el caso fue el robo del Renault Symbol a un chofer de Uber el domingo 8 de marzo, un d\u00eda antes del homicidio de Zoe.<\/p>\n<p>Siempre seg\u00fan los voceros, en su investigaci\u00f3n, el fiscal Devoto pudo determinar que \u201cEl Chuleta\u201d, \u201cEl Cabeza\u201d y el pr\u00f3fugo \u201cEl Aguja\u201d, se subieron al Symbol como pasajeros, para luego robarle a mano armado el veh\u00edculo al chofer en Adrogu\u00e9.<\/p>\n<p>La banda ten\u00eda como modalidad hacerse pedir el Uber desde el tel\u00e9fono celular de un inocente, y en este caso, fue una chica de 18 a\u00f1os que fue interrogada por el fiscal, colabor\u00f3, aport\u00f3 datos y no qued\u00f3 vinculada a la causa.<\/p>\n<p>La principal hip\u00f3tesis del fiscal Devoto es que con el auto robado 24 horas antes, esta misma banda quiso asaltar a Zoe, su hermana de 16 a\u00f1os y el amigo que las acompa\u00f1aba, y cuando el delincuente armado quiso bajar del auto, se le escap\u00f3 el tiro que le dio en la cabeza a la joven.<\/p>\n<p>El hecho ocurri\u00f3 alrededor de las 22.50 del 9 de marzo, en el cruce de las calles Crist\u00f3bal Col\u00f3n y Tinogasta, de Monte Grande, cuando las dos hermanas, acompa\u00f1adas por un amigo, salieron de un gimnasio de la zona rumbo a su casa, ubicada en Olavarr\u00eda al 700, a unas siete cuadras de donde se registr\u00f3 el crimen.<\/p>\n<p>Toda la secuencia qued\u00f3 registrada por c\u00e1maras de seguridad y en los videos se observa que cuando los tres caminaban por la vereda de Col\u00f3n al 2500, un autom\u00f3vil Renault Symbol que ven\u00eda circulando por la calle detuvo su marcha, se abri\u00f3 la puerta trasera y, sin mediar palabra, una persona dispar\u00f3 un balazo que impact\u00f3 en la cabeza de Cortez, quien muri\u00f3 en el lugar.<\/p>\n<p>La autopsia confirm\u00f3 que la chica muri\u00f3 de ese \u00fanico disparo que entr\u00f3 por la regi\u00f3n temporal derecha, qued\u00f3 alojado en el cr\u00e1neo y se corresponde con un plomo calibre 32 o 38.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; La hermana de Zoe Nerea Cortez, la joven de 18 a\u00f1os que fue asesinada de un tiro en la<\/p>\n","protected":false},"author":1,"featured_media":23933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[2454],"class_list":["post-23932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-zoe-nerea-cortez"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2020\/03\/20200320-policiales-2-00004.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/23932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=23932"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/23932\/revisions"}],"predecessor-version":[{"id":23934,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/23932\/revisions\/23934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/23933"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=23932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=23932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=23932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}