{"id":19671,"date":"2019-10-28T17:17:59","date_gmt":"2019-10-28T20:17:59","guid":{"rendered":"http:\/\/laurbedigital.com.ar\/noticias\/?p=19671"},"modified":"2019-10-28T17:17:59","modified_gmt":"2019-10-28T20:17:59","slug":"la-nueva-pelicula-asterix-galo-se-conocera-ano-viene","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2019\/10\/28\/la-nueva-pelicula-asterix-galo-se-conocera-ano-viene\/","title":{"rendered":"La nueva pel\u00edcula de Ast\u00e9rix el Galo se conocer\u00e1 el a\u00f1o que viene"},"content":{"rendered":"<p>La sexta pel\u00edcula sobre Ast\u00e9rix el Galo, personaje creado por los franceses Ren\u00e9 Goscinny y Albert Uderzo en 1959 y considerado el m\u00e1s popular en su tipo en Francia, llevar\u00e1 a los irreductibles guerreros hasta la China, un pa\u00eds desconocido por ellos hasta el momento, revel\u00f3 este lunes la agencia Efe.<\/p>\n<p>El casting todav\u00eda no fue confirmado, aunque tras anunciarse el rodaje, el propio Canet public\u00f3 en su perfil de Instagram una foto de \u00e9l y el tambi\u00e9n actor Gilles Lellouche, caracterizados como Ast\u00e9rix y Ob\u00e9lix.<\/p>\n<p>Los personajes del nuevo cap\u00edtulo, \u00abAst\u00e9rix y Ob\u00e9lix, el reino medio\u00bb, cuyo rodaje comenzar\u00e1 en la primavera boreal de 2020, a cargo de Guillaume Canet, estar\u00e1n inspirados en los h\u00e9roes de la saga, pero el gui\u00f3n no saldr\u00e1 de uno de sus c\u00f3mics.<\/p>\n<p>Los guionistas ser\u00e1n los franceses Philippe Mechelen y Julien Herv\u00e9, mientras Canet se ocupar\u00e1 de la adaptaci\u00f3n y los di\u00e1logos.<\/p>\n<p>Desde su creaci\u00f3n, las aventuras de Ast\u00e9rix y Ob\u00e9lix han sido traducidas a un centenar de idiomas y son objeto de un nuevo c\u00f3mic cada dos a\u00f1os; el \u00faltimo filme de los h\u00e9roes, \u00abAst\u00e9rix y Ob\u00e9lix: Al servicio de su majestad\u00bb, se estren\u00f3 en 2012 y vendi\u00f3 3,8 millones de entradas en Francia, aunque en la Argentina solo se conoci\u00f3 por su edici\u00f3n en DVD.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sexta pel\u00edcula sobre Ast\u00e9rix el Galo, personaje creado por los franceses Ren\u00e9 Goscinny y Albert Uderzo en 1959 y<\/p>\n","protected":false},"author":1,"featured_media":19673,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[68],"tags":[],"class_list":["post-19671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-y-series"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2019\/10\/20191028-cine-28-3-03333.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/19671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=19671"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/19671\/revisions"}],"predecessor-version":[{"id":19676,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/19671\/revisions\/19676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/19673"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=19671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=19671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=19671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}