{"id":1890,"date":"2016-03-15T00:36:00","date_gmt":"2016-03-15T03:36:00","guid":{"rendered":"http:\/\/laurbedigital.com.ar\/noticias\/?p=1890"},"modified":"2016-03-15T00:36:00","modified_gmt":"2016-03-15T03:36:00","slug":"eva-no-duerme-se-llevo-el-premio-balance-2016-de-pantalla-pinamar","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2016\/03\/15\/eva-no-duerme-se-llevo-el-premio-balance-2016-de-pantalla-pinamar\/","title":{"rendered":"\u201cEva no duerme\u201d se llev\u00f3 el premio Balance 2016 de Pantalla Pinamar"},"content":{"rendered":"<p>Como todos los a\u00f1os, la cr\u00edtica especializada premia a la mejor pel\u00edcula del a\u00f1o anterior, entre aquellas que compitieron en los festivales clase A. En la 12\u00ba edici\u00f3n de Pantalla Pinamar, el premio Balance 2016, se lo llev\u00f3 el film de Pablo Ag\u00fcero, \u201cEva no duerme\u201d.<\/p>\n<p>La pel\u00edcula de Pablo Ag\u00fcero hab\u00eda sido una de las m\u00e1s aplaudidas por el p\u00fablico en el Festival de Mar del Plata y vuelve a sorprender en Pantalla Pinamar 2016, llev\u00e1ndose el mayor galard\u00f3n de la noche. Eva no duerme, se vasa en la propia investigaci\u00f3n del director para reconstruir la historia real de los viajes que ha ido haciendo el cuerpo de Eva Per\u00f3n, en su desaparici\u00f3n durante diecisiete a\u00f1os. El film, que conmocion\u00f3 a la audiencia por el relato de los hechos aporta una visi\u00f3n controvertida, llevada a la ficci\u00f3n muy cuidada desde lo est\u00e9tico.<\/p>\n<p>Con actuaciones de Gael Garc\u00eda Bernal, Denise Lavant, Imanol Arias y Daniel Fanego, la pel\u00edcula hab\u00eda sido estrenada en noviembre sin grandes resultados. Sin embargo el voto del p\u00fablico y de la cr\u00edtica le dio la posibilidad de levantar cabeza y convertirse en la protagonista del encuentro argentino-europeo que desde hace ya 12 a\u00f1os convierte a Pinamar en el atractivo m\u00e1s importante de Buenos Aires.<\/p>\n<p>Con la sala del cine Oasis 1 repleta de personalidades y cr\u00edticos del pa\u00eds, el \u00a0premio balance de plata, fue para \u201cEl Clan\u201d, de Pablo Trapero y el de bronce para \u201cGuaran\u00ed\u201d de Luis Zorraqu\u00edn que tambi\u00e9n se llev\u00f3 el premio SIGNIS. Adem\u00e1s se anunci\u00f3 durante el festival que las salas llegaron al 95.5 por ciento de ocupaci\u00f3n, y que la pr\u00f3xima edici\u00f3n del mismo, ya tiene fecha de realizaci\u00f3n desde el 11 hasta el 18 de marzo y que espera algunas sorpresas.<\/p>\n<p>Para terminar la edici\u00f3n del festival se proyecto el pre estreno de la pel\u00edcula espa\u00f1ola \u201cOcho apellidos Catalanes\u201d, de Emilio Mart\u00ednez L\u00e1zaro. Eva no duerme, se qued\u00f3 adem\u00e1s con los premios EGEDA, INCAATV, el premio Argentores y el premio Cinecolor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como todos los a\u00f1os, la cr\u00edtica especializada premia a la mejor pel\u00edcula del a\u00f1o anterior, entre aquellas que compitieron en<\/p>\n","protected":false},"author":1,"featured_media":1891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[30,5],"tags":[],"class_list":["post-1890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine","category-cultura"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2016\/03\/20160314-cine.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/1890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=1890"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/1890\/revisions"}],"predecessor-version":[{"id":1892,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/1890\/revisions\/1892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/1891"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=1890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=1890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=1890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}