{"id":125592,"date":"2026-03-28T14:03:36","date_gmt":"2026-03-28T17:03:36","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=125592"},"modified":"2026-03-28T14:03:36","modified_gmt":"2026-03-28T17:03:36","slug":"descubrieron-un-mural-conmemorativo-por-el-50-aniversario-de-la-dictadura-en-el-hcd-browniano","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2026\/03\/28\/descubrieron-un-mural-conmemorativo-por-el-50-aniversario-de-la-dictadura-en-el-hcd-browniano\/","title":{"rendered":"Descubrieron un mural conmemorativo por el 50\u00b0 aniversario de la dictadura en el Hcd Browniano"},"content":{"rendered":"<p>La actividad se realiz\u00f3 en el edificio situado en la calle Pellerano al 700 y fue encabezada por el intendente interino Juan Fabiani; el presidente del Concejo Deliberante, Nicol\u00e1s Jawtuschenko; y la Jefa de Gabinete Paula Eichel, en el marco de la 236\u00b0 sesi\u00f3n especial.<\/p>\n<p>El cuarto Mural Cer\u00e1mico Conmemorativo se present\u00f3 con el objetivo de recordar y reflexionar sobre el golpe de Estado de 1976, promoviendo los valores de Memoria, Verdad y Justicia y reafirmando el compromiso con los derechos humanos y la construcci\u00f3n de la memoria colectiva.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-125596\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/20220328-brown-placa-50-golpe-militar.png\" alt=\"\" width=\"768\" height=\"428\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/20220328-brown-placa-50-golpe-militar.png 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/20220328-brown-placa-50-golpe-militar-300x167.png 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<h5><strong><em>\u201cA 50 a\u00f1os del golpe c\u00edvico-militar, este mural nos invita a mantener viva la memoria colectiva y a reafirmar nuestro compromiso con la democracia, los derechos humanos y los valores de Memoria, Verdad y Justicia\u201d, sostuvo al respecto Mariano Cascallares.<\/em><\/strong><\/h5>\n<p>Tambi\u00e9n participaron la secretaria de Desarrollo, Seguridad Social y Derechos Humanos, B\u00e1rbara Mi\u00f1\u00e1n; el presidente del Instituto Municipal de las Culturas, Juan Manuel Pereyra Benitez; junto a ediles del Partido Justicialista en el mencionado cuerpo deliberativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad se realiz\u00f3 en el edificio situado en la calle Pellerano al 700 y fue encabezada por el intendente<\/p>\n","protected":false},"author":1,"featured_media":125593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El Municipio de Almirante Brown llev\u00f3 adelante el descubrimiento de un mural cer\u00e1mico conmemorativo por el 50\u00b0 aniversario de la \u00faltima dictadura c\u00edvico-militar en el Honorable Concejo Deliberante browniano.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[2,33],"tags":[],"class_list":["post-125592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown","category-alte-brown-alte-brown"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2026\/03\/20220328-brown-placa.png","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/125592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=125592"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/125592\/revisions"}],"predecessor-version":[{"id":125598,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/125592\/revisions\/125598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/125593"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=125592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=125592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=125592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}