{"id":121869,"date":"2025-11-27T02:35:56","date_gmt":"2025-11-27T05:35:56","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=121869"},"modified":"2025-11-27T02:35:56","modified_gmt":"2025-11-27T05:35:56","slug":"el-gobierno-apuesta-a-la-recesion-subio-la-tasa-para-secar-de-pesos-la-economia","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/11\/27\/el-gobierno-apuesta-a-la-recesion-subio-la-tasa-para-secar-de-pesos-la-economia\/","title":{"rendered":"El Gobierno apuesta a la recesi\u00f3n: subi\u00f3 la tasa para secar de pesos la econom\u00eda"},"content":{"rendered":"<p data-path-to-node=\"4\">En una jugada que reafirma la primac\u00eda de la pol\u00edtica antiinflacionaria sobre el impulso econ\u00f3mico, el Gobierno decidi\u00f3 apostar a mantener el freno sobre la actividad a trav\u00e9s de la absorci\u00f3n de liquidez. \u00bfCu\u00e1l fue el mecanismo utilizado? Una cr\u00edtica renovaci\u00f3n de deuda del Tesoro que logr\u00f3 captar 13,99 billones de pesos sobre vencimientos estimados en 14,5 billones, renovando m\u00e1s del 95% del total. Esta decisi\u00f3n, que implic\u00f3 subir la tasa de inter\u00e9s de referencia, frustr\u00f3 las expectativas del mercado que aguardaba una liberaci\u00f3n de hasta 2 billones de pesos para movilizar el cr\u00e9dito. La presi\u00f3n sobre el d\u00f3lar y el repunte de la inflaci\u00f3n se impusieron, reforzando la estrategia de la <b>recesi\u00f3n como ancla monetaria<\/b>.<\/p>\n<h4>El cerrojo de la liquidez: absorci\u00f3n r\u00e9cord de pesos<\/h4>\n<p data-path-to-node=\"6\">La operaci\u00f3n de renovaci\u00f3n de deuda del Tesoro fue el principal indicador de la pol\u00edtica monetaria. El mercado especulaba con una estrategia m\u00e1s laxa que permitiera inyectar liquidez y, por ende, \u201ccombustible\u201d a una econom\u00eda que se mantiene en estado de anemia, a pesar de las revisiones del INDEC. Sin embargo, se impuso la cautela extrema.<\/p>\n<p data-path-to-node=\"7\">La decisi\u00f3n de absorber la mayor cantidad posible de pesos, captando la casi totalidad de las ofertas (que ascendieron a 14,69 billones de pesos), est\u00e1 directamente asociada a la renovada presi\u00f3n sobre el d\u00f3lar.<\/p>\n<p data-path-to-node=\"8\"><b>Datos clave de la operaci\u00f3n:<\/b><\/p>\n<ul data-path-to-node=\"9\">\n<li>\n<p data-path-to-node=\"9,0,0\"><b>Renovaci\u00f3n:<\/b> 13,99 billones de pesos captados (m\u00e1s del 95%).<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"9,1,0\"><b>Margen Financiero:<\/b> El Tesoro acumul\u00f3 un excedente financiero de m\u00e1s de 6 billones de pesos en el mes, colocando deuda por 23 billones sobre vencimientos de 16 billones.<\/p>\n<\/li>\n<\/ul>\n<p data-path-to-node=\"10\">Este margen se obtiene, sin embargo, a un alto costo: el sostenimiento de tasas de inter\u00e9s elevadas y una baja monetizaci\u00f3n de la econom\u00eda, lo que garantiza el freno a la inversi\u00f3n y el consumo.<\/p>\n<h5>El costo de la renovaci\u00f3n: suba de la tasa y concentraci\u00f3n de plazos<\/h5>\n<p data-path-to-node=\"12\">Para poder renovar la casi totalidad de la deuda, el Gobierno tuvo que aceptar subir un escal\u00f3n las tasas de inter\u00e9s respecto al mercado secundario. La mayor colocaci\u00f3n se concentr\u00f3 en el plazo m\u00e1s corto, con 5 billones de pesos al 13 de febrero, y el rendimiento se elev\u00f3 del 2,41% de Tasa Efectiva Mensual (TEM) al 2,69% de TEM.<\/p>\n<p data-path-to-node=\"13\">Los otros instrumentos colocados mayormente al 30 de abril incluyeron bonos ajustables por la Tasa de Plazos Fijos Mayoristas (TAMAR) m\u00e1s un <i>spread<\/i> del 4%, y Letras Capitalizables (Lecap) con una TEM del 2,54%, adem\u00e1s de una porci\u00f3n en <i>Dollar Link<\/i> (que actualiza por el d\u00f3lar oficial).<\/p>\n<p data-path-to-node=\"14\">El Banco Central (BCRA) debi\u00f3 armar toda la ingenier\u00eda legal necesaria para que los bancos renueven su tenencia de t\u00edtulos p\u00fablicos, blindando la operaci\u00f3n para evitar un colapso monetario. La presi\u00f3n cambiaria reciente, que vio el d\u00f3lar mayorista subir por quinta jornada consecutiva, y las expectativas inflacionarias reforzaron la necesidad del equipo econ\u00f3mico de mantener el <b>ancla monetaria<\/b> como pol\u00edtica dominante.<\/p>\n<h2>El d\u00f3lar como term\u00f3metro y la presi\u00f3n cambiaria<\/h2>\n<p data-path-to-node=\"16\">La persistente expectativa de un cambio de r\u00e9gimen, que incluir\u00eda una eventual devaluaci\u00f3n, ha impedido que el precio del d\u00f3lar actuara como ancla antiinflacionaria. La alta demanda en el mercado de cambios, que se hab\u00eda manifestado intensamente antes de las elecciones de octubre, volvi\u00f3 a resurgir en los \u00faltimos cinco d\u00edas, ejerciendo una presi\u00f3n significativa a pesar de la liquidaci\u00f3n de divisas proveniente de la deuda privada.<\/p>\n<h5>Deuda privada: la fuente inesperada de d\u00f3lares<\/h5>\n<p data-path-to-node=\"18\">Mientras el Gobierno mantiene cerrado el mercado de deuda voluntaria en divisas, con un Riesgo Pa\u00eds en la zona de 650 puntos, se observa un fen\u00f3meno paralelo: la colocaci\u00f3n r\u00e9cord de Obligaciones Negociables (ON) y t\u00edtulos de deuda por parte de empresas y el Gobierno de la Ciudad Aut\u00f3noma de Buenos Aires (CABA).<\/p>\n<ul data-path-to-node=\"19\">\n<li>\n<p data-path-to-node=\"19,0,0\"><b>Volumen:<\/b> En las \u00faltimas seis semanas, se colocaron m\u00e1s de 2.900 millones de d\u00f3lares en los mercados internacionales.<\/p>\n<\/li>\n<li>\n<p data-path-to-node=\"19,1,0\"><b>Efecto:<\/b> Estos d\u00f3lares son volcados al mercado oficial de cambios, lo que incrementa los dep\u00f3sitos del sector privado y engrosa temporalmente las reservas brutas del BCRA (ya que figuran como encajes). Al 20 de noviembre, los dep\u00f3sitos en d\u00f3lares del sector privado alcanzaron un r\u00e9cord de $35.540 millones, con una suba de $430 millones en el mes.<\/p>\n<\/li>\n<\/ul>\n<p data-path-to-node=\"20\">Este flujo de d\u00f3lares privados, con empresas como Genneia y CGC planeando nuevas colocaciones de hasta 500 millones de d\u00f3lares cada una, y la provincia de Santa Fe buscando hasta 1.000 millones, podr\u00eda superar los 5.200 millones de d\u00f3lares en el trimestre.<\/p>\n<p data-path-to-node=\"21\">Como advierte GMA Capital, este panorama de liquidez y apetito inversor plantea una pregunta crucial: \u00bfes esta liquidez una oportunidad para que el Gobierno nacional regrese al mercado voluntario de deuda? Por ahora, la cautela oficial y la falta de capacidad de acumulaci\u00f3n genuina de reservas mantienen esa puerta cerrada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una jugada que reafirma la primac\u00eda de la pol\u00edtica antiinflacionaria sobre el impulso econ\u00f3mico, el Gobierno decidi\u00f3 apostar a<\/p>\n","protected":false},"author":1,"featured_media":121847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El Tesoro renov\u00f3 m\u00e1s del 95% de su deuda, reteniendo liquidez por temor a la presi\u00f3n cambiaria y la inflaci\u00f3n. La suba de la tasa al 2,69% TEM confirma que el Ejecutivo prioriza el ancla monetaria y la recesi\u00f3n frente al est\u00edmulo del cr\u00e9dito y la actividad.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,41],"tags":[],"class_list":["post-121869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/20251127-Milei-Libra-Caputo.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=121869"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121869\/revisions"}],"predecessor-version":[{"id":121870,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121869\/revisions\/121870"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/121847"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=121869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=121869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=121869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}