{"id":121615,"date":"2025-11-18T12:24:29","date_gmt":"2025-11-18T15:24:29","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=121615"},"modified":"2025-11-18T12:25:08","modified_gmt":"2025-11-18T15:25:08","slug":"cascallares-superviso-los-trabajos-realizados-en-la-renovada-plaza-santa-ana-de-glew","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/11\/18\/cascallares-superviso-los-trabajos-realizados-en-la-renovada-plaza-santa-ana-de-glew\/","title":{"rendered":"Cascallares supervis\u00f3 los trabajos realizados en la renovada Plaza Santa Ana de Glew"},"content":{"rendered":"<div dir=\"ltr\">\n<div>\n<p>En ese marco el intendente Mariano Cascallares, acompa\u00f1ado por vecinos de la zona, recorri\u00f3 los trabajos realizados en la plaza ubicada en Mazzini entre Tap\u00edn y Presidente Quintana. Las obras incluyeron tareas de parquizaci\u00f3n, renovaci\u00f3n de veredas, instalaci\u00f3n de luminarias LED, construcci\u00f3n de un play\u00f3n deportivo, juegos inclusivos, equipamiento de hormig\u00f3n (mesas y bancos), forestaci\u00f3n, instalaci\u00f3n de cestos de basura y la colocaci\u00f3n de carteler\u00eda.<\/p>\n<p>Durante la jornada tambi\u00e9n se llev\u00f3 a cabo un operativo de salud que incluy\u00f3 vacunaci\u00f3n del Calendario Nacional tanto para ni\u00f1os como para adultos. Adem\u00e1s, Zoonosis Brown brind\u00f3 los servicios de castraci\u00f3n y vacunaci\u00f3n para perros y gatos.<\/p>\n<p>Por otro lado, el Jard\u00edn N\u00b0 964 de Glew present\u00f3 al Honorable Concejo Deliberante un proyecto para la designaci\u00f3n oficial del nombre de la plaza. Como resultado, el espacio fue bautizado como \u00abEsta plaza es de todos.<\/p>\n<h5><strong><em>\u201cSeguimos avanzando con distintas obras en todo el distrito. Aqu\u00ed, en Glew, adem\u00e1s de la plaza, inauguramos recientemente el Jard\u00edn de Infantes N\u00b0 964, en el barrio Santa Ana. Tambi\u00e9n construimos la Casa Activa, un centro destinado a actividades para la tercera edad. Adem\u00e1s, estamos proyectando una nueva Plaza-Parque cerca de esta zona. Son obras que mejoran la calidad de vida de nuestros vecinos\u201d, destac\u00f3 el intendente Mariano Cascallares.<\/em><\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-121617 size-full\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/20251118-Brown-Cascallares-Plaza-Santa-Ana-Glew-1.jpg\" alt=\"Plaza Santa Ana de Glew\" width=\"768\" height=\"456\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/20251118-Brown-Cascallares-Plaza-Santa-Ana-Glew-1.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/20251118-Brown-Cascallares-Plaza-Santa-Ana-Glew-1-300x178.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Cabe destacar que el proyecto original se inici\u00f3 en 2023. Sin embargo en diciembre de 2024 la paralizaci\u00f3n de obras por parte del gobierno nacional interrumpi\u00f3 los trabajos. Ante esta situaci\u00f3n, la Comuna decidi\u00f3 reactivar y finalizar la obra utilizando fondos municipales para que vecinos y familias puedan disfrutar de este renovado espacio recreativo.<\/p>\n<div>Del recorrido tambi\u00e9n participaron el secretario de Gesti\u00f3n Descentralizada, Atilio Gari; la subsecretaria de la Agencia de Gesti\u00f3n Urbana, Carla Ortwein; el delegado municipal de Glew, Guillermo Antoniani, y numerosos vecinos del barrio.<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En ese marco el intendente Mariano Cascallares, acompa\u00f1ado por vecinos de la zona, recorri\u00f3 los trabajos realizados en la plaza<\/p>\n","protected":false},"author":1,"featured_media":121616,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El Municipio de Almirante Brown llev\u00f3 adelante la renovaci\u00f3n integral de la Plaza del barrio Santa Ana en Glew, un importante espacio p\u00fablico que ha sido completamente remodelado sumando equipamiendo, parquizaci\u00f3n y forestaci\u00f3n.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,33,50],"tags":[],"class_list":["post-121615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown","category-alte-brown-alte-brown","category-glew"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/20251118-Brown-Cascallares-Plaza-Santa-Ana-Glew.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=121615"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121615\/revisions"}],"predecessor-version":[{"id":121619,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121615\/revisions\/121619"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/121616"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=121615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=121615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=121615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}