{"id":121352,"date":"2025-11-08T18:30:53","date_gmt":"2025-11-08T21:30:53","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=121352"},"modified":"2025-11-08T18:30:53","modified_gmt":"2025-11-08T21:30:53","slug":"cheques-rechazados-record-la-tension-de-la-cadena-de-pagos-y-el-agobio-de-la-deuda-familiar","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/11\/08\/cheques-rechazados-record-la-tension-de-la-cadena-de-pagos-y-el-agobio-de-la-deuda-familiar\/","title":{"rendered":"Cheques rechazados r\u00e9cord: La tensi\u00f3n de la cadena de pagos y el agobio de la deuda familiar"},"content":{"rendered":"<h4>La morosidad como term\u00f3metro de la crisis econ\u00f3mica<\/h4>\n<p>\u00bf<b>Qu\u00e9<\/b> est\u00e1 pasando en la cadena de pagos argentina? El <b>r\u00e9cord de cheques rechazados<\/b> (<span class=\"math-inline\" data-math=\"5W\">$5W$<\/span>) por insuficiencia de fondos durante <b>septiembre<\/b> (<span class=\"math-inline\" data-math=\"5W\">$5W$<\/span>) de este a\u00f1o, que alcanz\u00f3 la cifra de <b>92.535<\/b> (<span class=\"math-inline\" data-math=\"5W\">$5W$<\/span>), se ha convertido en una se\u00f1al de alarma ineludible sobre el deterioro de la salud financiera de hogares y empresas. Este dato, analizado por el <b>Instituto Argentina Grande<\/b> (<span class=\"math-inline\" data-math=\"5W\">$5W$<\/span>) a partir de informaci\u00f3n oficial del <b>Banco Central de la Rep\u00fablica Argentina (BCRA)<\/b>, evidencia la creciente dificultad de los argentinos para afrontar sus obligaciones, siendo el registro m\u00e1s alto desde junio de 2020 (<span class=\"math-inline\" data-math=\"H\">$H$<\/span>).<\/p>\n<p>El fen\u00f3meno de los cheques rebotados no es un hecho aislado, sino que forma parte de un panorama de <b>endeudamiento familiar<\/b> que, seg\u00fan la consultora EcoGo, ya cubre el <b>130% de los ingresos promedio<\/b> de una persona. Esta situaci\u00f3n de tensi\u00f3n en la cadena de pagos tiene un impacto directo y severo en los cimientos de la econom\u00eda, afectando el d\u00eda a d\u00eda de trabajadores, trabajadoras y empresarios por igual.<\/p>\n<h4>Deterioro del cr\u00e9dito: tarjetas y pr\u00e9stamos en riesgo<\/h4>\n<p>El aumento en los cheques rechazados se complementa con el incremento de la morosidad en el sistema financiero. El \u00faltimo Informe sobre Bancos del BCRA detalla que el nivel de mora general en los pr\u00e9stamos se ubic\u00f3 en <b>3,7%<\/b>. Al enfocarse en los pr\u00e9stamos a las familias, el atraso en los pagos asciende significativamente al <b>6,6%<\/b>.<\/p>\n<h5>El salto alarmante en tarjetas de cr\u00e9dito<\/h5>\n<p>Dentro del rubro familiar, el foco de mayor preocupaci\u00f3n recae en las <b>tarjetas de cr\u00e9dito<\/b>. La irregularidad en sus pagos se ubic\u00f3 en <b>6,7%<\/b>, lo que representa un avance de <b>1,4 puntos porcentuales<\/b> respecto al mes anterior. Sin embargo, lo que realmente dimensiona la gravedad del escenario es el salto interanual: la mora en tarjetas pas\u00f3 de <b>1,9% en agosto de 2024 a 6,7%<\/b> en el mismo mes de este a\u00f1o, un alarmante incremento del <b>252% interanual<\/b>.<\/p>\n<p>Estos datos sugieren que las familias est\u00e1n utilizando el endeudamiento, especialmente a trav\u00e9s de las tarjetas, como un salvavidas para llegar a fin de mes, una estrategia que se vuelve insostenible r\u00e1pidamente a medida que la inflaci\u00f3n y la quietud salarial carcomen el poder adquisitivo.<\/p>\n<h4>Las pymes atrapadas entre la deuda y la extensi\u00f3n de plazos<\/h4>\n<p>El impacto del programa econ\u00f3mico actual tambi\u00e9n se siente con fuerza en el sector productivo. Un informe del <b>Radar Pyme del Tercer Trimestre 2025<\/b> de la Asociaci\u00f3n de Empresarios y Empresarias Nacionales para el Desarrollo Argentino (<b>ENAC<\/b>) revela el agobio financiero de las Peque\u00f1as y Medianas Empresas (Pymes):<\/p>\n<ul>\n<li>El <b>21,3%<\/b> de las Pymes se endeud\u00f3 para poder pagar impuestos.<\/li>\n<li>Otro <b>20,5%<\/b> tuvo que recurrir al endeudamiento para afrontar el pago de salarios o aguinaldos.<\/li>\n<\/ul>\n<h5>La presi\u00f3n en los tiempos de cobro y pago<\/h5>\n<p>Adem\u00e1s del endeudamiento directo, las Pymes enfrentan un escenario de tensi\u00f3n en la gesti\u00f3n de su capital de trabajo debido a la extensi\u00f3n unilateral de los plazos de pago por parte de sus clientes. El <b>59%<\/b> de las empresas encuestadas por ENAC indic\u00f3 que sus clientes extendieron los plazos de cobro, y un <b>47%<\/b> se\u00f1al\u00f3 un aumento del incumplimiento. Esto crea un desequilibrio financiero grave: mientras las Pymes financian a sus clientes durante <b>37 d\u00edas<\/b> en promedio, deben pagar a sus propios proveedores en solo <b>30 d\u00edas<\/b>, forzando una cadena de pagos cada vez m\u00e1s ajustada y dependiente del cr\u00e9dito.<\/p>\n<h4>Endeudarse para consumir y la lentitud salarial<\/h4>\n<p>El fen\u00f3meno del endeudamiento para cubrir necesidades b\u00e1sicas se agrava con el cr\u00e9dito no bancario. La consultora EcoGo estima que el endeudamiento de las familias con entidades no financieras ya llega al <b>31% de la masa salarial mensual<\/b>, superando el pico de septiembre de 2022. La morosidad en estas carteras de pr\u00e9stamos no bancarios es notablemente alta, alcanzando el <b>16,5%<\/b> de la cartera en agosto. Este incremento continuo en la morosidad no solo refleja los problemas econ\u00f3micos del sector, sino que podr\u00eda traducirse en una futura restricci\u00f3n en la oferta de cr\u00e9dito.<\/p>\n<p>Esta delicada situaci\u00f3n financiera se vincula directamente con la lentitud en la recuperaci\u00f3n salarial. Seg\u00fan Vectorial, en agosto los ingresos de los trabajadores subieron apenas un <b>0,5%<\/b>, una \u00abvelocidad de recomposici\u00f3n excesivamente lenta\u00bb que responde a la estrategia gubernamental de usar el salario como un <b>ancla antiinflacionaria<\/b>. Esta quietud en los ingresos termina siendo un freno tanto para los precios como para la actividad econ\u00f3mica, ya que la <b>demanda interna insuficiente<\/b> es se\u00f1alada como el principal obst\u00e1culo por los propios empresarios, seg\u00fan encuestas de tendencia de negocios del INDEC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La morosidad como term\u00f3metro de la crisis econ\u00f3mica \u00bfQu\u00e9 est\u00e1 pasando en la cadena de pagos argentina? El r\u00e9cord de<\/p>\n","protected":false},"author":1,"featured_media":121353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El volumen de cheques rechazados por falta de fondos super\u00f3 las 92.000 unidades en septiembre, marcando un m\u00e1ximo desde 2020, un reflejo directo del creciente endeudamiento y la morosidad que ahogan a las familias y pymes argentinas.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3,41],"tags":[],"class_list":["post-121352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/11\/20261109-Cheques.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=121352"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121352\/revisions"}],"predecessor-version":[{"id":121355,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/121352\/revisions\/121355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/121353"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=121352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=121352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=121352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}