{"id":120422,"date":"2025-10-08T13:52:22","date_gmt":"2025-10-08T16:52:22","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=120422"},"modified":"2025-10-08T13:52:22","modified_gmt":"2025-10-08T16:52:22","slug":"cascallares-acompano-la-jura-de-nuevos-jueces-y-fiscales-del-departamento-judicial-de-lomas-de-zamora","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/10\/08\/cascallares-acompano-la-jura-de-nuevos-jueces-y-fiscales-del-departamento-judicial-de-lomas-de-zamora\/","title":{"rendered":"Cascallares acompa\u00f1\u00f3 la jura de nuevos jueces y fiscales del Departamento Judicial de Lomas De Zamora"},"content":{"rendered":"<p>El acto se desarroll\u00f3 a lo largo de tres jornadas y cont\u00f3 con la presencia del miembro de la Suprema Corte de Justicia bonaerense, Sergio Torres; del ministro de Justicia de la Provincia, Mart\u00edn Mena; y de autoridades del Poder Judicial del Departamento Judicial de Lomas de Zamora.<\/p>\n<h5><strong><em>\u201cEste es el resultado del procedimiento de selecci\u00f3n de los postulantes a jueces e integrantes del Ministerio P\u00fablico que llevamos adelante desde el Consejo de la Magistratura bonaerense\u201d, destac\u00f3 Mariano Cascallares, quien subray\u00f3 que estas designaciones \u201cpermiten acelerar y dar mayor eficiencia al funcionamiento del sistema judicial de la regi\u00f3n\u201d.<\/em><\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-120424\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251008-Brown-fiscales.jpg\" alt=\"\" width=\"768\" height=\"428\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251008-Brown-fiscales.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251008-Brown-fiscales-300x167.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Durante las jornadas prestaron juramento las juezas de Familia Patricia Barrientos y Fernanda Arrinda; el juez de Garant\u00edas Mat\u00edas Ocampo; y el juez en lo Civil y Comercial Javier Vignolo.<\/p>\n<p>Tambi\u00e9n asumieron los jueces del Tribunal Oral en lo Criminal Sebasti\u00e1n De Cesare, Georgina Retamales, Luc\u00eda Copertino, Jonathan Barraud, Fernando Carrillo y Mar\u00eda Fernanda Anaya.<\/p>\n<div>Adem\u00e1s, juraron los agentes fiscales Romina Pellegrino, Sabrina Marotta, Miguel Reynoso, Sebasti\u00e1n Grys, Leandro Patteta, Roberto Daniel Pucci, Gustavo Fernando Fern\u00e1ndez y Sergio Z\u00e1rate; junto a los defensores penales Eduardo Magoja, Leonardo Schumman y Natalia Pazzano.<\/div>\n<div><\/div>\n<div>Estas asunciones son muy importantes dado que permitir\u00e1n agilizar y eficientizar la administraci\u00f3n de Justicia en beneficio de las vecinos y los vecinos de Almirante Brown.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El acto se desarroll\u00f3 a lo largo de tres jornadas y cont\u00f3 con la presencia del miembro de la Suprema<\/p>\n","protected":false},"author":1,"featured_media":120423,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El intendente de Almirante Brown e integrante del Consejo de la Magistratura bonaerense, Mariano Cascallares, particip\u00f3 de la ceremonia de jura de decenas de nuevos jueces y fiscales que desempe\u00f1ar\u00e1n funciones en el Departamento Judicial de Lomas de Zamora.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,33],"tags":[],"class_list":["post-120422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown","category-alte-brown-alte-brown"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251008-Brown-Cascallares.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=120422"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120422\/revisions"}],"predecessor-version":[{"id":120425,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120422\/revisions\/120425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/120423"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=120422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=120422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=120422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}