{"id":120353,"date":"2025-10-06T16:55:15","date_gmt":"2025-10-06T19:55:15","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=120353"},"modified":"2025-10-06T16:56:20","modified_gmt":"2025-10-06T19:56:20","slug":"cascallares-y-marinucci-entregaron-pases-multimodales-de-transporte-a-vecinos-brownianos","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/10\/06\/cascallares-y-marinucci-entregaron-pases-multimodales-de-transporte-a-vecinos-brownianos\/","title":{"rendered":"Cascallares y Marinucci entregaron pases multimodales de transporte a vecinos brownianos"},"content":{"rendered":"<div dir=\"ltr\">\n<div>\n<p>Estos Pases Multimodales tienen como principal objetivo que personas con discapacidad, trasplantadas o en lista de espera puedan viajar en el transporte p\u00fablico de forma gratuita. En este sentido, el beneficio permite el acceso gratuito del transporte p\u00fablico en la Provincia de Buenos Aires tanto terrestre como fluvial.<\/p>\n<h5><strong><em>Durante la jornada, Mariano Cascallares le agradeci\u00f3 a Marinucci el trabajo articulado y remarc\u00f3 que \u201ces un avance muy importante porque este pase multimodal permitir\u00e1 brindar m\u00e1s y mejores servicios y atender las necesidades de toda nuestra gente\u201d.<\/em><\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-120355 size-full\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251006-Brown-pases-1.jpg\" alt=\"pases multimodales de transporte \" width=\"768\" height=\"510\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251006-Brown-pases-1.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251006-Brown-pases-1-300x199.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<h5><strong><em>Mientras que Marinucci, en tanto, remarc\u00f3 que \u201cseguimos construyendo una Provincia con m\u00e1s inclusi\u00f3n, m\u00e1s derechos y m\u00e1s acceso al transporte p\u00fablico\u201d.<\/em><\/strong><\/h5>\n<p>De la jornada participaron tambi\u00e9n el secretario de Gobierno, Juan Jos\u00e9 Fabiani; el secretario de Educaci\u00f3n, Ciencia y Tecnolog\u00eda, Sergio Pianciola; la secretar\u00eda de Desarrollo, Seguridad Social y Derechos Humanos, B\u00e1rbara Mi\u00f1\u00e1n, y la directora de General de Tr\u00e1nsito y Trasporte, Paola Fracas.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estos Pases Multimodales tienen como principal objetivo que personas con discapacidad, trasplantadas o en lista de espera puedan viajar en<\/p>\n","protected":false},"author":1,"featured_media":120354,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El intendente de Almirante Brown, Mariano Cascallares, entreg\u00f3 junto al ministro de Transporte de la Provincia de Buenos Aires, Mart\u00edn Marinucci, Pases Multimodales de Transporte a vecinos de nuestro distrito para seguir ampliando derechos.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,2594],"tags":[],"class_list":["post-120353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-efemerides"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/10\/20251006-Brown-pases.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=120353"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120353\/revisions"}],"predecessor-version":[{"id":120357,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120353\/revisions\/120357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/120354"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=120353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=120353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=120353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}