{"id":120297,"date":"2025-10-04T04:50:15","date_gmt":"2025-10-04T07:50:15","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=120297"},"modified":"2025-10-04T04:50:15","modified_gmt":"2025-10-04T07:50:15","slug":"crisis-laboral-despidos-sin-causa-en-alza-y-el-pluriempleo-forzado-marcan-la-era-milei","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/10\/04\/crisis-laboral-despidos-sin-causa-en-alza-y-el-pluriempleo-forzado-marcan-la-era-milei\/","title":{"rendered":"Crisis laboral: despidos sin causa en alza y el pluriempleo forzado marcan la era Milei"},"content":{"rendered":"<p>La econom\u00eda argentina navega en un escenario de fragilidad marcado por la inflaci\u00f3n, la inestabilidad cambiaria y la amenaza de recesi\u00f3n, con el mercado laboral como uno de los principales damnificados. El impacto del <b>ajuste del gobierno libertario<\/b> se siente directamente en los bolsillos y la estabilidad de los trabajadores: un empleo ya no garantiza la cobertura de las necesidades b\u00e1sicas. La doble cara de esta crisis es el r\u00e9cord en los <b>despidos injustificados<\/b> y el <b>boom de la doble jornada forzada<\/b>.<\/p>\n<h4><strong>La urgencia del pluriempleo ante el salario pulverizado<\/strong><\/h4>\n<p>El deterioro sostenido del poder adquisitivo del salario, que en el sector registrado formal se mantiene por debajo de los niveles de noviembre de 2023, ha empujado a miles de personas a una b\u00fasqueda desesperada de <b>ingresos complementarios<\/b>.<\/p>\n<p>Seg\u00fan datos del Instituto Argentina Grande (IAG), la tasa de <b>\u00abocupados demandantes\u00bb<\/b> \u2014personas que tienen trabajo, pero buscan activamente un segundo ingreso\u2014 creci\u00f3 2,3 puntos en el segundo trimestre de 2025 respecto al mismo periodo del a\u00f1o anterior. Esto significa que <b>m\u00e1s de 204.000 personas<\/b> se encuentran en la necesidad de aceptar dobles jornadas para intentar cubrir, al menos, la <b>Canasta B\u00e1sica<\/b>.<\/p>\n<p>Este fen\u00f3meno es la expresi\u00f3n m\u00e1s clara de la <b>precarizaci\u00f3n laboral<\/b>. Ante la falta de poder de compra del salario, el trabajador se ve obligado a aumentar su carga horaria, pero no por crecimiento de la econom\u00eda, sino por mera subsistencia. Otros indicadores que reflejan esta p\u00e9rdida de calidad en el empleo son:<\/p>\n<ul>\n<li><b>Aumento de cuentapropistas:<\/b> La cantidad de trabajadores por cuenta propia creci\u00f3 1,4 puntos interanuales.<\/li>\n<li><b>Ca\u00edda del empleo formal:<\/b> El peso de los asalariados formales sobre el total del mercado laboral cay\u00f3 0,9 puntos.<\/li>\n<li><b>Incorporaci\u00f3n forzada:<\/b> Cada vez m\u00e1s personas que estaban fuera del mercado de trabajo se ven obligadas a incorporarse a la b\u00fasqueda de empleo para complementar los ingresos del hogar, aunque los nuevos puestos generados son mayormente precarios.<\/li>\n<\/ul>\n<h4><strong>Despidos sin causa y crisis en la Industria<\/strong><\/h4>\n<p>En simult\u00e1neo con la necesidad creciente de m\u00e1s trabajo, el mercado laboral sufre el golpe de las desvinculaciones. El porcentaje de <b>despidos sin causa<\/b> lleg\u00f3 a representar el <b>16%<\/b> del total de las separaciones en julio de 2025, el nivel m\u00e1s alto del \u00faltimo a\u00f1o y superior al 13% registrado un a\u00f1o antes, seg\u00fan el Instituto Interdisciplinario de Econom\u00eda Pol\u00edtica (IIEP-UBA CONICET).<\/p>\n<p>Este aumento en la terminaci\u00f3n de la relaci\u00f3n laboral se complementa con otro dato preocupante: el porcentaje de empresas que registraron <b>solo bajas en su personal<\/b> ascendi\u00f3 al 15%. La destrucci\u00f3n de puestos de trabajo se concentra en sectores clave, siendo la <b>Industria<\/b> la m\u00e1s golpeada. Desde septiembre de 2023, el sector industrial perdi\u00f3 cerca de <b>40.400 puestos<\/b>, con 8.100 de esas bajas registradas solo en lo que va de 2025. Este declive muestra que el empleo en la industria ha registrado variaciones negativas en casi todos los meses del \u00faltimo a\u00f1o.<\/p>\n<p>Mientras la evidencia muestra una contracci\u00f3n del empleo formal y una agudizaci\u00f3n de la precarizaci\u00f3n, el Gobierno insiste en impulsar una <b>reforma laboral<\/b> que, seg\u00fan los cr\u00edticos, lejos de garantizar la creaci\u00f3n de fuentes de trabajo, podr\u00eda terminar por \u00ablegalizar\u00bb las condiciones precarias de contrataci\u00f3n ya existentes.<\/p>\n<h4><strong>Deterioro del tejido social y crisis alimentaria<\/strong><\/h4>\n<p>El impacto del ajuste trasciende la esfera laboral y se traduce en una grave crisis social, particularmente en los hogares. Se observa una <b>fuerte ca\u00edda en la tasa de empleo de jefes y jefas de hogar<\/b>, los principales proveedores de ingresos familiares, que se contrajo 1,1 puntos al comparar el segundo trimestre de 2025 con 2023.<\/p>\n<p>Las consecuencias son alarmantes en t\u00e9rminos de seguridad alimentaria:<\/p>\n<ul>\n<li><b>El 58% de los hogares no logr\u00f3 cubrir satisfactoriamente la Canasta B\u00e1sica Alimentaria (CBA)<\/b>, implicando un consumo por debajo de los par\u00e1metros nutricionales recomendados, seg\u00fan el Instituto de Estad\u00edsticas y Tendencias Sociales y Econ\u00f3micas (IETSE).<\/li>\n<li>En el <b>19% de los hogares<\/b> fue necesario <b>pedir comida o dinero para alimentarse<\/b>.<\/li>\n<li>El <b>10,6%<\/b> de los hogares refiri\u00f3 que alg\u00fan integrante se aliment\u00f3 una sola vez al d\u00eda o debi\u00f3 <b>ayunar de manera forzada<\/b>.<\/li>\n<\/ul>\n<p>Estos datos no solo evidencian el deterioro de las condiciones de vida de los sectores medios y bajos, sino que tambi\u00e9n alertan sobre una <b>crisis alimentaria<\/b> que compromete directamente la salud de la poblaci\u00f3n y el tejido social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La econom\u00eda argentina navega en un escenario de fragilidad marcado por la inflaci\u00f3n, la inestabilidad cambiaria y la amenaza de<\/p>\n","protected":false},"author":1,"featured_media":118478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El ajuste macroecon\u00f3mico impulsado por el gobierno de Javier Milei ha generado un mapa laboral signado por la precarizaci\u00f3n: el porcentaje de despidos sin causa alcanza m\u00e1ximos hist\u00f3ricos, al tiempo que m\u00e1s de 200.000 trabajadores se ven forzados a buscar un segundo empleo para compensar la pulverizaci\u00f3n de sus salarios.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,41],"tags":[],"class_list":["post-120297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/08\/20260806-desempleo.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=120297"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120297\/revisions"}],"predecessor-version":[{"id":120298,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120297\/revisions\/120298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/118478"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=120297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=120297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=120297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}