{"id":120252,"date":"2025-10-02T17:32:23","date_gmt":"2025-10-02T20:32:23","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=120252"},"modified":"2025-10-02T17:32:23","modified_gmt":"2025-10-02T20:32:23","slug":"almirante-brown-se-suma-a-la-cuarta-jornada-latinoamericana-masiva-de-castracion","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/10\/02\/almirante-brown-se-suma-a-la-cuarta-jornada-latinoamericana-masiva-de-castracion\/","title":{"rendered":"Almirante Brown se suma a la Cuarta Jornada Latinoamericana Masiva de Castraci\u00f3n"},"content":{"rendered":"<p>En ese marco, el viernes 3 de octubre se llevar\u00e1 adelante una jornada especial de esterilizaci\u00f3n gratuita en el Centro Municipal de Sanidad Animal y Zoonosis, ubicado en la calle Mart\u00edn Fierro N\u00b0 33, esquina Avenida Monteverde de Burzaco.<\/p>\n<p>La actividad comenzar\u00e1 a las 7:30 horas, con el registro por orden de llegada, sin necesidad de turno previo.<\/p>\n<p>Desde Zoonosis Brown recordaron que los animales deben presentarse con un ayuno de 12 horas de s\u00f3lidos y l\u00edquidos, y es obligatorio llevar una manta por cada animal.<\/p>\n<p>En el caso de los gatos, deber\u00e1n ser trasladados en bolsas de red (tipo cebolla). Asimismo, se inform\u00f3 que las hembras pre\u00f1adas o en celo tambi\u00e9n pueden ser castradas.<\/p>\n<h5><strong><em>Al respecto, el intendente Mariano Cascallares subray\u00f3 que \u201cAlmirante Brown es el primer municipio no eutan\u00e1sico de la provincia de Buenos Aires y uno de los pioneros a nivel nacional. Nuestro programa de castraciones gratuitas, masivas, sistem\u00e1ticas, tempranas y abarcativas es un modelo para otros distritos. Paralelamente realizamos durante todo el a\u00f1o operativos itinerantes y descentralizados en cada una de nuestras localidades\u201d.<\/em><\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-111554\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2024\/12\/20241209-Brown-Zoonosis-castraciones-1.jpg\" alt=\"\" width=\"768\" height=\"428\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2024\/12\/20241209-Brown-Zoonosis-castraciones-1.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2024\/12\/20241209-Brown-Zoonosis-castraciones-1-300x167.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>Cabe destacar que el\u00a0Centro Municipal de Sanidad Animal y Zoonosis de Almirante Brown\u00a0es reconocido como un\u00a0modelo sanitario a nivel regional, nacional e internacional.<\/p>\n<p>Semana a semana recibe la visita de funcionarios, profesionales y equipos veterinarios de distintos puntos del pa\u00eds y de Am\u00e9rica Latina, interesados en conocer de primera mano su funcionamiento t\u00e9cnico y la metodolog\u00eda de trabajo, con el objetivo de replicarla en sus respectivos territorios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ese marco, el viernes 3 de octubre se llevar\u00e1 adelante una jornada especial de esterilizaci\u00f3n gratuita en el Centro<\/p>\n","protected":false},"author":1,"featured_media":116792,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El Municipio de Almirante Brown inform\u00f3 que se sumar\u00e1 a la Cuarta Jornada Latinoamericana de Castraci\u00f3n Masiva, una iniciativa impulsada por la red Castralat, que convoca a pa\u00edses de toda Am\u00e9rica Latina con el objetivo de promover el bienestar animal y el control \u00e9tico de la poblaci\u00f3n de perros y gatos.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,33],"tags":[],"class_list":["post-120252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown","category-alte-brown-alte-brown"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/06\/20250611-BROWN-ZOONOSIS.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=120252"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120252\/revisions"}],"predecessor-version":[{"id":120253,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/120252\/revisions\/120253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/116792"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=120252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=120252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=120252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}