{"id":117639,"date":"2025-07-11T04:30:18","date_gmt":"2025-07-11T07:30:18","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=117639"},"modified":"2025-07-11T04:30:18","modified_gmt":"2025-07-11T07:30:18","slug":"senado-aprueba-aumento-a-jubilados-y-la-extension-de-la-moratoria","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/07\/11\/senado-aprueba-aumento-a-jubilados-y-la-extension-de-la-moratoria\/","title":{"rendered":"Senado aprueba aumento a jubilados y la extensi\u00f3n de la moratoria"},"content":{"rendered":"<div class=\"source-inline-chip-container ng-star-inserted\"><\/div>\n<p><span class=\"citation-11 citation-end-11\">En una sesi\u00f3n marcada por la tensi\u00f3n pol\u00edtica y las ausencias estrat\u00e9gicas, el Senado de la Naci\u00f3n aprob\u00f3 este jueves el proyecto de ley que establece un nuevo esquema para los haberes jubilatorios y prorroga la moratoria previsional.<\/span> <span class=\"citation-10 citation-end-10\">La medida, que representa un duro golpe para la administraci\u00f3n de Javier Milei, fue sancionada con un contundente apoyo de la oposici\u00f3n, que logr\u00f3 reunir los votos necesarios para avanzar con ambas iniciativas, desafiando la postura del Poder Ejecutivo sobre la sostenibilidad fiscal.<\/span><\/p>\n<p><span class=\"citation-9\">El proyecto que contempla el <\/span><b><span class=\"citation-9\">aumento a jubilados<\/span><\/b><span class=\"citation-9 citation-end-9\">, que incluye una recomposici\u00f3n del 7,2 por ciento y la elevaci\u00f3n del bono complementario de 70.000 a 110.000 pesos, fue aprobado por 52 votos afirmativos y 4 abstenciones.<\/span> Esta amplia mayor\u00eda fue posible gracias a la convergencia de legisladores peronistas, radicales y representantes de partidos provinciales, superando as\u00ed el umbral de los dos tercios de los sufragios. De manera similar, la extensi\u00f3n de la <b>moratoria previsional<\/b> obtuvo 39 votos a favor, 14 en contra y una abstenci\u00f3n, consolidando el avance de una agenda legislativa que colisiona directamente con los postulados econ\u00f3micos del gobierno.<\/p>\n<h3>La sesi\u00f3n: Un qu\u00f3rum disputado y la ca\u00edda del sistema<\/h3>\n<p>La jornada legislativa comenz\u00f3 pasadas las 14:15, luego de que la oposici\u00f3n lograra conformar el qu\u00f3rum necesario para iniciar el debate. Un total de 34 senadores del interbloque peronista fueron clave para este objetivo, a quienes se sumaron figuras destacadas de la Uni\u00f3n C\u00edvica Radical (UCR) como Eduardo Vischi, Mart\u00edn Lousteau, Favio Fama, Pablo Blanco y Maximiliano Abad. Tambi\u00e9n se hicieron presentes el jefe de la bancada Las Provincias Unidas, Carlos \u201cCamau\u201d Esp\u00ednola; la senadora cordobesa Alejandra Vigo y la rionegrina M\u00f3nica Silva. A ellos se unieron los senadores santacruce\u00f1os Natalia Gadano y Jos\u00e9 Carambia, cercanos al gobernador Claudio Vidal, y la senadora del PRO Guadalupe Tagliaferri, vinculada a Horacio Rodr\u00edguez Larreta, quien marc\u00f3 una disidencia dentro de su propio bloque.<\/p>\n<p>Una de las particularidades de la sesi\u00f3n fue la intermitente ca\u00edda del sistema de votaci\u00f3n, un incidente que podr\u00eda abrir nuevas v\u00edas de discusi\u00f3n y cuestionamientos sobre la validez del procedimiento. Antes de la votaci\u00f3n final, los bloques de La Libertad Avanza (LLA), la mayor parte del PRO y otros representantes provinciales optaron por ausentarse del recinto. <span class=\"citation-8 citation-end-8\">Los legisladores libertarios, en l\u00ednea con la postura presidencial, no reconocen la validez de la sesi\u00f3n y han adelantado que buscar\u00e1n judicializar las iniciativas aprobadas, argumentando que atentan contra el equilibrio fiscal que el gobierno busca preservar.<\/span><\/p>\n<p>Tras una hora y media de intensos debates sobre la imposici\u00f3n del temario, prim\u00f3 la iniciativa del senador peronista Jos\u00e9 Mayans, quien logr\u00f3 imponer su criterio para considerar v\u00e1lidos los despachos, a pesar de las objeciones presentadas por los legisladores libertarios. De esta manera, se dio inicio formal al debate sobre los proyectos que finalmente ser\u00edan convertidos en ley.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-117636\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/20260711-senado1.jpg\" alt=\"\" width=\"768\" height=\"428\" title=\"\"><\/p>\n<h3>Argumentos a favor y en contra: El costo fiscal en el centro del debate<\/h3>\n<p>El primer orador en defender el proyecto aprobado en la C\u00e1mara de Diputados fue el senador peronista Mariano Recalde. Si bien reconoci\u00f3 que la mejora propuesta para los jubilados \u00abes m\u00ednima\u00bb y apenas alcanza para \u00abcubrir peque\u00f1os gastos\u00bb, Recalde enfatiz\u00f3 que el incremento cuenta con fuentes de financiamiento propias. En este sentido, destac\u00f3 que la iniciativa propone el redireccionamiento de partidas que el Poder Ejecutivo hab\u00eda asignado a la Agencia Federal de Inteligencia (AFI), anteriormente conocida como SIDE. \u00abEl proyecto cuenta con fuente de financiamiento propia que permitir\u00eda llevar un peque\u00f1o alivio a los jubilados y responder fiscalmente a esta necesidad\u00bb, afirm\u00f3 el senador, buscando desestimar las preocupaciones sobre el impacto en el <b>equilibrio fiscal<\/b>.<\/p>\n<p>A su turno, la senadora del PRO Carmen \u00c1lvarez Rivero expres\u00f3 su rotundo rechazo al proyecto, argumentando que, si bien la preocupaci\u00f3n por los jubilados es leg\u00edtima, la soluci\u00f3n debe abordarse desde una perspectiva m\u00e1s integral. La legisladora se\u00f1al\u00f3 la necesidad de estudiar otras propuestas, como la situaci\u00f3n del empleo informal, para abordar el problema de los diez millones de trabajadores argentinos que se encuentran en la informalidad y no realizan aportes previsionales. \u00abMe preocupan los jubilados y si de verdad queremos ayudarlos debemos tomar el toro por las astas y resolver entonces el problema de diez millones de trabajadores argentinos que est\u00e1n en la informalidad y no aportan\u00bb, sostuvo \u00c1lvarez Rivero, poniendo el foco en la sustentabilidad a largo plazo del sistema.<\/p>\n<p>Por su parte, la senadora Guadalupe Tagliaferri, tambi\u00e9n del PRO, lament\u00f3 que el a\u00f1o pasado un grupo de diputados haya avalado el <b>veto de Milei<\/b> a una iniciativa similar. Con una cr\u00edtica velada a la ret\u00f3rica oficial, Tagliaferri sentenci\u00f3: \u00abLa casta para el Gobierno son los jubilados. Por m\u00e1s que digan desde el relato cosas distintas\u00bb. Sin embargo, a pesar de su cr\u00edtica, la senadora vot\u00f3 en contra de la moratoria previsional, marcando una posici\u00f3n matizada dentro del bloque opositor. Finalmente, la senadora M\u00f3nica Silva, en un llamado a la conciliaci\u00f3n, indic\u00f3 que \u00abes muy importante que hoy logremos la aprobaci\u00f3n de esta ley y apelemos a la sensibilidad del Gobierno para que sea aplicable\u00bb, dejando entrever la incertidumbre sobre la implementaci\u00f3n de la medida ante la postura presidencial.<\/p>\n<h3>El futuro de la ley: \u00bfVeto presidencial a la vista?<\/h3>\n<p>La aprobaci\u00f3n de esta <b>ley jubilatoria<\/b> en el Senado representa un claro desaf\u00edo a la pol\u00edtica de ajuste fiscal impulsada por el gobierno de Javier Milei. El presidente ya hab\u00eda advertido p\u00fablicamente sobre su intenci\u00f3n de vetar cualquier iniciativa que, a su juicio, comprometa el equilibrio de las cuentas p\u00fablicas. La confrontaci\u00f3n entre el Poder Ejecutivo y el Poder Legislativo se intensifica, y la expectativa ahora se centra en la decisi\u00f3n final del mandatario.<\/p>\n<p>La judicializaci\u00f3n anunciada por La Libertad Avanza y la posibilidad de un veto presidencial abren un nuevo cap\u00edtulo en la relaci\u00f3n entre los poderes del Estado, con los jubilados en el centro de una disputa que va m\u00e1s all\u00e1 de los n\u00fameros y se adentra en la concepci\u00f3n misma del rol del Estado y la pol\u00edtica social en Argentina. La ley, si bien aprobada, enfrenta ahora la barrera de la Casa Rosada, y su destino final definir\u00e1 no solo el futuro de millones de jubilados, sino tambi\u00e9n la din\u00e1mica pol\u00edtica de los pr\u00f3ximos meses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una sesi\u00f3n marcada por la tensi\u00f3n pol\u00edtica y las ausencias estrat\u00e9gicas, el Senado de la Naci\u00f3n aprob\u00f3 este jueves<\/p>\n","protected":false},"author":1,"featured_media":117635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El Senado de la Naci\u00f3n ha asestado un significativo rev\u00e9s al gobierno de Javier Milei al convertir en ley el proyecto que incrementa los haberes jubilatorios y extiende la moratoria previsional. La iniciativa, que eleva el bono a $110.000 y recompone un 7,2% adicional, fue aprobada con amplio respaldo opositor, a pesar de las advertencias presidenciales sobre un posible veto por razones de equilibrio fiscal.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,41],"tags":[],"class_list":["post-117639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/20260711-senado.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/117639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=117639"}],"version-history":[{"count":1,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/117639\/revisions"}],"predecessor-version":[{"id":117640,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/117639\/revisions\/117640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/117635"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=117639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=117639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=117639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}