{"id":117526,"date":"2025-07-08T02:40:04","date_gmt":"2025-07-08T05:40:04","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=117526"},"modified":"2025-07-08T02:40:04","modified_gmt":"2025-07-08T05:40:04","slug":"cascallares-visito-el-centro-cultural-el-gaucho-y-le-entrego-su-personeria-juridica","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/07\/08\/cascallares-visito-el-centro-cultural-el-gaucho-y-le-entrego-su-personeria-juridica\/","title":{"rendered":"Cascallares visit\u00f3 el centro cultural \u201cEl Gaucho\u201d y le entreg\u00f3 su personer\u00eda jur\u00eddica"},"content":{"rendered":"<p>El encuentro se llev\u00f3 a cabo en la sede de la instituci\u00f3n, ubicada en la calle Alsina N\u00b0 1236, donde el jefe comunal fue recibido por integrantes de la comisi\u00f3n directiva, entre ellos el presidente Justin Leonel Barbieri y la vicepresidenta Andrea Alejandra Villalba.<\/p>\n<h5><strong><em>\u201cEl Centro Cultural El Gaucho es un verdadero ejemplo del trabajo comunitario que fortalece los lazos barriales, la identidad local y la cultura nacional, desde nuestro querido distrito. Desde el Estado municipal acompa\u00f1amos y reconocemos ese esfuerzo que se sostiene desde hace 15 a\u00f1os\u201d, expres\u00f3 el intendente.<\/em><\/strong><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-117528 size-full\" src=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/20260708-Centro-Cultural-El-Gaucho-1.jpg\" alt=\"centro cultural \u201cEl Gaucho\u201d \" width=\"768\" height=\"428\" title=\"\" srcset=\"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/20260708-Centro-Cultural-El-Gaucho-1.jpg 768w, https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/20260708-Centro-Cultural-El-Gaucho-1-300x167.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>El Centro naci\u00f3 a partir de la tradici\u00f3n gauchesca del barrio que le da nombre, y con el tiempo se consolid\u00f3 como un espacio cultural clave para la comunidad. Organiza pe\u00f1as, talleres y actividades que promueven el encuentro social y articulan con el CIC de Burzaco.<\/p>\n<p>Participaron tambi\u00e9n del acto el secretario de Relaciones con la Comunidad, Federico Sassone; el presidente del Instituto Municipal de las Culturas, Juan Manuel Pereira Ben\u00edtez, y la delegada municipal de Burzaco, Andrea Capasso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El encuentro se llev\u00f3 a cabo en la sede de la instituci\u00f3n, ubicada en la calle Alsina N\u00b0 1236, donde<\/p>\n","protected":false},"author":1,"featured_media":117527,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"El intendente de Almirante Brown, Mariano Cascallares, visit\u00f3 el Centro Cultural \u201cEl Gaucho\u201d en la localidad de Burzaco, donde hizo entrega del certificado de reconocimiento municipal y del folio de inscripci\u00f3n otorgado por la Direcci\u00f3n Provincial de Personas Jur\u00eddicas.El intendente de Almirante Brown, Mariano Cascallares, visit\u00f3 el Centro Cultural \u201cEl Gaucho\u201d en la localidad de Burzaco, donde hizo entrega del certificado de reconocimiento municipal y del folio de inscripci\u00f3n otorgado por la Direcci\u00f3n Provincial de Personas Jur\u00eddicas.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2,33,43],"tags":[],"class_list":["post-117526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alte-brown","category-alte-brown-alte-brown","category-burzaco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2025\/07\/20260708-Centro-Cultural-El-Gaucho.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/117526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=117526"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/117526\/revisions"}],"predecessor-version":[{"id":117530,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/117526\/revisions\/117530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/117527"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=117526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=117526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=117526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}