{"id":112685,"date":"2025-01-20T13:39:05","date_gmt":"2025-01-20T16:39:05","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=112685"},"modified":"2025-01-20T13:39:05","modified_gmt":"2025-01-20T16:39:05","slug":"whatsapp-prueba-una-nueva-funcion-con-tres-tildes-azules","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2025\/01\/20\/whatsapp-prueba-una-nueva-funcion-con-tres-tildes-azules\/","title":{"rendered":"WhatsApp prueba una nueva funci\u00f3n con tres tildes azules"},"content":{"rendered":"<p>WhatsApp, la plataforma de mensajer\u00eda l\u00edder con m\u00e1s de dos mil millones de usuarios en todo el mundo, sigue innovando para mantenerse en la cima. En su b\u00fasqueda por mejorar la privacidad, est\u00e1 probando una funci\u00f3n que podr\u00eda marcar un antes y un despu\u00e9s en la experiencia de uso: la incorporaci\u00f3n de una tercera tilde azul que alertar\u00e1 cuando se realice una captura de pantalla de una conversaci\u00f3n.<\/p>\n<p>Actualmente, la aplicaci\u00f3n utiliza dos tildes azules para indicar que un mensaje ha sido le\u00eddo. Sin embargo, esta nueva herramienta busca ampliar la transparencia, permitiendo a los usuarios saber si el receptor ha capturado im\u00e1genes del contenido compartido, ya sea un mensaje, una foto o un video. Este cambio forma parte de los esfuerzos de WhatsApp por ofrecer mayor control y seguridad a sus usuarios, una de las demandas m\u00e1s frecuentes en el \u00e1mbito digital.<\/p>\n<p>De acuerdo con fuentes cercanas al desarrollo, esta caracter\u00edstica ya est\u00e1 disponible en versiones beta, accesibles \u00fanicamente para un grupo reducido de personas. Aunque la empresa no ha confirmado oficialmente su lanzamiento, la posibilidad de que se integre en futuras actualizaciones genera expectativa. Como ocurre con otras funciones en prueba, la implementaci\u00f3n generalizada podr\u00eda tardar varios meses, dependiendo de los resultados obtenidos en la etapa beta.<\/p>\n<p>La medida ha sido recibida con opiniones divididas. Por un lado, muchos usuarios consideran que es un avance significativo en la protecci\u00f3n de la privacidad. Por otro, algunos expresan preocupaciones sobre posibles inconvenientes al compartir informaci\u00f3n leg\u00edtima, como en entornos educativos o laborales.<\/p>\n<p>Esta tercera tilde azul se sumar\u00eda a una serie de herramientas recientes de WhatsApp dise\u00f1adas para proteger la informaci\u00f3n personal, como los mensajes que desaparecen y el bloqueo de conversaciones con contrase\u00f1a. Estas iniciativas reflejan el compromiso de la plataforma por adaptarse a un entorno donde la privacidad es cada vez m\u00e1s valorada.<\/p>\n<p>En conclusi\u00f3n, la incorporaci\u00f3n de la tercera tilde azul refuerza la apuesta de WhatsApp por brindar mayor transparencia y seguridad en sus chats. Aunque a\u00fan se desconoce la fecha exacta de su lanzamiento, esta funci\u00f3n promete transformar la forma en que los usuarios interact\u00faan, marcando un nuevo est\u00e1ndar en la mensajer\u00eda digital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WhatsApp, la plataforma de mensajer\u00eda l\u00edder con m\u00e1s de dos mil millones de usuarios en todo el mundo, sigue innovando<\/p>\n","protected":false},"author":1,"featured_media":110775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"La popular aplicaci\u00f3n de mensajer\u00eda trabaja en una actualizaci\u00f3n que notificar\u00e1 a los usuarios si alguien realiza una captura de pantalla durante una conversaci\u00f3n, reforzando la privacidad en sus chats.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[],"class_list":["post-112685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2024\/11\/20241111-WhatsApp.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/112685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=112685"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/112685\/revisions"}],"predecessor-version":[{"id":112687,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/112685\/revisions\/112687"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/110775"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=112685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=112685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=112685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}