{"id":109641,"date":"2024-10-14T01:35:46","date_gmt":"2024-10-14T04:35:46","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=109641"},"modified":"2024-10-14T01:35:46","modified_gmt":"2024-10-14T04:35:46","slug":"la-genetica-pesa-mas-que-la-dieta-en-la-longevidad","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2024\/10\/14\/la-genetica-pesa-mas-que-la-dieta-en-la-longevidad\/","title":{"rendered":"La gen\u00e9tica pesa m\u00e1s que la dieta en la longevidad"},"content":{"rendered":"<p>Durante a\u00f1os, la ciencia ha debatido sobre el impacto de la alimentaci\u00f3n en la longevidad humana. Sin embargo, un reciente estudio realizado en ratones ha revelado que la gen\u00e9tica podr\u00eda ser un factor determinante en la esperanza de vida, superando la influencia de la dieta.<\/p>\n<p>El estudio, dirigido por un equipo de investigadores estadounidenses y publicado en la revista cient\u00edfica Nature, se centr\u00f3 en 960 ratones hembra de origen gen\u00e9ticamente diverso. A diferencia de estudios previos, que utilizaban cepas consangu\u00edneas limitadas, este dise\u00f1o garantiz\u00f3 que los resultados fuesen m\u00e1s representativos de la diversidad gen\u00e9tica humana. Los roedores fueron divididos en grupos que segu\u00edan cinco tipos de dietas: desde acceso ilimitado a alimentos hasta diversas formas de ayuno y restricci\u00f3n cal\u00f3rica.<\/p>\n<p>Los resultados fueron reveladores: todas las dietas redujeron la tasa de envejecimiento, pero las que implicaban una reducci\u00f3n cal\u00f3rica mostraron efectos m\u00e1s significativos en la prolongaci\u00f3n de la vida. Sin embargo, el estudio destac\u00f3 que la p\u00e9rdida de peso no era el factor determinante en la longevidad, lo que sugiere que otros mecanismos est\u00e1n en juego.<\/p>\n<h4><strong>Menos calor\u00edas, m\u00e1s vida, pero no necesariamente mejor salud<\/strong><\/h4>\n<p>Los ratones que consum\u00edan menos calor\u00edas vivieron m\u00e1s tiempo en promedio, alcanzando hasta 34 meses de vida en comparaci\u00f3n con los 25 meses de los que com\u00edan sin restricciones. No obstante, este aumento en la longevidad no siempre vino acompa\u00f1ado de mejor salud. Los ratones que perdieron m\u00e1s peso tendieron a tener sistemas inmunitarios m\u00e1s d\u00e9biles y menor energ\u00eda, lo que result\u00f3 en una vida m\u00e1s corta.<\/p>\n<p>Curiosamente, los ratones que mantuvieron su peso, a pesar de la restricci\u00f3n alimentaria, fueron los que m\u00e1s tiempo vivieron. Este hallazgo sugiere que un equilibrio moderado en la reducci\u00f3n de calor\u00edas podr\u00eda ser m\u00e1s efectivo para la longevidad sin comprometer la salud.<\/p>\n<h4><strong>La gen\u00e9tica, el factor clave<\/strong><\/h4>\n<p>El an\u00e1lisis gen\u00e9tico mostr\u00f3 que la longevidad estaba m\u00e1s influenciada por la gen\u00e9tica que por las dietas. Seg\u00fan el autor principal del estudio, Gary Churchill, los factores gen\u00e9ticos a\u00fan no identificados son los que en \u00faltima instancia determinan c\u00f3mo las dietas afectan la esperanza de vida.<\/p>\n<p>Este descubrimiento destaca la importancia de comprender c\u00f3mo los genes y la dieta interact\u00faan en la salud y longevidad humana, y sugiere que los cambios en la dieta podr\u00edan no ser la clave universal para una vida larga.<\/p>\n<p>En conclusi\u00f3n, si bien reducir calor\u00edas puede prolongar la vida, los factores gen\u00e9ticos subyacentes son esenciales para determinar cu\u00e1n efectivos son estos cambios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a\u00f1os, la ciencia ha debatido sobre el impacto de la alimentaci\u00f3n en la longevidad humana. Sin embargo, un reciente<\/p>\n","protected":false},"author":1,"featured_media":109635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"Un nuevo estudio sugiere que los genes pueden tener un papel m\u00e1s importante en la esperanza de vida que la alimentaci\u00f3n, seg\u00fan un experimento con ratones publicado en Nature.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[15],"tags":[],"class_list":["post-109641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2024\/10\/20241014-dieta-nutricion.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/109641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=109641"}],"version-history":[{"count":2,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/109641\/revisions"}],"predecessor-version":[{"id":109643,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/109641\/revisions\/109643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/109635"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=109641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=109641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=109641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}