{"id":106649,"date":"2024-07-04T21:45:18","date_gmt":"2024-07-05T00:45:18","guid":{"rendered":"https:\/\/laurbedigital.com.ar\/noticias\/?p=106649"},"modified":"2024-07-04T21:50:36","modified_gmt":"2024-07-05T00:50:36","slug":"efemerides-del-5-de-julio-que-se-conmemora-2","status":"publish","type":"post","link":"https:\/\/laurbedigital.com.ar\/noticias\/2024\/07\/04\/efemerides-del-5-de-julio-que-se-conmemora-2\/","title":{"rendered":"Efem\u00e9rides del 5 de julio: \u00bfqu\u00e9 se conmemora?"},"content":{"rendered":"<p><b>1946\u00a0&#8211; LOUIS REARD.<\/b>\u00a0El ingeniero franc\u00e9s Louis R\u00e9ard presenta la bikini en un evento de moda en la piscina p\u00fablica Piscine Molitor de Par\u00eds. La joven Micheline Bernardini, bailarina nudista del Casino de Par\u00eds, fue quien visti\u00f3 por primera vez la prenda de dos breves piezas de tela.<\/p>\n<p><b>1954\u00a0&#8211; ELVIS PRESLEY.<\/b>\u00a0El cantante estadounidense Elvis Presley graba en los estudios Sun Records la canci\u00f3n \u00abThat\u2019s all right\u00bb, su primer tema comercial. \u00abEl Rey del Rock and Roll\u00bb cambiar\u00eda la historia de la m\u00fasica para convertirse en \u00edcono cultural del siglo XX.<\/p>\n<p><b>1960\u00a0&#8211; TRILLIZAS DE ORO<\/b>. Nacen en el barrio porte\u00f1o de Floresta las hermanas Mar\u00eda Laura, Mar\u00eda Emilia y Mar\u00eda Eugenia Fern\u00e1ndez Rousse, actrices, cantantes y conductoras de televisi\u00f3n que ganaron fama con el nombre de \u201cLas trillizas de oro\u201d.<\/p>\n<p><b>1964\u00a0&#8211; PINK FLOYD.<\/b>\u00a0Se crea en Londres la banda de rock Pink Floyd, considerada una de las m\u00e1s influyentes en la historia de la m\u00fasica e inicialmente formada por el baterista Nick Mason, el tecladista Richard Wright, el bajista Roger Waters y el guitarrista Syd Barrett. Grab\u00f3 15 discos de los que se llevan vendidos m\u00e1s de 300 millones de copias. La banda gan\u00f3 popularidad por su m\u00fasica psicod\u00e9lica que evolucion\u00f3 hacia el rock progresivo y el sinf\u00f3nico.<\/p>\n<p><b>1969\u00a0<\/b><b>&#8211; ROLLING STONES<\/b>. La banda brit\u00e1nica de rock The Rolling Stones ofrece un concierto gratuito en el Hyde Park de Londres ante 250.000 espectadores como tributo al fallecido Brian Jones, uno de sus fundadores. Fue el debut de Mick Taylor,<\/p>\n<p><b>1980\u00a0&#8211; LUIS SANDRINI.<\/b>\u00a0Muere en Buenos Aires, a la edad de 75 a\u00f1os, el actor y humorista Luis Sandrini, ganador del Premio Konex p\u00f3stumo de 1981, quien film\u00f3 80 pel\u00edculas, entre ellas \u201cLos tres berretines\u201d, \u201cEl profesor tirabombas\u201d y \u201cLa fiesta de todos\u201d.<\/p>\n<p><b>1984\u00a0&#8211; DIEGO A. MARADONA<\/b>. Ante 80.000 hinchas en el estadio del N\u00e1poles, el astro del f\u00fatbol Diego Armando Maradona es presentado como nuevo jugador del club italiano, con el que gan\u00f3 cinco t\u00edtulos y el amor incondicional de los napolitanos.<\/p>\n<p><b>1996\u00a0&#8211; OVEJA DOLLY.<\/b>\u00a0En el Instituto Roslin, de la ciudad escocesa de Edimburgo, nace la oveja Dolly, primer mam\u00edfero surgido de la clonaci\u00f3n de una c\u00e9lula adulta de ovino. Su nacimiento no fue anunciado sino hasta siete meses despu\u00e9s, el 22 de febrero de 1997.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1946\u00a0&#8211; LOUIS REARD.\u00a0El ingeniero franc\u00e9s Louis R\u00e9ard presenta la bikini en un evento de moda en la piscina p\u00fablica Piscine<\/p>\n","protected":false},"author":1,"featured_media":106652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"Conoc\u00e9 cu\u00e1les son las efem\u00e9rides del 5 de julio, d\u00eda en el que se conmemoran diversas fechas importantes en la Argentina y el mundo.","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[5,2594],"tags":[],"class_list":["post-106649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-efemerides"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/laurbedigital.com.ar\/noticias\/wp-content\/uploads\/2024\/07\/20240705-Maradona-Napoles-1984.jpg","_links":{"self":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/106649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/comments?post=106649"}],"version-history":[{"count":4,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/106649\/revisions"}],"predecessor-version":[{"id":106654,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/posts\/106649\/revisions\/106654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media\/106652"}],"wp:attachment":[{"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/media?parent=106649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/categories?post=106649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laurbedigital.com.ar\/noticias\/wp-json\/wp\/v2\/tags?post=106649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}